{"id":3198,"date":"2026-02-11T22:42:06","date_gmt":"2026-02-11T22:42:06","guid":{"rendered":"https:\/\/www.europesays.com\/be-fr\/3198\/"},"modified":"2026-02-11T22:42:06","modified_gmt":"2026-02-11T22:42:06","slug":"lopposition-reclame-la-demission-de-la-ministre-jacqueline-galant-apres-ses-propos-sur-la-rtbf-et-depose-une-motion-de-mefiance","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/be-fr\/3198\/","title":{"rendered":"L&rsquo;opposition r\u00e9clame la d\u00e9mission de la ministre Jacqueline Galant apr\u00e8s ses propos sur la RTBF et d\u00e9pose une motion de m\u00e9fiance"},"content":{"rendered":"<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">La ministre s&rsquo;\u00e9tait content\u00e9e de lire devant les d\u00e9put\u00e9s un texte pr\u00e9par\u00e9 \u00e0 l&rsquo;avance, \u00e9ludant ainsi les nombreuses questions incisives de l&rsquo;opposition sur ses propos pol\u00e9miques et la proc\u00e9dure de d\u00e9signation du futur administrateur g\u00e9n\u00e9ral.<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Pour m\u00e9moire, le 13 janvier dernier, devant des militants MR r\u00e9unis \u00e0 Walhain (Brabant wallon), la ministre des M\u00e9dias avait dit esp\u00e9rer que le prochain remplacement de l&rsquo;administrateur g\u00e9n\u00e9ral de la RTBF et du directeur de l&rsquo;information puisse faire passer la ligne \u00e9ditoriale de la radio-t\u00e9l\u00e9vision publique \u00ab\u00a0de l&rsquo;autre c\u00f4t\u00e9 de l&rsquo;\u00e9chiquier politique\u00a0\u00bb.<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Elle avait aussi d\u00e9plor\u00e9 la pr\u00e9sence de nombreux \u00ab\u00a0gauchos\u00a0\u00bb parmi la jeune g\u00e9n\u00e9ration de journalistes. Ses propos avaient engendr\u00e9 une r\u00e9action ferme de la RTBF, de ses journalistes, ainsi que des associations professionnelles qui y ont vu une volont\u00e9 d&rsquo;ing\u00e9rence politique dans les m\u00e9dias.<\/p>\n<p><a href=\"https:\/\/www.dhnet.be\/actu\/belgique\/2026\/02\/10\/etrillee-par-lopposition-concernant-ses-propos-sur-la-rtbf-jacqueline-galant-se-defend-6QNWYMTQZ5FIBINPDB3JLZMNSQ\/\" target=\"_self\" class=\"ap-StoryInterstitialLink ap-StoryElement ap-StoryElement--mb\" rel=\"nofollow noopener\">\u00c9trill\u00e9e par l&rsquo;opposition concernant ses propos sur la RTBF, Jacqueline Galant se d\u00e9fend: \u00ab\u00a0Une d\u00e9mocratie a besoin d&rsquo;un m\u00e9dia public fort&#8230;\u00a0\u00bb<\/a><\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">La F\u00e9d\u00e9ration europ\u00e9enne des journalistes a d\u00e9pos\u00e9 de son c\u00f4t\u00e9 une alerte aupr\u00e8s du Conseil de l&rsquo;Europe, le gardien de la convention europ\u00e9enne des droits de l&rsquo;homme qui consacre notamment la libert\u00e9 de la presse.<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Conform\u00e9ment au r\u00e8glement du parlement de la FWB, la motion de m\u00e9fiance d\u00e9pos\u00e9e mercredi soir par l&rsquo;opposition sera examin\u00e9e par la conf\u00e9rence des pr\u00e9sidents. Le vote sur le texte devrait intervenir dans les prochains jours.<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Selon l&rsquo;opposition PS, c&rsquo;est la premi\u00e8re fois dans l&rsquo;histoire de la F\u00e9d\u00e9ration qu&rsquo;une motion de m\u00e9fiance est d\u00e9pos\u00e9e envers un ministre du gouvernement.<\/p>\n<p><a href=\"https:\/\/www.dhnet.be\/actu\/belgique\/2026\/02\/10\/lopposition-tacle-jacqueline-galant-apres-ses-propos-polemiques-sur-la-rtbf-elle-nest-plus-apte-a-etre-la-ministre-des-medias-6VB3H4IIP5HUDKFWRV4OYEG3KE\/\" target=\"_self\" class=\"ap-StoryInterstitialLink ap-StoryElement ap-StoryElement--mb\" rel=\"nofollow noopener\">L&rsquo;opposition tacle Jacqueline Galant apr\u00e8s ses propos pol\u00e9miques sur la RTBF : \u00ab\u00a0Elle n&rsquo;est plus apte \u00e0 \u00eatre la ministre des M\u00e9dias\u00a0\u00bb<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"La ministre s&rsquo;\u00e9tait content\u00e9e de lire devant les d\u00e9put\u00e9s un texte pr\u00e9par\u00e9 \u00e0 l&rsquo;avance, \u00e9ludant ainsi les nombreuses&hellip;\n","protected":false},"author":2,"featured_media":3199,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[12,13,18,17,2810,1404,2811],"class_list":{"0":"post-3198","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-belgique","8":"tag-be","9":"tag-be-fr","10":"tag-belgique","11":"tag-belgium","12":"tag-gvtfra","13":"tag-media","14":"tag-parlfra"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/3198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/comments?post=3198"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/3198\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media\/3199"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media?parent=3198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/categories?post=3198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/tags?post=3198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}