{"id":53151,"date":"2026-03-24T18:03:08","date_gmt":"2026-03-24T18:03:08","guid":{"rendered":"https:\/\/www.europesays.com\/be-fr\/53151\/"},"modified":"2026-03-24T18:03:08","modified_gmt":"2026-03-24T18:03:08","slug":"des-dizaines-et-des-dizaines-de-policiers-dans-les-rues-du-centre-ville-de-charleroi-voici-ce-quil-se-passe","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/be-fr\/53151\/","title":{"rendered":"Des dizaines et des dizaines de policiers dans les rues du centre-ville de Charleroi: voici ce qu&rsquo;il se passe"},"content":{"rendered":"<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">En fait, de nombreux policiers sont convi\u00e9s \u00e0 l&rsquo;H\u00f4tel de Ville de Charleroi pour \u00e9couter ce que le bourgmestre Thomas Dermine attend d&rsquo;eux. <a href=\"https:\/\/www.lavenir.net\/regions\/charleroi\/charleroi\/2026\/03\/24\/le-plan-disruption-30-presente-ce-mardi-comment-la-police-de-charleroi-compte-sattaquer-au-narcotrafic-et-a-ses-nuisances-en-centre-ville-DVAVAMLWRVFHXA6D7WJV5BS2RY\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Le plan Disruption 3.0<\/a> doit effectivement \u00eatre activ\u00e9 dans les jours \u00e0 venir : les policiers se d\u00e9placent donc du commissariat central, la \u00ab\u00a0Tour bleue\u00a0\u00bb, vers le Beffroi de l&rsquo;h\u00f4tel de ville, pour une rencontre officielle avec le bourgmestre, chef de la police.<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Pour rappel, \u00ab\u00a0Disruption\u00a0\u00bb est ce plan imagin\u00e9 \u00e0 l&rsquo;\u00e9poque de Paul Magnette avec la police locale de Charleroi pour \u00ab\u00a0occuper le terrain\u00a0\u00bb, s\u00e9curiser les points chauds et faire patrouiller davantage de policiers. Sous Thomas Dermine, bourgmestre actuel, ce dispositif va voir une nouvelle mouture se mettre en place : en journ\u00e9e, 15 policiers seront actifs sur le terrain pour \u00ab\u00a0traquer\u00a0\u00bb les dealers et pr\u00e9venir la violence (12 \u00e9quivalents temps plein la nuit), sur le centre-ville, notamment au Campus, en coordination avec le CPAS, les \u00e9ducateurs de rue et les gardiens de la paix.<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Plus d&rsquo;informations \u00e0 venir.<\/p>\n","protected":false},"excerpt":{"rendered":"En fait, de nombreux policiers sont convi\u00e9s \u00e0 l&rsquo;H\u00f4tel de Ville de Charleroi pour \u00e9couter ce que le&hellip;\n","protected":false},"author":2,"featured_media":53152,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[12,13,18,17,143,335,1321],"class_list":{"0":"post-53151","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-belgique","8":"tag-be","9":"tag-be-fr","10":"tag-belgique","11":"tag-belgium","12":"tag-charleroi","13":"tag-paul-magnette","14":"tag-thomas-dermine"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@be_fr\/116285473180695308","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/53151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/comments?post=53151"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/53151\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media\/53152"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media?parent=53151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/categories?post=53151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/tags?post=53151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}