{"id":64363,"date":"2026-04-02T22:19:05","date_gmt":"2026-04-02T22:19:05","guid":{"rendered":"https:\/\/www.europesays.com\/be-fr\/64363\/"},"modified":"2026-04-02T22:19:05","modified_gmt":"2026-04-02T22:19:05","slug":"christian-clavier-ouvre-les-portes-de-sa-sublime-maison-bruxelloise-a-la-facade-art-deco-un-cocon-convivial","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/be-fr\/64363\/","title":{"rendered":"Christian Clavier ouvre les portes de sa sublime maison bruxelloise \u00e0 la \u00ab\u00a0fa\u00e7ade Art D\u00e9co\u00a0\u00bb, un cocon \u00ab\u00a0convivial\u00a0\u00bb"},"content":{"rendered":"<p>Par <a class=\"author_recette\" id=\"author_name\" href=\"https:\/\/www.nextplz.fr\/auteur\/victoria-buisson\" rel=\"nofollow noopener\" target=\"_blank\">Victoria<br \/>\nBuisson<\/a> &#8211;<br \/>\nPubli\u00e9 le 02 Avr 2026 \u00e0<br \/>\n22:00<\/p>\n<p class=\"article-intro excerpt\">Apr\u00e8s des ann\u00e9es \u00e0 Londres,<br \/>\nChristian Clavier a pris la d\u00e9cision de poser ses valises \u00e0<br \/>\nBruxelles, en Belgique.<\/p>\n<p>Les Visiteurs, Qu&rsquo;est-ce qu&rsquo;on a fait au Bon Dieu ?, Les<br \/>\nBronz\u00e9s, Ast\u00e9rix et Ob\u00e9lix : Mission Cl\u00e9op\u00e2tre, Jamais sans mon<br \/>\npsy, Le P\u00e8re No\u00ebl est une ordure&#8230; Christian Clavier ne<br \/>\ncompte plus les succ\u00e8s dans lesquels il a eu l&rsquo;opportunit\u00e9 de<br \/>\njouer. Figure embl\u00e9matique du cin\u00e9ma fran\u00e7ais, l&rsquo;acteur encha\u00eene en<br \/>\neffet les projets depuis le d\u00e9but des ann\u00e9es 1970. Et \u00e0 73 ans, il<br \/>\nn&rsquo;a visiblement pas l&rsquo;intention de tirer un trait sur sa passion.<br \/>\nCette ann\u00e9e, il devrait d&rsquo;ailleurs revenir prochainement sur les<br \/>\n\u00e9crans dans le second volet de Cocorico, mais aussi dans<br \/>\nla suite de Kaamelott d&rsquo;Alexandre Astier.<\/p>\n<p>Christian Clavier<br \/>\nbien install\u00e9 en Belgique<\/p>\n<p>Vous l&rsquo;aurez compris, Christian Clavier n&rsquo;est pas du genre \u00e0 se<br \/>\nreposer sur ses lauriers. Ce jeudi 2 avril 2026, il sera m\u00eame de<br \/>\nretour sur TF1 avec la diffusion de Qu&rsquo;est-ce qu&rsquo;on a fait au<br \/>\nBon Dieu ? Un film culte pour l&rsquo;acteur qui a r\u00e9cemment pris la<br \/>\nd\u00e9cision de quitter l&rsquo;Hexagone pour s&rsquo;installer en Belgique. Selon<br \/>\nles informations relay\u00e9es par Gala, c&rsquo;est en effet \u00e0<br \/>\nBruxelles que l&rsquo;acolyte de Jean Reno aurait choisi de poser ses<br \/>\nvalises. Un choix sur lequel il est notamment revenu en 2024, lors<br \/>\nd&rsquo;un entretien accord\u00e9 \u00e0 nos confr\u00e8res de<br \/>\nCin\u00e9-T\u00e9l\u00e9-Revue.<\/p>\n<p>Paris : une<br \/>\nville \u00ab\u00a0devenue invivable\u00a0\u00bb pour l&rsquo;acteur<\/p>\n<p>\u00ab\u00a0L\u2019ambiance est plus conviviale et internationale\u00a0\u00bb,<br \/>\navait r\u00e9v\u00e9l\u00e9 Christian Clavier, visiblement ravi de sa nouvelle vie<br \/>\nchez nos voisins belges. Pour l&rsquo;acteur, Paris \u00e9tait<br \/>\nvraisemblablement \u00ab\u00a0devenue invivable\u00a0\u00bb. Exit la<br \/>\ncapitale fran\u00e7aise, il a donc choisi de s&rsquo;installer dans une vaste<br \/>\ndemeure avec jardin, nich\u00e9e dans le prestigieux secteur du haut de<br \/>\nSaint-Gilles. Ce quartier hupp\u00e9 se trouve \u00e0 seulement dix minutes<br \/>\nen m\u00e9tro de la Gare de Bruxelles-Midi. Il offre ainsi le calme<br \/>\nr\u00e9sidentiel et la proximit\u00e9 pratique avec le centre.<\/p>\n<p>\u00ab\u00a0Une ambiance<br \/>\nboh\u00e8me tr\u00e8s pris\u00e9e des Fran\u00e7ais\u00a0\u00bb<\/p>\n<p>\u00ab\u00a0Avec ses fa\u00e7ades Art D\u00e9co typiques, ses petites rues \u00e0<br \/>\nl\u2019esprit village et ses commerces de quartier, il y r\u00e8gne une<br \/>\nambiance boh\u00e8me tr\u00e8s pris\u00e9e des Fran\u00e7ais\u00a0\u00bb, pr\u00e9cise le site<br \/>\nimmobilier\u00a0Inside-properties.be. Un d\u00e9tail que<br \/>\n<a href=\"https:\/\/www.nextplz.fr\/people\/476802-christian-clavier-accuse-de-racisme-il-ne-mache-pas-ses-mots-dieu-merci-la-france-entiere-na-pas\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\ncelui qui a \u00e9t\u00e9 accus\u00e9 de racisme<\/a> avait d\u00e9j\u00e0 appr\u00e9ci\u00e9 par le<br \/>\npass\u00e9. \u00ab\u00a0C\u2019est ce que j\u2019avais aim\u00e9 \u00e0 Londres, o\u00f9 j\u2019ai \u00e9galement<br \/>\nhabit\u00e9 jusqu\u2019au Brexit\u00a0\u00bb, avait-il en effet avou\u00e9 au cours de<br \/>\nson interview avec le m\u00e9dia belge.<\/p>\n<p>Des rumeurs d&rsquo;exil<br \/>\nfiscal qui circulent<\/p>\n<p>Pour m\u00e9moire, Christian Clavier, p\u00e8re d&rsquo;une fille avec l&rsquo;actrice<br \/>\nMarie-Anne Chazel, a quitt\u00e9 la France pour Londres en 2012. \u00c0 cette<br \/>\n\u00e9poque, il avait \u00e9t\u00e9 critiqu\u00e9 par les autorit\u00e9s fiscales fran\u00e7aises<br \/>\npour un imp\u00f4t impay\u00e9, ce qui avait aliment\u00e9 <a href=\"https:\/\/www.nextplz.fr\/people\/489118-christian-clavier-dans-le-viseur-du-fisc-sa-luxueuse-villa-corse-a-85-millions-deuros-en-cause\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\nles rumeurs d&rsquo;exil fiscal<\/a>. Son agente, Alexandra Schamis, avait<br \/>\nalors tenu \u00e0 clarifier la situation aupr\u00e8s de l&rsquo;AFP : \u00ab\u00a0Il ne<br \/>\ns\u2019agit absolument pas d\u2019un exil fiscal\u00a0: la Grande-Bretagne<br \/>\nn\u2019est pas du tout une destination favorable\u00a0\u00bb. De quoi mettre<br \/>\nun terme aux rumeurs.<\/p>\n","protected":false},"excerpt":{"rendered":"Par Victoria Buisson &#8211; Publi\u00e9 le 02 Avr 2026 \u00e0 22:00 Apr\u00e8s des ann\u00e9es \u00e0 Londres, Christian Clavier&hellip;\n","protected":false},"author":2,"featured_media":64364,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[102],"tags":[12,13,18,17,7766,129,128,96,95,109],"class_list":{"0":"post-64363","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-people","8":"tag-be","9":"tag-be-fr","10":"tag-belgique","11":"tag-belgium","12":"tag-buzz_nonli","13":"tag-celebrities","14":"tag-celebrity","15":"tag-divertissement","16":"tag-entertainment","17":"tag-people"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@be_fr\/116337440428945574","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/64363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/comments?post=64363"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/64363\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media\/64364"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media?parent=64363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/categories?post=64363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/tags?post=64363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}