{"id":65339,"date":"2026-04-03T18:04:06","date_gmt":"2026-04-03T18:04:06","guid":{"rendered":"https:\/\/www.europesays.com\/be-fr\/65339\/"},"modified":"2026-04-03T18:04:06","modified_gmt":"2026-04-03T18:04:06","slug":"retrouvee-nue-et-defenestree-au-pied-de-son-immeuble-la-compagne-de-son-realisateur-a-perdu-la-vie","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/be-fr\/65339\/","title":{"rendered":"retrouv\u00e9e nue et d\u00e9fenestr\u00e9e au pied de son immeuble, la compagne de son r\u00e9alisateur a perdu la vie"},"content":{"rendered":"<p>Dans la nuit, tout bascule. Une intervention des secours, une<br \/>\nsc\u00e8ne choquante en pleine rue, et un nom bien connu du paysage<br \/>\naudiovisuel fran\u00e7ais qui surgit au c\u0153ur de l&rsquo;enqu\u00eate. L&rsquo;affaire<br \/>\nimplique un r\u00e9alisateur ayant travaill\u00e9 sur la s\u00e9rie Jos\u00e9phine,<br \/>\nange gardien, port\u00e9e depuis pr\u00e8s de trente ans par <a href=\"https:\/\/www.melty.fr\/people\/mimie-mathy-68-ans-et-hors-la-loi-elle-lassume-elle-refuse-de-respecter-cette-regle-jai-un-principe-2283629.html\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\nMimie Mathy, connue pour ne pas respecter une r\u00e8gle en<br \/>\nparticulier<\/a>. Les faits se d\u00e9roulent dans le Xe arrondissement<br \/>\nde Paris, dans la nuit du jeudi au vendredi. Une femme d&rsquo;une<br \/>\nquarantaine d&rsquo;ann\u00e9es est retrouv\u00e9e morte au pied d&rsquo;un immeuble de<br \/>\nla rue du Faubourg-Poissonni\u00e8re. Rapidement, son compagnon est<br \/>\ninterpell\u00e9. Il s&rsquo;agit d&rsquo;un r\u00e9alisateur et producteur li\u00e9 \u00e0 la<br \/>\nfiction de renom de TF1. L&rsquo;enqu\u00eate est en cours pour<br \/>\nd\u00e9terminer les circonstances exactes de ce drame.<\/p>\n<p>Une intervention des secours dans un contexte troublant<\/p>\n<p>Il est environ 4 h du matin lorsque les secours sont alert\u00e9s. \u00c0<br \/>\nleur arriv\u00e9e, la victime est d\u00e9j\u00e0 en arr\u00eat cardio-respiratoire. Des<br \/>\nt\u00e9moins pr\u00e9sents sur la sc\u00e8ne macabre tentent un massage cardiaque<br \/>\nen attendant les \u00e9quipes m\u00e9dicales, mais les efforts resteront<br \/>\nvains malgr\u00e9 l&rsquo;intervention du SMUR et des sapeurs-pompiers. Tr\u00e8s<br \/>\nvite, les premiers \u00e9l\u00e9ments interrogent. La victime est retrouv\u00e9e<br \/>\nnue sur la voie publique. Les constatations laissent penser qu&rsquo;elle<br \/>\naurait chut\u00e9 depuis plusieurs \u00e9tages. Une blessure \u00e0 la hanche,<br \/>\npossiblement caus\u00e9e par une arme blanche, est aussi relev\u00e9e. \u00c0<br \/>\nproximit\u00e9 du corps, un manche de couteau sans lame est d\u00e9couvert,<br \/>\nrenfor\u00e7ant le caract\u00e8re myst\u00e9rieux de la sc\u00e8ne.<\/p>\n<p>Un suspect au comportement qui intrigue les enqu\u00eateurs<\/p>\n<p>Dans un second temps, les policiers m\u00e8nent des investigations<br \/>\ndans l&rsquo;immeuble. Leur enqu\u00eate les conduit jusqu&rsquo;au cinqui\u00e8me et<br \/>\ndernier \u00e9tage. C&rsquo;est l\u00e0 qu&rsquo;ils d\u00e9couvrent un homme sortant<br \/>\nd&rsquo;un appartement, l&rsquo;altitude attire imm\u00e9diatement<br \/>\nl&rsquo;attention. Selon les \u00e9l\u00e9ments rapport\u00e9s, il pr\u00e9sente un regard<br \/>\nd\u00e9crit comme \u00ab\u00a0hagard, abattu\u00a0\u00bb et r\u00e9pond de mani\u00e8re \u00e9vasive aux<br \/>\nquestions. \u00c0 l&rsquo;int\u00e9rieur du logement, les enqu\u00eateurs d\u00e9couvrent<br \/>\nplusieurs objets : de la coca\u00efne pos\u00e9e sur une<br \/>\ntable, des couteaux de cuisine ainsi que des effets<br \/>\npersonnels appartenant \u00e0 la victime. L&rsquo;homme reconnait \u00eatre le<br \/>\ncompagnon de la victime. Il est imm\u00e9diatement interpell\u00e9 et<br \/>\n<a href=\"https:\/\/www.melty.fr\/people\/rima-hassan-drogue-retrouvee-apres-un-achat-de-cbd-ce-scenario-inattendu-qui-pourrait-concerner-bien-plus-de-consommateurs-2307665.html\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\nplac\u00e9 en garde \u00e0 vue afin d&rsquo;\u00eatre entendu<\/a>.<\/p>\n<p>Josephine, ange gardien, et un<br \/>\nr\u00e9alisateur d\u00e9sormais au c\u0153ur d&rsquo;une enqu\u00eate<\/p>\n<p>Peu apr\u00e8s, son identit\u00e9 est \u00e9voqu\u00e9e dans l&rsquo;enqu\u00eate. Il s&rsquo;agirait<br \/>\nde Philippe P., un r\u00e9alisateur ayant particip\u00e9 \u00e0 plusieurs saisons<br \/>\nde Jos\u00e9phine, ange gardien. Diffus\u00e9e depuis 1997,<br \/>\nla s\u00e9rie s&rsquo;impose comme une r\u00e9f\u00e9rence de la t\u00e9l\u00e9vision fran\u00e7aise,<br \/>\navec plus de 100 \u00e9pisodes et des audiences ayant d\u00e9pass\u00e9 les 11<br \/>\nmillions de t\u00e9l\u00e9spectateurs. D\u00e8s lors, l&rsquo;affaire prend une<br \/>\ndimension particuli\u00e8re. La police judiciaire, le parquet et la<br \/>\npolice scientifique sont mobilis\u00e9s. Les investigations se<br \/>\npoursuivent pour comprendre pr\u00e9cis\u00e9ment ce qu&rsquo;il s&rsquo;est pass\u00e9 dans<br \/>\ncet appartement parisien, dans une nuit dont de nombreuses <a href=\"https:\/\/www.melty.fr\/people\/loana-vue-comme-une-criminelle-ces-demarches-insensees-et-tentatives-desesperees-pour-sen-sortir-2307768.html\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\nzones d&rsquo;ombre subsistent<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"Dans la nuit, tout bascule. Une intervention des secours, une sc\u00e8ne choquante en pleine rue, et un nom&hellip;\n","protected":false},"author":2,"featured_media":65340,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[102],"tags":[12,13,18,17,3309,7766,129,128,96,95,109],"class_list":{"0":"post-65339","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-people","8":"tag-be","9":"tag-be-fr","10":"tag-belgique","11":"tag-belgium","12":"tag-breakingnews","13":"tag-buzz_nonli","14":"tag-celebrities","15":"tag-celebrity","16":"tag-divertissement","17":"tag-entertainment","18":"tag-people"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@be_fr\/116342100029944873","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/65339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/comments?post=65339"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/65339\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media\/65340"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media?parent=65339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/categories?post=65339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/tags?post=65339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}