{"id":67664,"date":"2026-04-06T14:43:06","date_gmt":"2026-04-06T14:43:06","guid":{"rendered":"https:\/\/www.europesays.com\/be-fr\/67664\/"},"modified":"2026-04-06T14:43:06","modified_gmt":"2026-04-06T14:43:06","slug":"la-coree-du-sud-presente-ses-excuses-a-la-coree-du-nord-apres-un-incident-des-actes-irresponsables-et-imprudents-de-certaines-personnes","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/be-fr\/67664\/","title":{"rendered":"La Cor\u00e9e du Sud pr\u00e9sente ses excuses \u00e0 la Cor\u00e9e du Nord apr\u00e8s un incident: \u00ab\u00a0Des actes irresponsables et imprudents de certaines personnes\u00a0\u00bb"},"content":{"rendered":"<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">\u00ab\u00a0Un incident impliquant des drones civils, qui n&rsquo;aurait pas d\u00fb se produire, a eu lieu sous cette administration et il a \u00e9t\u00e9 confirm\u00e9 qu&rsquo;un responsable du Service national de renseignement et un soldat en service actif \u00e9taient impliqu\u00e9s\u00a0\u00bb, a pr\u00e9cis\u00e9 M. Lee lundi.<\/p>\n<p><a href=\"https:\/\/www.lalibre.be\/international\/asie\/2026\/03\/28\/la-coree-du-sud-et-la-belgique-face-a-un-monde-trouble-il-est-important-de-respecter-les-normes-internationales-et-nos-alliances-BGH7GVRSARF2ZEGOD6SNMDQGWM\/\" target=\"_self\" class=\"ap-StoryInterstitialLink ap-StoryElement ap-StoryElement--mb\" rel=\"nofollow noopener\">La Cor\u00e9e du Sud et la Belgique face \u00e0 un monde troubl\u00e9 : \u00ab\u00a0Il est important de respecter les normes internationales et nos alliances\u00a0\u00bb<\/a><\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Pyongyang avait annonc\u00e9 en janvier avoir abattu un drone \u00e9quip\u00e9 de \u00ab\u00a0mat\u00e9riel de surveillance\u00a0\u00bb pr\u00e8s de la ville nord-cor\u00e9enne de Kaesong, \u00e0 quelques kilom\u00e8tres de la fronti\u00e8re intercor\u00e9enne, et <a href=\"https:\/\/www.lalibre.be\/international\/asie\/2026\/02\/12\/la-coree-du-nord-promet-une-reponse-terrible-en-cas-de-nouvelle-incursion-de-drones-MFADPMVSGZD3BESJUMOBHA74MI\/\" target=\"_self\" rel=\"nofollow noopener\">promis une r\u00e9ponse \u00ab\u00a0terrible\u00a0\u00bb<\/a> en cas de nouvelle incursion de drones venus du Sud. Trois civils sud-cor\u00e9ens ont \u00e9t\u00e9 inculp\u00e9s.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"w-full lazyload lazyload--opacity object-contain\" style=\"aspect-ratio:150 \/ 100;opacity:1\" alt=\"(FILES) These images taken on January 4, 2026 and released as a combo image by North Korea's official Korean Central News Agency (KCNA) via KNS on January 10, 2026 shows wreckage of a drone that North Korea claims originated from South Korea, and brought down by specialised electronic warfare assets after violating North Korean airspace. South Korean President Lee Jae Myung expressed regret to Pyongyang on April 6, 2026 for drones being sent into North Korea earlier this year by civilians whose behaviour he called &quot;reckless.&quot; (Photo by KCNA VIA KNS \/ AFP) \/ South Korea OUT \/ ---EDITORS NOTE--- RESTRICTED TO EDITORIAL USE - MANDATORY CREDIT &quot;AFP PHOTO\/KCNA VIA KNS&quot; - NO MARKETING NO ADVERTISING CAMPAIGNS - DISTRIBUTED AS A SERVICE TO CLIENTS&#10;THIS PICTURE WAS MADE AVAILABLE BY A THIRD PARTY. AFP CAN NOT INDEPENDENTLY VERIFY THE AUTHENTICITY, LOCATION, DATE AND CONTENT OF THIS IMAGE. \/ \" width=\"2500\" height=\"1667\" fetchpriority=\"auto\" src=\"https:\/\/www.europesays.com\/be-fr\/wp-content\/uploads\/2026\/04\/1775339536_35_S5VKD3X55FFF3BW6V4SEHXNP7I.png\"  data- data-optimumx=\"1\"\/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.europesays.com\/be-fr\/wp-content\/uploads\/2026\/04\/EO7HW6KNH5FCNGP5PLCO4BRRCE.jpg\" width=\"2500\" height=\"1667\" alt=\"(FILES) These images taken on January 4, 2026 and released as a combo image by North Korea's official Korean Central News Agency (KCNA) via KNS on January 10, 2026 shows wreckage of a drone that North Korea claims originated from South Korea, and brought down by specialised electronic warfare assets after violating North Korean airspace. South Korean President Lee Jae Myung expressed regret to Pyongyang on April 6, 2026 for drones being sent into North Korea earlier this year by civilians whose behaviour he called \" reckless.=\"\" by=\"\" kcna=\"\" via=\"\" kns=\"\" afp=\"\" south=\"\" korea=\"\" out=\"\" note---=\"\" restricted=\"\" to=\"\" editorial=\"\" use=\"\" mandatory=\"\" credit=\"\" photo=\"\" no=\"\" marketing=\"\" advertising=\"\" campaigns=\"\" distributed=\"\" as=\"\" a=\"\" service=\"\" clients=\"\" this=\"\" picture=\"\" was=\"\" made=\"\" available=\"\" third=\"\" party.=\"\" can=\"\" not=\"\" independently=\"\" verify=\"\" the=\"\" authenticity=\"\" location=\"\" date=\"\" and=\"\" content=\"\" of=\"\" image.=\"\" class=\"absolute inset-0 w-full\"\/> \u00a9AFP or licensors<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">En septembre, l&rsquo;agence officielle nord-cor\u00e9enne KCNA avait d\u00e9j\u00e0 accus\u00e9 la Cor\u00e9e du Sud d&rsquo;avoir envoy\u00e9 un drone similaire au-dessus de Kaesong, affirmant que l&rsquo;engin s&rsquo;\u00e9tait \u00e9cras\u00e9 apr\u00e8s avoir \u00e9t\u00e9 neutralis\u00e9 par un brouillage \u00e9lectronique.<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Lee Jae Myung veut renouer le dialogue avec le Nord depuis son entr\u00e9e en fonction l&rsquo;ann\u00e9e derni\u00e8re. Cependant, le dirigeant nord-cor\u00e9en Kim Jong Un, qui a qualifi\u00e9 S\u00e9oul d'\u00a0\u00bbennemi le plus hostile\u00a0\u00bb, a jusqu&rsquo;\u00e0 pr\u00e9sent rejet\u00e9 sa main tendue.<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Les deux Etats n&rsquo;ont jamais sign\u00e9 de trait\u00e9 de paix \u00e0 l&rsquo;issue de la guerre de Cor\u00e9e (1950-1953), qui s&rsquo;est sold\u00e9e par un armistice.<\/p>\n","protected":false},"excerpt":{"rendered":"\u00ab\u00a0Un incident impliquant des drones civils, qui n&rsquo;aurait pas d\u00fb se produire, a eu lieu sous cette administration&hellip;\n","protected":false},"author":2,"featured_media":67665,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[12,13,18,17,11452,11473,1240,31,76,32],"class_list":{"0":"post-67664","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-international","8":"tag-be","9":"tag-be-fr","10":"tag-belgique","11":"tag-belgium","12":"tag-coree-du-nord","13":"tag-coree-du-sud","14":"tag-diplomatie","15":"tag-international","16":"tag-technologies","17":"tag-world-news"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@be_fr\/116358296860069905","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/67664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/comments?post=67664"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/67664\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media\/67665"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media?parent=67664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/categories?post=67664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/tags?post=67664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}