{"id":83225,"date":"2026-04-22T18:04:12","date_gmt":"2026-04-22T18:04:12","guid":{"rendered":"https:\/\/www.europesays.com\/be-fr\/83225\/"},"modified":"2026-04-22T18:04:12","modified_gmt":"2026-04-22T18:04:12","slug":"marine-bientot-en-duo-avec-celine-dion","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/be-fr\/83225\/","title":{"rendered":"Marine bient\u00f4t en duo avec C\u00e9line Dion ?"},"content":{"rendered":"<p itemprop=\"description\">Les artistes de la nouvelle g\u00e9n\u00e9ration sont nombreux \u00e0 vouloir collaborer avec C\u00e9line Dion. Marine, gagnante de la Star Academy saison 12, ne fait pas exception \u00e0 la r\u00e8gle.<\/p>\n<p>C&rsquo;est l&rsquo;information la plus comment\u00e9e depuis le d\u00e9but de l&rsquo;ann\u00e9e 2026 dans la chanson fran\u00e7aise : <a href=\"https:\/\/mradio.fr\/news\/musique\/56546\/celine-dion-en-concert-a-paris-des-l-automne-2026\" target=\"_blank\" rel=\"noopener nofollow\">C\u00e9line Dion est de retour !<\/a> La star a pr\u00e9vu une s\u00e9rie de concerts \u00e0 Paris La D\u00e9fense Arena au dernier trimestre, ce qui a provoqu\u00e9 l&rsquo;effet d&rsquo;un petit s\u00e9isme dans l&rsquo;industrie, avec des milliers de fans qui se sont jet\u00e9s sur les billetteries en ligne. Mais m\u00eame parmi les autres chanteurs, l&rsquo;annonce du retour de la Star a provoqu\u00e9 une certaine \u00e9motion, \u00e0 l&rsquo;image de <a href=\"https:\/\/mradio.fr\/news\/musique\/56725\/je-vais-te-manger-marine-tacle-ses-haters-avec-beaucoup-d-humour\" target=\"_blank\" rel=\"noopener nofollow\">Marine<\/a>, gagnante de la <a href=\"https:\/\/mradio.fr\/news\/musique\/56553\/marine-son-parcours-a-la-star-academy-de-son-arrivee-jusqu-a-sa-victoire\" target=\"_blank\" rel=\"noopener nofollow\">Star Academy<\/a> saison 12, qui se met \u00e0 r\u00eaver d&rsquo;un duo avec des \u00e9toiles dans les yeux.<\/p>\n<p>La jeune chanteuse a elle-m\u00eame fait l&rsquo;exp\u00e9rience de la tourn\u00e9e r\u00e9cemment, d&rsquo;abord avec la Star Academy et ensuite en solo, elle qui sillonne actuellement les routes de France, et qui tournera encore tout l&rsquo;\u00e9t\u00e9. On peut dire que Marine a pris en exp\u00e9rience depuis ses d\u00e9buts, mais \u00e7a ne l&#8217;emp\u00eache pas de r\u00e9agir comme une enfant \u00e9merveill\u00e9e lorsque le sujet de C\u00e9line Dion est abord\u00e9, pendant l&rsquo;\u00e9mission \u00ab\u00a0Flashback\u00a0\u00bb sur CStar.\u00a0<\/p>\n<p>&#13;<\/p>\n<p>Si je l&rsquo;avais devant, je lui dirais quoi ? J&rsquo;aimerais bien chanter sur sc\u00e8ne avec elle. Mais \u00e7a, c&rsquo;est un r\u00eave inaccessible je pense. Je ne dois pas \u00eatre la seule qui aurait bien envie de chanter sur sc\u00e8ne avec elle\u2026 Je me dis que All by myself je peux la faire avec elle, je peux assurer la high note.<\/p>\n<p>&#13;<\/p>\n<p>A sa r\u00e9ponse, on sent que Marine a vraiment r\u00e9fl\u00e9chi \u00e0 cette question en amont et qu&rsquo;elle voue une v\u00e9ritable admiration \u00e0 C\u00e9line Dion. Une admiration qu&rsquo;on avait pu ressentir \u00e0 l&rsquo;\u00e9poque d&rsquo;un prime de la Star Academy, lorsqu&rsquo;elle avait chant\u00e9 la fameuse chanson \u00ab\u00a0All by myself\u00a0\u00bb, qui avait tellement marqu\u00e9 les gens que la production lui a demand\u00e9 de le refaire sur sc\u00e8ne pendant la tourn\u00e9e des \u00e9l\u00e8ves.\u00a0<\/p>\n<p>&#13;<\/p>\n<p>Au d\u00e9but j\u2019ai h\u00e9sit\u00e9 \u00e0 dire non puis apr\u00e8s je me suis dit &lsquo;\u00e7a va \u00eatre un d\u00e9fi, \u00e7a va \u00eatre trop bien&rsquo;. Et puis vocalement, \u00e7a entra\u00eene, \u00e7a muscle donc je l\u2019ai vraiment chant\u00e9 59 fois d\u2019affil\u00e9e.<\/p>\n<p>&#13;<\/p>\n<p>Autant vous dire que <a href=\"https:\/\/mradio.fr\/news\/people\/55088\/marine-star-academy-comparee-a-celine-dion-decouvrez-son-point-commun-avec-la-chanteuse\" target=\"_blank\" rel=\"noopener nofollow\">cette envie de Marine de chanter avec C\u00e9line Dion<\/a>, c&rsquo;est du tr\u00e8s s\u00e9rieux, ce n&rsquo;est pas qu&rsquo;un caprice. On esp\u00e8re que son v\u0153u sera exauc\u00e9 un jour !<\/p>\n","protected":false},"excerpt":{"rendered":"Les artistes de la nouvelle g\u00e9n\u00e9ration sont nombreux \u00e0 vouloir collaborer avec C\u00e9line Dion. Marine, gagnante de la&hellip;\n","protected":false},"author":2,"featured_media":83226,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[98],"tags":[141,10,1823,4290,12,13,18,17,6617,366,96,95,151,140,7725,107,7726,108,1164,943,530,525,7727],"class_list":{"0":"post-83225","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-musique","8":"tag-actu","9":"tag-actualites","10":"tag-actus","11":"tag-artistes","12":"tag-be","13":"tag-be-fr","14":"tag-belgique","15":"tag-belgium","16":"tag-chanson-francaise","17":"tag-concert","18":"tag-divertissement","19":"tag-entertainment","20":"tag-france","21":"tag-info","22":"tag-mradio","23":"tag-music","24":"tag-musicale","25":"tag-musique","26":"tag-musique-francaise","27":"tag-paris","28":"tag-podcast","29":"tag-radio","30":"tag-radio-francaise"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@be_fr\/116449684047493415","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/83225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/comments?post=83225"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/posts\/83225\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media\/83226"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/media?parent=83225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/categories?post=83225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/be-fr\/wp-json\/wp\/v2\/tags?post=83225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}