{"id":10267,"date":"2026-02-18T14:28:19","date_gmt":"2026-02-18T14:28:19","guid":{"rendered":"https:\/\/www.europesays.com\/ch-de\/10267\/"},"modified":"2026-02-18T14:28:19","modified_gmt":"2026-02-18T14:28:19","slug":"gefaehrliches-duo-grippe-und-pneumokokken-warum-eine-impfung-jetzt-sinnvoll-ist","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-de\/10267\/","title":{"rendered":"Gef\u00e4hrliches Duo: Grippe und Pneumokokken &#8211; warum eine Impfung jetzt sinnvoll ist"},"content":{"rendered":"<p>\n        Gef\u00e4hrliches Duo: Grippe und Pneumokokken &#8211; warum eine Impfung jetzt sinnvoll ist\n    <\/p>\n<p>                          <img decoding=\"async\" class=\"pp-lazy\" src=\"https:\/\/www.europesays.com\/ch-de\/wp-content\/uploads\/2026\/02\/Frau wird geimpft_co~zer Pharma GmbH.jpg\" alt=\"Eine Impfung gegen Pneumokokken kann vor langfristigen Folgen f\u00fcr die Gesundheit sch\u00fctzen \/ Weiterer Text \u00fcber ots und www.presseportal.de\/nr\/13016 \/ Die Verwendung dieses Bildes f\u00fcr redaktionelle Zwecke ist unter Beachtung aller mitgeteilten Nutzungsbedingungen zul\u00e4ssig und dann auch honorarfrei. Ver\u00f6ffentlichung ausschlie\u00dflich mit Bildrechte-Hinweis.\" title=\"Eine Impfung gegen Pneumokokken kann vor langfristigen Folgen f\u00fcr die Gesundheit sch\u00fctzen \/ Weiterer Text \u00fcber ots und www.presseportal.de\/nr\/13016 \/ Die Verwendung dieses Bildes f\u00fcr redaktionelle Zwecke ist unter Beachtung aller mitgeteilten Nutzungsbedingungen zul\u00e4ssig und dann auch honorarfrei. Ver\u00f6ffentlichung ausschlie\u00dflich mit Bildrechte-Hinweis.\"\/><br \/>\n              Eine Impfung gegen Pneumokokken kann vor langfristigen Folgen f\u00fcr die Gesundheit sch\u00fctzen \/ Weiterer Text \u00fcber ots und www.presseportal.de\/nr\/13016 \/ Die Verwendung dieses Bildes f\u00fcr redaktionelle Zwecke ist unter Beachtung aller mitgeteilten Nutzungsbedingungen zul\u00e4ssig und dann auch honorarfrei. Ver\u00f6ffentlichung ausschlie\u00dflich mit Bildrechte-Hinweis.<\/p>\n<p>Berlin (ots) &#8211; <\/p>\n<p>Mit K\u00e4lte, Frost und vor allem Atemwegserkrankungen hat uns der Winter aktuell fest im Griff. Laut Robert Koch-Institut (RKI) waren allein in den ersten beiden Kalenderwochen mehr als doppelt so viele Personen an Grippe erkrankt wie in 2025 zum selben Zeitpunkt [1]. Auch die F\u00e4lle schwerwiegender Pneumokokken-Infektionen sind im gleichen Meldezeitraum besorgniserregend hoch [1]. Pneumokokken k\u00f6nnen zu Blutvergiftung und Hirnhautentz\u00fcndung f\u00fchren und gelten als h\u00e4ufigster Ausl\u00f6ser f\u00fcr eine bakterielle Lungenentz\u00fcndung bei Erwachsenen. Wer bereits an Grippe erkrankt ist, hat ein besonders hohes Risiko f\u00fcr eine zus\u00e4tzliche Infektion mit Pneumokokken, weil das Immunsystem und die Lunge geschw\u00e4cht und anf\u00e4lliger sind [2]. Eine Impfung kann vor den Folgen einer Infektion sch\u00fctzen und wird f\u00fcr alle Menschen ab 60 Jahren sowie f\u00fcr alle Personen ab 18 Jahren mit chronischen Erkrankungen von der St\u00e4ndigen Impfkommission (STIKO) empfohlen [3]. <\/p>\n<p>Aufgrund der derzeit hohen Zahl an Grippef\u00e4llen steigt auch die Gefahr einer Infektion durch Pneumokokken [4], [5]. Pneumokokken sind Bakterien, die genau wie Grippeviren durch Tr\u00f6pfcheninfektionen \u00fcbertragen werden, etwa beim Husten, Niesen oder Sprechen [6]. Sie sind verantwortlich f\u00fcr eine Vielzahl von Erkrankungen, die von leichteren Atemwegsinfekten bis hin zu lebensbedrohlichen Lungenentz\u00fcndungen, Hirnhautentz\u00fcndungen oder Blutvergiftungen reichen [4]. F\u00fcr bakterielle Lungenentz\u00fcndungen stellen sie die h\u00e4ufigste Ursache dar [7]. Was diese Bakterien jetzt allerdings besonders gef\u00e4hrlich macht: Pneumokokken sind nach Grippeinfektionen oft f\u00fcr schwerwiegende Koinfektionen verantwortlich, die einen Klinikaufenthalt mit sich ziehen k\u00f6nnen [2]. Eine Koinfektion bedeutet, dass zu einer Virusinfektion wie Grippe noch eine bakterielle Infektion hinzukommen kann. Dieses gef\u00e4hrliche Duo kann als sogenannte Superinfektion den Zustand der Patient:innen dann erheblich verschlechtern. Untersuchungen zeigen, dass viele Grippe-bedingte Todesf\u00e4lle meist durch eine bakterielle Lungenentz\u00fcndung verursacht wurden [8]. <\/p>\n<p>Langfristige Folgen einer Pneumokokken-Infektion mit Lungenentz\u00fcndung <\/p>\n<p>Besonders \u00e4ltere Menschen sind gef\u00e4hrdet, an einer Pneumokokken-Infektion schwer zu erkranken, denn mit zunehmendem Alter l\u00e4sst die Kraft des Immunsystems nach. Generell gilt, dass Personen ab 60 Jahren anf\u00e4lliger f\u00fcr schwere Infektionskrankheiten werden [9], [10], [11]. So kann eine bakterielle Lungenentz\u00fcndung den K\u00f6rper, egal ob gesund oder vorerkrankt, erheblich schw\u00e4chen und f\u00fcr Betroffene oft einen tiefen Einschnitt im Leben bedeuten. Viele erholen sich danach nicht mehr vollst\u00e4ndig und leiden fortan unter k\u00f6rperlichen Einschr\u00e4nkungen [11]. So k\u00f6nnen zum Beispiel einfache Alltagst\u00e4tigkeiten wie Treppensteigen, Einkaufen oder Gartenarbeit auch nach der Genesung beschwerlich oder nicht mehr ohne Hilfe m\u00f6glich sein. <\/p>\n<p>Eine Impfung gegen Pneumokokken kann sch\u00fctzen <\/p>\n<p>Eine Impfung kann dabei helfen, die Risikogruppen vor einer Pneumokokken-Infektion zu sch\u00fctzen. Die STIKO empfiehlt daher Personen ab 60 Jahren standardm\u00e4\u00dfig eine einmalige Impfung gegen Pneumokokken, die zu jedem Zeitpunkt im Jahr und unabh\u00e4ngig von der Saison f\u00fcr Atemwegserkrankungen erfolgen kann [3]. Aber auch f\u00fcr Personen ab 18 Jahren mit bestimmten Grunderkrankungen [A] wie etwa einer chronisch-obstruktiven Lungenerkrankung (COPD), einer Immunschw\u00e4che, Asthma oder Diabetes sowie bei speziellen beruflichen T\u00e4tigkeiten [B] wird die Pneumokokken-Impfung von der STIKO empfohlen [3]. <\/p>\n<p>Tipp: Impfstatus aktualisieren und individuelles Infektionsrisiko einsch\u00e4tzen <\/p>\n<p>Wer bereits vor oder w\u00e4hrend der Corona-Pandemie gegen Pneumokokken geimpft wurde, sollte sich jetzt mit seinem Arzt oder seiner \u00c4rztin beraten und ggf. eine Aktualisierung des Impfstatus pr\u00fcfen. Um das individuelle Infektionsrisiko besser einsch\u00e4tzen zu k\u00f6nnen, steht auf www.lungesch\u00fctzen.de (http:\/\/www.xn--lungeschtzen-klb.de) zudem ein einfacher Online-Test zur Verf\u00fcgung. <\/p>\n<p>\u00dcber Pfizer &#8211; &#171;Breakthroughs that change patients&#8216; lives&#187; <\/p>\n<p>Bei Pfizer arbeiten wir weltweit t\u00e4glich daran, die Lebensqualit\u00e4t von Menschen zu verbessern, indem wir ihnen Zugang zu innovativen Medikamenten und Impfstoffen erm\u00f6glichen. Dabei setzen wir auf Wissenschaft und unser globales Netzwerk aus Forschungs-, Entwicklungs-, Produktions- und Vertriebszentren. Es ist unser Anspruch, bei der Entdeckung, Entwicklung und Herstellung innovativer Arzneimittel neue Standards zu setzen. Das gilt f\u00fcr ihre Qualit\u00e4t, ihre Sicherheit und ihren Nutzen f\u00fcr Patient:innen. Sowohl in Industrie- als auch in Schwellenl\u00e4ndern treiben unsere Kolleg:innen die Pr\u00e4vention, Behandlung und Heilung der schwerwiegendsten Erkrankungen unserer Zeit voran. Als einer der weltweit f\u00fchrenden forschenden Arzneimittelhersteller f\u00f6rdern wir gemeinsam mit medizinischem Fachpersonal, Gesundheitseinrichtungen, Regierungsorganisationen und lokalen Gemeinschaften \u00fcberall auf der Welt eine verl\u00e4ssliche und bezahlbare Gesundheitsversorgung. Seit mehr als 175 Jahren arbeiten wir daran, f\u00fcr alle, die sich auf uns verlassen, etwas zu bewegen. <\/p>\n<p>Der Hauptsitz von Pfizer ist in New York. In Deutschland arbeiten mehr als 3.000 Mitarbeiter:innen an den Standorten Berlin, Freiburg und Karlsruhe. Unser Werk in Freiburg ist eine der modernsten Pharmaproduktionsst\u00e4tten der Welt und die gr\u00f6\u00dfte von Pfizer f\u00fcr Tabletten und Kapseln. Es ist Vorreiter bei Nachhaltigkeit und Industrie 4.0. <\/p>\n<p>Mehr auf www.pfizer.de. Folgen Sie uns auf LinkedIn (https:\/\/www.linkedin.com\/company\/pfizer\/) und Instagram (https:\/\/www.instagram.com\/pfizer_wissenschaft\/). <\/p>\n<p>Quellen <\/p>\n<p>[A] Mit relevanter Grunderkrankung, wie angeborene oder erworbene Immundefekte, chronische Krankheiten und fremdk\u00f6rperassoziierte Risiken f\u00fcr Hirnhautentz\u00fcndung durch Pneumokokken (Pneumokokken-Meningitis) [6]. <\/p>\n<p>[B] Zus\u00e4tzlich als Impfung in der beruflichen Indikation empfohlen: Berufliche T\u00e4tigkeiten wie Schwei\u00dfen und Trennen von Metallen, die zu einer Exposition gegen\u00fcber Metallrauchen, einschlie\u00dflich metalloxidischen Schwei\u00dfrauchen, f\u00fchren [6]. <\/p>\n<p>[1] Robert Koch-Institut. Epid Bull. 2026;3:1-22. <\/p>\n<p>[2] Boehme JD, et al. Deutsches \u00c4rzteblatt: Koinfektion mit Influenza und Pneumokokken: Influenza bereitet Infektion mit Pneumokokken vor &#8211; Deutsches \u00c4rzteblatt (https:\/\/ots.de\/PJ4QrU). Letzter Zugriff: 19.01.2026. <\/p>\n<p>[3] Robert Koch-Institut. Epid Bull. 2026;4:1-79. <\/p>\n<p>[4] European Centre for Disease Prevention and Control (ECDC): Factsheet about pneumococcal disease. Stand: 28.11.2023. https:\/\/www.ecdc.europa.eu\/en\/pneumococcal-disease\/facts. Letzter Zugriff: 19.01.2026. <\/p>\n<p>[5] Deutsches \u00c4rzteblatt: Perspektive der Pneumologie und Allergologie. Koinfektion mit Influenza und Pneumokokken: Influenza breitet Infektion mit Pneumokokken vor. https:\/\/ots.de\/1pA5J4. Letzter Zugriff: 19.01.2026. <\/p>\n<p>[6] Robert Koch-Institut. Faktenblatt zur Pneumokokken-Impfung. https:\/\/ots.de\/2P6Slr. Letzter Zugriff: 19.01.2026. <\/p>\n<p>[7] Braeken DCW, et al. Infection. 2021;49:533-537. <\/p>\n<p>[8] Robert Koch Institut. H\u00e4ufig gestellte Fragen und Antworten zur Grippe (Influenza). Stand 21.01.2026 https:\/\/www.rki.de\/SharedDocs\/FAQs\/DE\/Influenza\/FAQ_Liste.html Letzter Zugriff: 26.01.2026 <\/p>\n<p>[9] Pletz MW, Bahrs C. Internist. 2021;62(8):807-815. <\/p>\n<p>[10] Weiser JN, Ferreira DM, Paton JC. Nat Rev Microbiol. 2018;16:355-367. <\/p>\n<p>[11] Kruckow KL et al. Pneumonia (Nathan). 2023; 15(1): 5. <\/p>\n<p>Pressekontakt:<\/p>\n<p>IPG PR<br \/>Johanna Meier-Rink<br \/>Spiesergasse 11, 50670 K\u00f6ln<br \/>Telefon: +49 (0)170 &#8211; 5443244<br \/>E-Mail: JMeier-Rink@ipg-pr.com<\/p>\n<p>Original-Content von: Pfizer Pharma GmbH, \u00fcbermittelt durch news aktuell<\/p>\n<p>    <script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"Gef\u00e4hrliches Duo: Grippe und Pneumokokken &#8211; warum eine Impfung jetzt sinnvoll ist Eine Impfung gegen Pneumokokken kann vor&hellip;\n","protected":false},"author":2,"featured_media":3861,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[312,46,67,66,330,4562,316,296,45,44],"class_list":{"0":"post-10267","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-gesundheit","8":"tag-bild","9":"tag-ch","10":"tag-gesundheit","11":"tag-health","12":"tag-medizin","13":"tag-pfizer-pharma-gmbh","14":"tag-pressemitteilungen","15":"tag-ratgeber","16":"tag-schweiz","17":"tag-switzerland"},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts\/10267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/comments?post=10267"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts\/10267\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/media\/3861"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/media?parent=10267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/categories?post=10267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/tags?post=10267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}