{"id":114033,"date":"2026-05-07T10:35:14","date_gmt":"2026-05-07T10:35:14","guid":{"rendered":"https:\/\/www.europesays.com\/ch-de\/114033\/"},"modified":"2026-05-07T10:35:14","modified_gmt":"2026-05-07T10:35:14","slug":"appenzell-innerrhoden-person-bekommt-an-landsgemeinde-k-o-tropfen-verabreicht","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-de\/114033\/","title":{"rendered":"Appenzell Innerrhoden: Person bekommt an Landsgemeinde K.-o.-Tropfen verabreicht"},"content":{"rendered":"<p type=\"textBlockArray\" class=\"sc-9c011e72-2 fFxHyD\">An der Landsgemeinde vom 26. April kam es in Appenzell zu einem Vorfall. Wie die Kantonspolizei Appenzell Innerrhoden in einer Medienmitteilung schreibt, wurden einer Person Substanzen aus dem Bereich der K.-o.-Tropfen verabreicht.<\/p>\n<p type=\"textBlockArray\" class=\"sc-9c011e72-2 fFxHyD\">Die Polizei erhielt zwei Tage nach dem Vorfall eine Meldung davon und nahm daraufhin umgehend die Ermittlungen auf. Nun bittet sie Zeuginnen und Zeugen, Betroffene oder Personen mit Hinweisen, sich bei der Kantonspolizei Appenzell Innerrhoden zu melden.<\/p>\n<p>Aufeinander aufpassen und Getr\u00e4nke im Blick behalten<\/p>\n<p type=\"textBlockArray\" class=\"sc-9c011e72-2 fFxHyD\">Weiter r\u00e4t sie, Getr\u00e4nke nie unbeaufsichtigt zu lassen und auf Mitmenschen zu achten. Leide man an unerkl\u00e4rlichen Symptomen, wird geraten, direkt ein Spital aufzusuchen, um Untersuchungen durchf\u00fchren zu lassen. Weiter soll man allf\u00e4llige Vorf\u00e4lle bei der Polizei melden und sich vor Ort beraten lassen.<\/p>\n<p><a href=\"https:\/\/www.20min.ch\/autoren\/50653925\/zoe-stoller\" class=\"sc-b1f21c84-2 egfiIF\" rel=\"nofollow noopener\" target=\"_blank\"><img decoding=\"async\" alt=\"Zo\u00e9 Stoller\" src=\"https:\/\/www.europesays.com\/ch-de\/wp-content\/uploads\/2026\/05\/1778150114_696_d1070143-8581-4d10-a38d-20fdb0517b6e.jpeg\" class=\"sc-b1f21c84-1 iTOvpR\"\/><\/a><\/p>\n<p class=\"sc-f19a47c0-1 jKqFcj\">Zo\u00e9 Stoller (sto) arbeitet seit 2021 bei 20 Minuten. Sie als Blattmacherin und stellvertretende Leiterin des Ressorts Regionen.<\/p>\n","protected":false},"excerpt":{"rendered":"An der Landsgemeinde vom 26. April kam es in Appenzell zu einem Vorfall. Wie die Kantonspolizei Appenzell Innerrhoden&hellip;\n","protected":false},"author":2,"featured_media":114034,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[46,42,40,45,44],"class_list":{"0":"post-114033","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-schweiz","8":"tag-ch","9":"tag-nachrichten","10":"tag-schlagzeilen","11":"tag-schweiz","12":"tag-switzerland"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_de\/116532845910455974","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts\/114033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/comments?post=114033"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts\/114033\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/media\/114034"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/media?parent=114033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/categories?post=114033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/tags?post=114033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}