{"id":11865,"date":"2026-02-19T14:46:07","date_gmt":"2026-02-19T14:46:07","guid":{"rendered":"https:\/\/www.europesays.com\/ch-de\/11865\/"},"modified":"2026-02-19T14:46:07","modified_gmt":"2026-02-19T14:46:07","slug":"airbus-ist-nicht-einverstanden-mit-den-prioritaeten-von-pratt-whitney","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-de\/11865\/","title":{"rendered":"Airbus ist nicht einverstanden mit den Priorit\u00e4ten von Pratt &#038; Whitney"},"content":{"rendered":"\n<p>Es geht langsamer aufw\u00e4rts: Airbus erwartet f\u00fcr die A320-Neo-Familie eine stabile Produktionsrate von 75 Flugzeugen pro Monat &#8211; nun aber erst nach 2027. Bis dahin peilt der europ\u00e4ische Flugzeugbauer eine Steigerung des Aussto\u00dfes auf 70 bis 75 Jets monatlich an.<\/p>\n<p>Verantwortlich macht Airbus den Triebwerksbauer Pratt &amp; Whitney. Er liefere nicht gen\u00fcgend Motoren f\u00fcr die neu produzierten Flugzeuge der A320-Neo-Familie. Bei der Pr\u00e4sentation der Jahreszahlen sagte Airbus-Chef Guillaume Faury am Donnerstag (19. Februar) in Toulouse, dass der Motorenbauer die zugesagten Liefermengen nicht einhalte. Und das werde die A320-Neo-Produktionsrate im Jahr 2026 beeintr\u00e4chtigen und in geringerem Ma\u00dfe auch noch 2027. Faury betonte, dass Pratt &amp; Whitney das zentrale Problem sei, w\u00e4hrend andere Zulieferer auf Kurs seien.<\/p>\n<p>Pratt &amp; Whitney legt Schwerpunkt auf aktive Flotte<\/p>\n<p>Faury sagte, Pratt &amp; Whitney habe seine Situation gegen\u00fcber Airbus erkl\u00e4rt. Der Triebwerksbauer habe darauf verwiesen, dass die Zahl der aktiven Flugzeuge, die bei Fluggesellschaften am Boden bleiben m\u00fcssten, nicht so stark gesunken sei wie geplant und erwartet.<\/p>\n<p>\u00abPratt &amp; Whitney m\u00f6chte einen Gro\u00dfteil seiner Mittel, seines Materials und seiner Triebwerke f\u00fcr die Unterst\u00fctzung der Flotte bereitstellen\u00bb, sagte Faury. Airbus sei mit dieser Priorisierung \u00absehr unzufrieden\u00bb und \u00abnicht einverstanden\u00bb. Der Triebwerksbauer m\u00fcsse seine Verpflichtungen f\u00fcr aktive und f\u00fcr neu gebaute Flugzeuge erf\u00fcllen, so der Airbus-Chef.<\/p>\n<p>\u00abWollen unsere vertraglichen Rechte durchsetzen\u00bb<\/p>\n<p>Derzeit laufen Gespr\u00e4che zwischen Airbus und Pratt &amp; Whitney. Faury erkl\u00e4rte, diese seien wichtig, damit der Flugzeugbauer Planungssicherheit f\u00fcr 2026 und 2027 bekomme.<\/p>\n<p>Der Airbus-Chef sagte, dass der Triebwerkshersteller seine vertraglichen Verpflichtungen derzeit nicht erf\u00fclle. \u00abWir wollen unsere vertraglichen Rechte durchsetzen\u00bb, so Faury. Daher habe man \u00abeinen Prozess gem\u00e4\u00df den vertraglichen Anforderungen f\u00fcr Streitf\u00e4lle eingeleitet\u00bb. Mehr k\u00f6nne er dazu derzeit nicht sagen. Klar sei aber, dass dies Zeit brauche.<\/p>\n<p>Von der Breaking News bis zur Hintergrundanalyse: Unser Team begleitet die Luftfahrt mit Erfahrung und Leidenschaft. Unterst\u00fctzen Sie unabh\u00e4ngigen Qualit\u00e4tsjournalismus \u2013 f\u00fcr weniger als einen Cappuccino im Monat. <a href=\"https:\/\/www.aerotelegraph.com\/insider\" id=\"529883fb-9a5b-4add-bdbf-6f575ebaa20b\" rel=\"nofollow noopener\" target=\"_blank\">Jetzt hier klicken und abonnieren<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Es geht langsamer aufw\u00e4rts: Airbus erwartet f\u00fcr die A320-Neo-Familie eine stabile Produktionsrate von 75 Flugzeugen pro Monat &#8211;&hellip;\n","protected":false},"author":2,"featured_media":11866,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[493,1753,57,46,52,51,53,56,5102,45,44,55,54],"class_list":{"0":"post-11865","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-unternehmen-maerkte","8":"tag-airbus","9":"tag-airbus-a320-neo","10":"tag-business","11":"tag-ch","12":"tag-companies","13":"tag-companies-markets","14":"tag-markets","15":"tag-maerkte","16":"tag-pratt_whitney","17":"tag-schweiz","18":"tag-switzerland","19":"tag-unternehmen","20":"tag-unternehmen-maerkte"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts\/11865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/comments?post=11865"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts\/11865\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/media\/11866"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/media?parent=11865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/categories?post=11865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/tags?post=11865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}