{"id":122222,"date":"2026-05-13T12:49:11","date_gmt":"2026-05-13T12:49:11","guid":{"rendered":"https:\/\/www.europesays.com\/ch-de\/122222\/"},"modified":"2026-05-13T12:49:11","modified_gmt":"2026-05-13T12:49:11","slug":"boy-george-blamiert-sich-fuer-san-marino","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-de\/122222\/","title":{"rendered":"Boy George blamiert sich f\u00fcr San Marino"},"content":{"rendered":"<p class=\"asmb-article-excerpt headline-single-article weight-500\">Warum San Marino scheiterte \u2013 trotz Superstar unter der Discokugel.<\/p>\n<p>Ein <a href=\"https:\/\/www.musikexpress.de\/pashanim-esc-boykott-3193865\/\" target=\"_blank\" rel=\"noopener nofollow\">ESC<\/a> mitten in der Stadt: Anders als etwa in der Arena-Zone von Liverpool 2023 muss heuer ein ganzes Viertel eingehegt werden. Vor dem verschachtelten Mehrzweck-Messehallen-Komplex namens Wiener Stadthalle patrouillieren auch fesche Polizistinnen in schwarzen Kampfwesten mit gelber R\u00fcckenaufschrift \u201eSocial Media\u201c. Austria kann modern.<\/p>\n<p>In der Halle selbst wird die Zeitmaschine angeworfen. Ein VIP namens <a href=\"https:\/\/www.musikexpress.de\/artists\/boy-george\/\" target=\"_blank\" rel=\"noopener nofollow\">Boy George<\/a> war eigens zur Opening Party am Wochenende angetreten. Im Rampenlicht w\u00e4hnt man sich dann in der Hochphase von MTV: Glitzer, Regenbogenfarben, Diskokugel-\u00c4sthetik und ein Popstar, dessen campe Superhits den UK-Pop der 1980er aufgemischt hatten.<\/p>\n<p>Gemeinsam mit der italienischen Pops\u00e4ngerin Senhit aus San Marino sollte die Culture-Club-Ikone den Zwergstaat ins Finale f\u00fchren. Der gro\u00dfe Coup blieb aus. Bereits im Halbfinale ist Schluss.<\/p>\n<p>Wochenlange Spekulationen um Boy Georges Auftritt<\/p>\n<p>Wochenlang wurde \u00fcber einen m\u00f6glichen ESC-Auftritt von George O\u2019Dowd (64) spekuliert, ehe sein Auftritt endg\u00fcltig best\u00e4tigt wurde. Anders als Flo Rida, der 2021 erst auf den letzten Dr\u00fccker in Marino-Mission eingeflogen wurde, ging George den gesamten Rehearsal-Parcours. Dieses Projekt wollte offenbar mehr sein als ein billiger Promo-Stunt.<\/p>\n<p>Und tats\u00e4chlich lieferte die Performance von \u201eSuperstar\u201c genau das, was ESC-Fans von dieser Kombi erwartet hatten: maximalen Camp-Faktor. Senhit funkelte im silbernen Jumpsuit wie eine wandelnde Diskokugel, George thronte in einem kristallartigen DJ-Pult, w\u00e4hrend Spiegelw\u00e4nde und Regenbogen-Lichter die Mehrzweckhalle in eine knallige Pride-Party verwandelten. Zum Ausklang marschierten beide \u00fcber den Catwalk, begleitet von massiver Pyrotechnik. Vergebliches Geballer.<\/p>\n<p>Am Ende durften zehn andere L\u00e4nder jubeln: Griechenland, der Favorit Finnland, Belgien, Schweden, Moldau, Israel, Serbien, Litauen, Kroatien und Polen schafften den Sprung ins gro\u00dfe Finale.<\/p>\n<p>An dieser Stelle findest du Inhalte aus Youtube<\/p>\n<p>Um mit Inhalten aus Sozialen Netzwerken zu interagieren oder diese darzustellen, brauchen wir deine Zustimmung.<\/p>\n<p>\tSoziale Netzwerke aktivieren<\/p>\n<p>Vicky Leandros, Victoria Swarovski und ein skurriler Klamauk-Moment<\/p>\n<p>Nach einer nostalgischen R\u00fcckschau auf 70 Jahre Songwettbewerb intonierte Chanson-Lady Vicky Leandros mit \u201eL\u2019amour est bleu\u201c ihren Retro-Hit in Funkelrobe. Das rote Gewand von Kristall-Erbin und Moderatorin Victoria Swarovski wurde vom Wiener Boulevard als \u201eGuckloch\u201c-Design abgeheftet, w\u00e4hrend Sidekick Michael Ostrowski den \u201eSchm\u00e4h\u201c-Part \u00fcbernahm.<\/p>\n<p>Besonders skurril wurde es bei einer Einlage gemeinsam mit Australiens Ex-Teilnehmer Go-Jo. Zwischen K\u00e4ngurus, Dirndl-Klischees und einer singenden Swarovski schwankte der Auftritt zwischen Klamauk und Fremdsch\u00e4merei, was f\u00fcr wilde Resonanz in den sozialen Netzwerken sorgte.<\/p>\n<p>\u00dcberraschung aus Griechenland, Geige aus Finnland<\/p>\n<p>Einer der \u00dcberraschungs-Acts kam aus Griechenland: Akylas mischte in \u201eFerto\u201c Techno, Rap und eine v\u00f6llig \u00fcberdrehte B\u00fchnenshow inklusive Katzenohren-Beanies. Manche Fans sehen darin bereits einen m\u00f6glichen ESC-Sieger.<\/p>\n<p>Ganz anders der Vorab-Favorit Finnland: Linda Lampenius und Pete Parkkonen lieferten mit \u201eLiekinheitin\u201c einen exaltierten Mix aus echter (!) Geige, Rock plus dem offenbar unverzichtbaren Feuerinferno.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.europesays.com\/ch-de\/wp-content\/uploads\/2026\/04\/me-badge-recommendation.png\" alt=\"Musikexpress Badge\"\/><\/p>\n<p>Empfehlungen der Redaktion<\/p>\n<p>Israel-Auftritt mit Zwischenrufen, Pro-Gaza-Demo zum Finale erwartet<\/p>\n<p>Der israelische S\u00e4nger Noam Bettan musste w\u00e4hrend seines Auftritts vereinzelt Zwischenrufe aus dem Publikum hinnehmen, zog seinen Stiefel aber souver\u00e4n durch. Im Vergleich zu den Wettbewerben im schwedischen Malm\u00f6 und in Basel hielten sich die Anti-Israel-Aktionen bislang in Grenzen. Gleichwohl wird zum Finale am Samstag eine gro\u00dfe Pro-Gaza-Demo erwartet.<\/p>\n<p>Und nat\u00fcrlich durfte auch der ganz gro\u00dfe Star-Moment des Abends nicht fehlen: Boy George verfranzte sich in der Retro-Schleife. Zu durchschaubar war das Spiel mit dem Legion\u00e4r aus London.<\/p>\n","protected":false},"excerpt":{"rendered":"Warum San Marino scheiterte \u2013 trotz Superstar unter der Discokugel. Ein ESC mitten in der Stadt: Anders als&hellip;\n","protected":false},"author":2,"featured_media":122019,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[30665,46,68,2091,9384,85,86,45,44,69],"class_list":{"0":"post-122222","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-musik","8":"tag-boy-george","9":"tag-ch","10":"tag-entertainment","11":"tag-esc","12":"tag-esc-2026","13":"tag-music","14":"tag-musik","15":"tag-schweiz","16":"tag-switzerland","17":"tag-unterhaltung"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_de\/116567346508366481","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts\/122222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/comments?post=122222"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts\/122222\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/media\/122019"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/media?parent=122222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/categories?post=122222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/tags?post=122222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}