{"id":19740,"date":"2026-02-25T11:07:08","date_gmt":"2026-02-25T11:07:08","guid":{"rendered":"https:\/\/www.europesays.com\/ch-de\/19740\/"},"modified":"2026-02-25T11:07:08","modified_gmt":"2026-02-25T11:07:08","slug":"aus-familienhaus-geholt-david-bowies-tochter-lexi-macht-ihren-eltern-schwere-vorwuerfe","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-de\/19740\/","title":{"rendered":"Aus Familienhaus geholt: David Bowies Tochter Lexi macht ihren Eltern schwere Vorw\u00fcrfe"},"content":{"rendered":"<p>Aus Familienhaus geholtDavid Bowies Tochter Lexi macht ihren Eltern schwere Vorw\u00fcrfe<\/p>\n<p>25.02.2026, 07:20 Uhr <\/p>\n<p>Artikel anh\u00f6ren(03:37 min)<\/p>\n<p><img decoding=\"async\" class=\"Image_img__fQCi0 Image_Img_16_9__4BLfH widget-picture-inline_maximizable__t_E7h\" loading=\"eager\" fetchpriority=\"high\" src=\"https:\/\/www.europesays.com\/ch-de\/wp-content\/uploads\/2026\/02\/David-Bowie-and-Iman-during-2005-CFDA-Fashion-Awards-Inside-the-Dinner-Green-Room-Departures-at-New-.webp\" alt=\"David-Bowie-and-Iman-during-2005-CFDA-Fashion-Awards-Inside-the-Dinner-Green-Room-Departures-at-New-York-Public-Library-in-New-York-City-New-York-United-States\"\/>David Bowie und seine Frau Iman bei einer Gala im Jahr 2005 in New York. (Foto: FilmMagic)TeilenFolgen auf:<a href=\"https:\/\/www.whatsapp.com\/channel\/0029Va5cdVJD8SDp5YZgYF01\" title=\"Auf WhatsApp folgen\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/www.n-tv.de\/socialIcons\/whatsapp.svg\" alt=\"whatsapp\" class=\"ArticleShare_icon__FsrC2\"\/><\/a><a href=\"https:\/\/news.google.com\/publications\/CAAiEPMdif5mpRNxiLOeUpHCwwsqFAgKIhDzHYn-ZqUTcYiznlKRwsML?hl=de&amp;gl=DE&amp;ceid=DE%3Ade\" title=\"Auf Google News folgen\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/www.n-tv.de\/socialIcons\/google.svg\" alt=\"whatsapp\" class=\"ArticleShare_icon__FsrC2\"\/><\/a><\/p>\n<p class=\"Typography_text-m__XI0da Typography_weight-bold__uT6mq storyline_lead_text_leadtext__q_wg8\">Sie ist das Kind zweier weltber\u00fchmter Eltern. Ihr Vater David Bowie ist ein Musikidol, ihre Mutter Iman war fr\u00fcher ein Supermodel. Nun spricht Alexandria &#171;Lexi&#187; Jones \u00fcber ein Kapitel ihrer Kindheit, an das sie keine guten Erinnerungen hat. <\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Es sind Schilderungen, die unter die Haut gehen. Alexandria &#171;Lexi&#187; Jones hat in einem Video auf Instagram \u00fcber ihre schwierige Jugend gesprochen und dabei Vorw\u00fcrfe gegen ihre ber\u00fchmten Eltern erhoben. Sie ist die gemeinsame Tochter von Musiklegende David Bowie, der 2016 starb, und dem fr\u00fcheren Supermodel Iman Abdulmajid. Die heute 25-J\u00e4hrige berichtet in dem Clip, wie sie mit 14 Jahren gegen ihren Willen aus dem Familienhaus geholt und in eine Therapieeinrichtung gebracht worden sei.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Lexi sprach offen \u00fcber ihre Kindheit mit zwei weltber\u00fchmten Eltern. Zwar sei sie dankbar f\u00fcr die M\u00f6glichkeiten gewesen, die ihr diese Konstellation er\u00f6ffnet habe &#8211; doch gleichzeitig habe sie nie gewusst, ob Menschen aus den richtigen Gr\u00fcnden ihre N\u00e4he suchten. Mit 14 Jahren habe sie mit Depressionen, einer Essst\u00f6rung und Drogenmissbrauch zu k\u00e4mpfen gehabt.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Als ihr Vater 2014 die Diagnose Leberkrebs erhielt, habe Lexi nach eigenen Angaben ihren Tiefpunkt erreicht. W\u00e4hrend Gleichaltrige in ihrem Umfeld aus Neugier mit Drogen und Alkohol experimentierten, sei ihr Konsum aus einer ganz anderen Motivation heraus entstanden. Sie habe nicht gefeiert, sondern sei vor ihrem Leben geflohen &#8211; vor ihren Gedanken und ihrer komplizierten Familie. Und sie habe allein getrunken und Drogen genommen, auch als f\u00fcr alle anderen die Party l\u00e4ngst vorbei gewesen sei.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Dann kam der Tag, der alles ver\u00e4nderte. Wie Lexi berichtet, habe ihr Vater ihr vor der Abholung einen Brief vorgelesen, dessen letzter Satz sich in ihr Ged\u00e4chtnis eingebrannt habe: &#171;Es tut mir leid, dass wir das tun m\u00fcssen.&#187; Zwei M\u00e4nner seien dann im Haus aufgetaucht und h\u00e4tten sie zun\u00e4chst in ein sogenanntes Wildnis-Therapieprogramm gebracht, wo sie 91 Tage verbrachte.<\/p>\n<p>Tod des Vaters aus der Ferne erlebt<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">In dem kontroversen Programm lebte sie im Winter drau\u00dfen, schlief unter Planen und lernte \u00dcberlebenstechniken. Nach den drei Monaten in der Wildnis wurde Lexi laut ihren Angaben in ein therapeutisches Internat in Utah verlegt, wo sie \u00fcber ein Jahr lang blieb. Dort erreichte sie auch die Nachricht, die ihr Leben f\u00fcr immer ver\u00e4ndern sollte: Am 10. Januar 2016 starb David Bowie im Alter von 69 Jahren an Leberkrebs. Zwei Tage zuvor, an seinem Geburtstag, hatte Lexi noch mit ihm telefoniert.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Besonders schmerzhaft sei f\u00fcr sie gewesen, in den Meldungen \u00fcber den Tod ihres Vaters zu lesen, er sei im Kreise seiner ganzen Familie gestorben. &#171;Ja, die ganze Familie war da. Au\u00dfer mir&#187;, so Lexi Jones in ihrem Video.<\/p>\n<p class=\"Typography_text-s__wu_cm Typography_weight-normal__pqUbH Typography_color-darkgrey__sZEnP article-detail-footer_source__KslPc\">Quelle: ntv.de, gut\/spot<\/p>\n","protected":false},"excerpt":{"rendered":"Aus Familienhaus geholtDavid Bowies Tochter Lexi macht ihren Eltern schwere Vorw\u00fcrfe 25.02.2026, 07:20 Uhr Artikel anh\u00f6ren(03:37 min) David&hellip;\n","protected":false},"author":2,"featured_media":19741,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[101,46,587,68,1845,1013,1056,102,45,44,69],"class_list":{"0":"post-19740","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-prominente","8":"tag-celebrities","9":"tag-ch","10":"tag-david-bowie","11":"tag-entertainment","12":"tag-familie","13":"tag-popmusik","14":"tag-promi-paare","15":"tag-prominente","16":"tag-schweiz","17":"tag-switzerland","18":"tag-unterhaltung"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts\/19740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/comments?post=19740"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts\/19740\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/media\/19741"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/media?parent=19740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/categories?post=19740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/tags?post=19740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}