{"id":42999,"date":"2026-03-14T10:05:06","date_gmt":"2026-03-14T10:05:06","guid":{"rendered":"https:\/\/www.europesays.com\/ch-de\/42999\/"},"modified":"2026-03-14T10:05:06","modified_gmt":"2026-03-14T10:05:06","slug":"scarlett-gartmann-schwangere-frau-von-marco-reus-meldet-sich-aus-klinik-sport","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-de\/42999\/","title":{"rendered":"Scarlett Gartmann: Schwangere Frau von Marco Reus meldet sich aus Klinik | Sport"},"content":{"rendered":"<p><a class=\"skip-content skip-content--link\" href=\"#in-content-skip-link-target-v-0-0\">TTS-Player \u00fcberspringen\u21b5<\/a><a id=\"in-content-skip-link-target-v-0-0\" class=\"skip-content--target-link-hidden skip-content skip-content--target-link\" href=\"#in-content-skip-link-target-v-0-0\">Artikel weiterlesen<\/a><\/p>\n<p>Schreck-Moment bei <a href=\"https:\/\/www.bild.de\/sport\/fussball\/ex-bvb-star-in-usa-3-baby-fuer-marco-reus-und-seine-scarlett-69a29d347c787f6a1cef1c54\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">Scarlett Gartmann<\/a> (32). Bei Instagram postete die schwangere Ehefrau von Fu\u00dfball-Star <a href=\"https:\/\/www.bild.de\/sport\/fussball\/ex-bvb-star-in-usa-3-baby-fuer-marco-reus-und-seine-scarlett-69a29d347c787f6a1cef1c54\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">Marco Reus<\/a> (36) ein Foto aus dem Krankenhaus. Nach einem schweren Reitunfall hatte sie kurzzeitig das Bewusstsein verloren \u2013 nun gibt sie erste Entwarnung.<\/p>\n<p>Vor zwei Tagen \u201ebin ich beim Aufsteigen schwer vom Pferd gefallen\u201c, schildert Gartmann auf Instagram. Genaue Erinnerungen habe sie nicht: \u201eDanach ist alles schwarz. Ich war sofort bewusstlos und kann mich an den Moment selbst gar nicht erinnern.\u201c<\/p>\n<p>Wie genau der Unfall passiert ist, wei\u00df die Reiterin gar nicht. Sie schreibt: \u201eVielleicht habe ich ihn am Schweif ber\u00fchrt oder bin irgendwo h\u00e4ngengeblieben. Auf jeden Fall ging er sofort mit allen Vieren hoch und weil ich noch nicht richtig im Sattel sa\u00df, lag ich im n\u00e4chsten Moment schon im Dreck.\u201c<\/p>\n<p>Scarlett Gartmann: Ehefrau von Marco Reus meldet sich aus Klinik<\/p>\n<p>Und dann das Wichtigste: \u201eWas am Ende aber wirklich z\u00e4hlt: Dem Baby und mir geht es gut. Ich bin direkt ins Krankenhaus gefahren und habe alles durchchecken lassen und zum Gl\u00fcck ist alles in Ordnung. Nur ein paar Prellungen und Sch\u00fcrfwunden.\u201c<\/p>\n<p> An dieser Stelle findest du Inhalte aus Instagram <\/p>\n<p> Um mit Inhalten aus Instagram und anderen sozialen Netzwerken zu interagieren oder diese darzustellen, brauchen wir deine Zustimmung. <\/p>\n<p> soziale Netzwerke aktivieren  Um eingebettete Inhalte anzuzeigen, ist Ihre jederzeit widerrufliche Einwilligung (\u00fcber den Schalter oder \u00fcber &#187; <a class=\"embed-placeholder__text-link\" href=\"#\" rel=\"noopener noreferrer\" title=\"Tracking widerrufen\"> Widerruf Tracking und Cookies<\/a> &#187; am Seitenende) zur Verarbeitung personenbezogener Daten n\u00f6tig.  Dabei k\u00f6nnen Daten in Drittl\u00e4nder wie die USA \u00fcbermittelt werden (Art. 49 Abs. 1 lit. a DSGVO). Mit dem Aktivieren des Inhalts stimmen Sie zu. Weitere Infos finden Sie <a class=\"embed-placeholder__text-link\" href=\"#\" rel=\"noopener noreferrer\" title=\"Zu den Privatsph\u00e4re Einstellungen\"> hier<\/a>. <\/p>\n<p>Allerdings: Die werdende Mutter, die ihr drittes Kind erwartet, hat eine klare Entscheidung getroffen: \u201eTrotzdem habe ich f\u00fcr mich entschieden, dass das jetzt erstmal eine Pause vom Reiten w\u00e4hrend der Schwangerschaft ist. Nicht f\u00fcr immer, aber f\u00fcr jetzt. Sicherheit geht einfach vor \u2013 f\u00fcr mein Baby und f\u00fcr mich.\u201c<\/p>\n<p>Der langj\u00e4hrige BVB-St\u00fcrmer Reus und seine Scarlett sind seit 2019 verheiratet und haben schon zwei gemeinsame T\u00f6chter. Seit August 2024 l\u00e4sst der Ex-Nationalspieler (48 L\u00e4nderspiele) seine Karriere in der US-Liga bei Los Angeles Galaxy ausklingen. In seiner ersten Saison konnte er mit dem Klub direkt den US-Titel gewinnen. Endlich die erste Meisterschaft seiner Karriere, die ihm in zw\u00f6lf Jahren bei Borussia Dortmund stets verwehrt geblieben war.<\/p>\n<p>Sein Vertrag in Los Angeles l\u00e4uft noch bis zum Ende dieses Jahres. Ob es danach weitergeht, ist noch offen. Fest steht: Am 3. Mai kommt es f\u00fcr Reus und seinen Klub noch mal zum Aufeinandertreffen mit seinem ehemaligen Nationalmannschaftskollegen Thomas M\u00fcller (36). Die Bayern-Legende spielt mittlerweile in derselben Liga bei den Vancouver Whitecaps.<\/p>\n","protected":false},"excerpt":{"rendered":"TTS-Player \u00fcberspringen\u21b5Artikel weiterlesen Schreck-Moment bei Scarlett Gartmann (32). Bei Instagram postete die schwangere Ehefrau von Fu\u00dfball-Star Marco Reus&hellip;\n","protected":false},"author":2,"featured_media":43000,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[101,46,68,181,13496,13495,102,13497,13494,1646,45,44,103,1345,69],"class_list":{"0":"post-42999","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-prominente","8":"tag-celebrities","9":"tag-ch","10":"tag-entertainment","11":"tag-fussball","12":"tag-los-angeles-galaxy","13":"tag-major-league-soccer","14":"tag-prominente","15":"tag-reiten","16":"tag-reus-marco","17":"tag-schwangerschaft","18":"tag-schweiz","19":"tag-switzerland","20":"tag-texttospeech","21":"tag-unfaelle","22":"tag-unterhaltung"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_de\/116226962727441252","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts\/42999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/comments?post=42999"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts\/42999\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/media\/43000"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/media?parent=42999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/categories?post=42999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/tags?post=42999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}