{"id":48482,"date":"2026-03-18T09:13:07","date_gmt":"2026-03-18T09:13:07","guid":{"rendered":"https:\/\/www.europesays.com\/ch-de\/48482\/"},"modified":"2026-03-18T09:13:07","modified_gmt":"2026-03-18T09:13:07","slug":"whatsapp-bereitet-multi-user-support-fuer-ios-vor","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-de\/48482\/","title":{"rendered":"Whatsapp bereitet Multi User Support f\u00fcr iOS vor"},"content":{"rendered":"<p><a href=\"https:\/\/www.itmagazine.ch\/unternehmen\/1617\/Whatsapp.html\" rel=\"nofollow noopener\" target=\"_blank\">Whatsapp<\/a> rollt das sogenannte Profile Tab f\u00fcr iOS aus. Der wichtigste Punkt an dieser \u00c4nderung: Damit soll unter anderem deutlich besser zu erkennen sein, mit welchem Account man gerade eingeloggt ist. Dies soll etwa mit einem grossen Header-Bild in den Einstellungen umgesetzt werden. Ausgetauscht werden kann dieses aktuell bisher nicht, es ist wohl zu erwarten, dass ein kommendes Update diese Option mit sich bringt. <\/p>\n<p>Wie &#171;WABetainfo&#187; <a href=\"https:\/\/wabetainfo.com\/whatsapp-is-widely-rolling-out-a-new-profile-tab-on-ios\/\" target=\"_blank\" rel=\"noopener nofollow\">schreibt<\/a>, sollte das als Vorbereitung auf die vermutlich bald folgende Unterst\u00fctzung von mehreren Accounts auf einem Ger\u00e4t sein. Sp\u00e4testens dann ist es zentral, dass der Nutzer Klarheit hat, f\u00fcr welchen seiner Accounts er gerade die Einstellungen ver\u00e4ndert. Das neue Profile Tab ersetzt die alten Einstellungen und soll neu unter dem Begriff &#171;You&#187; im Men\u00fc auftauchen. <\/p>\n<p>Das Update l\u00e4sst sich bereits aus dem App Store f\u00fcr iOS herunterladen. F\u00fcr manche Nutzer k\u00f6nnte das neue Profile Tab auch nach dem Update noch nicht verf\u00fcgbar sein, hier ist noch etwas Geduld gefragt, bis das Feature dann freigeschaltet wird.<br \/>(win)<\/p>\n","protected":false},"excerpt":{"rendered":"Whatsapp rollt das sogenannte Profile Tab f\u00fcr iOS aus. Der wichtigste Punkt an dieser \u00c4nderung: Damit soll unter&hellip;\n","protected":false},"author":2,"featured_media":48483,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[46,1080,5655,45,60,59,44,64,61,1884,63,62],"class_list":{"0":"post-48482","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-wissenschaft-technik","8":"tag-ch","9":"tag-kommunikation","10":"tag-messenger-dienste","11":"tag-schweiz","12":"tag-science","13":"tag-science-technology","14":"tag-switzerland","15":"tag-technik","16":"tag-technology","17":"tag-whatsapp","18":"tag-wissenschaft","19":"tag-wissenschaft-technik"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_de\/116249407554156729","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts\/48482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/comments?post=48482"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts\/48482\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/media\/48483"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/media?parent=48482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/categories?post=48482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/tags?post=48482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}