{"id":72478,"date":"2026-04-05T08:14:14","date_gmt":"2026-04-05T08:14:14","guid":{"rendered":"https:\/\/www.europesays.com\/ch-de\/72478\/"},"modified":"2026-04-05T08:14:14","modified_gmt":"2026-04-05T08:14:14","slug":"31-jahre-lang-war-ein-skandalfilm-auf-platz-1-der-erfolgreichsten-nicht-jugendfreien-filme-bis-er-von-einer-kino-legende-entthront-wurde","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-de\/72478\/","title":{"rendered":"31 Jahre lang war ein Skandalfilm auf Platz 1 der erfolgreichsten, nicht jugendfreien Filme, bis er von einer Kino-Legende entthront wurde"},"content":{"rendered":"<p>31 Jahre sind eine lange Zeit. Das gilt nat\u00fcrlich auch f\u00fcr das Filmgesch\u00e4ft. So lange hat es gedauert, bis <a data-ga-on=\"click,auxclick,contextmenu\" data-ga-event-category=\"Article\" data-ga-event-action=\"Internal Link Text\" data-ga-event-label=\"Click\" title=\"Der letzte Tango in Paris\" href=\"https:\/\/www.moviepilot.de\/movies\/der-letzte-tango-in-paris\" class=\"sc-6a922024-0 dZMhco mp_article_parsed_internal_link\" rel=\"nofollow noopener\" target=\"_blank\">Der letzte Tango in Paris<\/a> von einem anderen nicht jugendfreien Film vom Thron gesto\u00dfen wurde. Das hat die spanische Regie-Legende <a data-ga-on=\"click,auxclick,contextmenu\" data-ga-event-category=\"Article\" data-ga-event-action=\"Internal Link Text\" data-ga-event-label=\"Click\" title=\"Pedro Almod\u00f3var\" href=\"https:\/\/www.moviepilot.de\/people\/pedro-almodovar\" class=\"sc-6a922024-0 dZMhco mp_article_parsed_internal_link\" rel=\"nofollow noopener\" target=\"_blank\">Pedro Almod\u00f3var<\/a> mit seinem \u00fcberragenden <a data-ga-on=\"click,auxclick,contextmenu\" data-ga-event-category=\"Article\" data-ga-event-action=\"Internal Link Text\" data-ga-event-label=\"Click\" title=\"La Mala Educaci\u00f3n \u2013 Schlechte Erziehung\" href=\"https:\/\/www.moviepilot.de\/movies\/la-mala-educacion-schlechte-erziehung\" class=\"sc-6a922024-0 dZMhco mp_article_parsed_internal_link\" rel=\"nofollow noopener\" target=\"_blank\">La Mala Educaci\u00f3n \u2013 Schlechte Erziehung<\/a> geschafft. Allerdings gab es wenig sp\u00e4ter einen Film mit derselben Altersfreigabe, der sogar noch mehr Geld eingespielt hat.<\/p>\n<p>Der letzte Tango in Paris war 31 Jahre lang der erfolgreichste Film ohne Jugendfreigabe \u2013 bis La Mala Educaci\u00f3n kam<\/p>\n<p>Wenn wir uns bei <a href=\"https:\/\/www.boxofficemojo.com\/chart\/mpaa_title_lifetime_gross\/?area=XWW&amp;by_mpaa=NC-17&amp;ref_=bo_cso_ac\" data-ga-on=\"click,auxclick,contextmenu\" data-ga-event-category=\"Article\" data-ga-event-action=\"External Link Text\" data-ga-event-label=\"www.boxofficemojo.com\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" class=\"sc-b3b33791-1 lidfUl\">Box Office Mojo\u00a0<\/a> die Liste der Filme mit dem h\u00f6chsten Einspielergebnis nach MPA-Altersfreigabe sortiert<br \/>\n anschauen, liegt Der letzte Tango in Paris auf Platz 3. Er ist im Jahr<br \/>\n1973 erschienen und war ein echter Skandalstreifen aufgrund von expliziter Sexdarstellung und rohen Emotionen.<\/p>\n<p>Sp\u00e4ter wurde der Film scharf daf\u00fcr kritisiert, dass Hauptdarstellerin <a data-ga-on=\"click,auxclick,contextmenu\" data-ga-event-category=\"Article\" data-ga-event-action=\"Internal Link Text\" data-ga-event-label=\"Click\" title=\"Maria Schneider\" href=\"https:\/\/www.moviepilot.de\/people\/maria-schneider\" class=\"sc-6a922024-0 dZMhco mp_article_parsed_internal_link\" rel=\"nofollow noopener\" target=\"_blank\">Maria Schneider<\/a> eine Vergewaltigungs-Szene aufnehmen musste, \u00fcber deren gewaltvollen Ablauf sie im Gegensatz zum Regisseur <a data-ga-on=\"click,auxclick,contextmenu\" data-ga-event-category=\"Article\" data-ga-event-action=\"Internal Link Text\" data-ga-event-label=\"Click\" title=\"Bernardo Bertolucci\" href=\"https:\/\/www.moviepilot.de\/people\/bernardo-bertolucci\" class=\"sc-6a922024-0 dZMhco mp_article_parsed_internal_link\" rel=\"nofollow noopener\" target=\"_blank\">Bernardo Bertolucci<\/a> und Schauspielpartner <a data-ga-on=\"click,auxclick,contextmenu\" data-ga-event-category=\"Article\" data-ga-event-action=\"Internal Link Text\" data-ga-event-label=\"Click\" title=\"Marlon Brando\" href=\"https:\/\/www.moviepilot.de\/people\/marlon-brando\" class=\"sc-6a922024-0 dZMhco mp_article_parsed_internal_link\" rel=\"nofollow noopener\" target=\"_blank\">Marlon Brando<\/a> nicht Bescheid wusste. Dieser Missbrauch vor der Kamera traumatisierte die Schauspielerin.<\/p>\n<p>2004<br \/>\n startete dann La Mala Educaci\u00f3n im Kino und konnte das<br \/>\nEinspielergebnis von 36 Millionen US-Dollar noch einmal um vier<br \/>\nMillionen \u00fcbertreffen. Nach 31 Jahren gab es also einen neuen nicht<br \/>\njugendfreien Film, der Der letzte Tango in Paris in die Tasche stecken<br \/>\nkonnte.<\/p>\n<p>Kurioserweise hat La Mala Educaci\u00f3n in Deutschland aber eine FSK-Freigabe &#171;ab 12 Jahren&#187; verpasst bekommen, w\u00e4hrend beide Filme in den USA die h\u00f6chste Freigabestufe haben und ab 18 Jahren freigegeben sind.<\/p>\n<p><\/p>\n<p>Darum geht es in La Mala Educaci\u00f3n<\/p>\n<p>In Pedro Almod\u00f3vars<br \/>\nhochgelobtem Drama bekommen wir es mit einer verschachtelten Reise in<br \/>\ndie Vergangenheit zu tun. Er bedient erneut komplexe emotionale und sexuelle Themen, die ihn in den 90ern und 2000er Jahren zum Aush\u00e4ngeschild des moderenen, spanischen Kinos machten. <\/p>\n<p>In La Mala Educaci\u00f3n wird der erfolgreiche Regisseur Enrique wird von<br \/>\nseinem Jugendfreund Ignacio besucht. Das wirbelt alles kr\u00e4ftig<br \/>\ndurcheinander und rei\u00dft haufenweise alte Wunden wieder auf. <\/p>\n<p>Im<br \/>\nLauf der Zeit kristallisiert sich heraus, dass Ignacio und Enrique nicht<br \/>\n nur befreundet waren, als sie in jungen Jahren auf ein Kloster-Internat<br \/>\n gehen mussten, sondern auch  ihre ersten gemeinsamen Erfahrungen mit Intimit\u00e4t und Sexualit\u00e4t gemeinsam gemacht haben. Au\u00dferdem kam es in der Klosterschule auch zu sexuellem<br \/>\nMissbrauch und das Erlebte von damals strahlt immer noch in die<br \/>\nGegenwart aus.<\/p>\n<p>Bereits 2007 kam mit Gefahr und Begierde von Ang Lee ein weiterer Film mit der hohen US-Altersfreigabe<br \/>\nins Kino, der mit 67 Millionen nochmal deutlich mehr Geld in die<br \/>\nKassen der Filmemacher gesp\u00fclt hat. Die Zeit von La Mala Educaci\u00f3n an<br \/>\nder Spitze dieser Liste hat sich also gerade einmal auf drei Jahre<br \/>\nbelaufen.<\/p>\n","protected":false},"excerpt":{"rendered":"31 Jahre sind eine lange Zeit. Das gilt nat\u00fcrlich auch f\u00fcr das Filmgesch\u00e4ft. So lange hat es gedauert,&hellip;\n","protected":false},"author":2,"featured_media":72479,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[20434,20435,14962,46,71,1027,68,9233,8157,2729,72,20436,70,1018,45,20433,20432,3039,44,69,3932],"class_list":{"0":"post-72478","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-kino","8":"tag-20434","9":"tag-20435","10":"tag-14962","11":"tag-ch","12":"tag-cinema","13":"tag-drama","14":"tag-entertainment","15":"tag-erotikfilm","16":"tag-gegenwart","17":"tag-hart","18":"tag-kino","19":"tag-kloster","20":"tag-movie","21":"tag-paris","22":"tag-schweiz","23":"tag-sexuelle-begierde","24":"tag-sexuelle-identitaet","25":"tag-sexueller-missbrauch","26":"tag-switzerland","27":"tag-unterhaltung","28":"tag-vergewaltigung"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_de\/116351097558814604","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts\/72478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/comments?post=72478"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts\/72478\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/media\/72479"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/media?parent=72478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/categories?post=72478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/tags?post=72478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}