{"id":78119,"date":"2026-04-09T21:01:50","date_gmt":"2026-04-09T21:01:50","guid":{"rendered":"https:\/\/www.europesays.com\/ch-de\/78119\/"},"modified":"2026-04-09T21:01:50","modified_gmt":"2026-04-09T21:01:50","slug":"us-finanzminister-bessent-draengt-senat-zur-verabschiedung-des-clarity-act","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-de\/78119\/","title":{"rendered":"US-Finanzminister Bessent dr\u00e4ngt Senat zur Verabschiedung des CLARITY Act"},"content":{"rendered":"<p>US-Finanzminister Scott Bessent fordert den Senat auf, den CLARITY Act noch vor dem Sommer zu verabschieden. In einem Op-Ed im Wall Street Journal schrieb er: Regulatorische Unklarheit habe Krypto-Entwicklung an Standorte mit klaren Regeln getrieben. Die CLARITY Act Krypto-Regulierung sei \u00fcberf\u00e4llig.<\/p>\n<p>Bessent formulierte ungew\u00f6hnlich direkt: Die Vorteile einer Ans\u00e4ssigkeit in den USA h\u00e4tten die Risiken f\u00fcr Krypto-Unternehmen selten \u00fcberwogen. Wirtschaftliche Sicherheit sei direkt mit nationaler Sicherheit verkn\u00fcpft. Damit stellt der Finanzminister die Krypto-Regulierung explizit in einen geopolitischen Kontext.<\/p>\n<p>CLARITY Act: Drei-Tier-System f\u00fcr digitale Assets<\/p>\n<p>House Financial Services Chairman French Hill brachte den CLARITY Act (H.R. 3633) am 29. Mai 2025 ein. Am 17. Juli verabschiedete das Repr\u00e4sentantenhaus das Gesetz mit 294 zu 134 Stimmen &#8211; eine \u00fcberparteiliche Mehrheit, erzielt w\u00e4hrend der sogenannten &#171;Crypto Week&#187; im Kongress.<\/p>\n<p>Im Kern etabliert das Gesetz ein Drei-Tier-Klassifikationssystem f\u00fcr digitale Assets. Es teilt die Aufsicht zwischen SEC und CFTC auf. Die CFTC erh\u00e4lt exklusive Jurisdiktion \u00fcber Spotm\u00e4rkte f\u00fcr digitale Rohstoffe, die SEC beh\u00e4lt die Aufsicht \u00fcber &#171;Investment Contract Assets&#187;. Neue Registrierungspflichten f\u00fcr digitale Rohstoffb\u00f6rsen, Broker-Dealer und Verwahrstellen kommen hinzu. Der jahrelange Jurisdiktionsstreit zwischen den beiden Beh\u00f6rden gilt als eines der gr\u00f6ssten Hindernisse f\u00fcr institutionelles Krypto-Engagement in den USA.<\/p>\n<p>Das Gesetz erg\u00e4nzt den bereits im Juli 2025 unterzeichneten <a href=\"https:\/\/cvj.ch\/glossary\/genius-act\/\" rel=\"nofollow noopener\" target=\"_blank\">GENIUS Act<\/a>, der 1:1-Reserve-Anforderungen f\u00fcr Stablecoins festlegt. Zusammen bilden die beiden Gesetze das regulatorische Fundament der Trump-Administration f\u00fcr digitale Assets.<\/p>\n<p>Stablecoin-Zinsen als Kernkonflikt im Senat<\/p>\n<p>Im Senat <a href=\"https:\/\/cvj.ch\/fokus\/legal-compliance\/clarity-act-bankenlobby-blockiert-das-wichtigste-krypto-gesetz-der-usa\/\" rel=\"nofollow noopener\" target=\"_blank\">steckt der CLARITY Act seit Monaten fest<\/a>. Der Hauptstreitpunkt ist, ob Krypto-Firmen wie Coinbase Zinsen auf Stablecoins anbieten d\u00fcrfen. JPMorgan und Bank of America warnten vor einem Verlust von bis zu 6.6 Billionen USD an Bankeinlagen, sollte eine solche Regelung kommen.<\/p>\n<p>Die Zahlen sprechen allerdings eine andere Sprache. Am 8. April ver\u00f6ffentlichte der White House Council of Economic Advisers eine Analyse, die das Banken-Argument entkr\u00e4ftet. Demnach w\u00fcrde ein Verbot von Stablecoin-Zinsen Bankenkredite um lediglich 2.1 Milliarden USD erh\u00f6hen &#8211; das entspricht 0.02 Prozent. Community Banks h\u00e4tten praktisch keinen Nutzen. Gleichzeitig beziffert die Studie den Wohlfahrtsverlust f\u00fcr Konsumenten auf 800 Millionen USD. Die Stablecoin-Reserven verblieben ohnehin mehrheitlich im Bankensystem.<\/p>\n<p>Auff\u00e4llig ist die Positionierung des Weissen Hauses. Pr\u00e4sident Trump <a href=\"https:\/\/cvj.ch\/fokus\/legal-compliance\/clarity-act-trump-warnt-banken-vor-blockade-seiner-krypto-agenda\/\" rel=\"nofollow noopener\" target=\"_blank\">stellte sich bereits Anfang M\u00e4rz \u00f6ffentlich auf die Seite der Krypto-Industrie gegen die Grossbanken<\/a>. Die CEA-Studie liefert nun die \u00f6konomische Munition f\u00fcr diese Haltung. Inzwischen gibt es einen Kompromiss der Senatoren Thom Tillis und Angela Alsobrooks vom 20. M\u00e4rz: Passive Stablecoin-Zinsen bleiben verboten. Aktivit\u00e4tsbasierte Belohnungen f\u00fcr Zahlungen, Transfers und Plattformnutzung sind hingegen erlaubt.<\/p>\n<p>Senats-Blockade und verschobene Markups<\/p>\n<p>Die legislative Geschichte im Senat liest sich als Serie von Verz\u00f6gerungen. Bereits im Juli 2025 ver\u00f6ffentlichten Senator Tim Scott und Cynthia Lummis einen Diskussionsentwurf. Im September folgte ein 182-seitiger Entwurf des Responsible Financial Innovation Act. David Sacks, White-House-Berater f\u00fcr Krypto und KI, k\u00fcndigte daraufhin im Dezember 2025 ein Senate Markup f\u00fcr Januar 2026 an. Das Banking Committee verschob es am geplanten Tag.<\/p>\n<p>Im Februar 2026 trat Bessent vor das Senate Banking Committee. Dort nannte er Gegner innerhalb der Industrie eine &#171;nihilistische Gruppe, die keine Regulierung dieser sehr guten Regulierung vorzieht&#187;. Wer das Gesetz nicht wolle, solle nach El Salvador ziehen. Diplomatisch war das nicht. Aber es signalisierte, wie ernst die Administration den Zeitplan nimmt. Laut Verhandlungsf\u00fchrern ist der Stablecoin-Zinsstreit &#171;zu 99 Prozent gel\u00f6st&#187;. Senate Republicans erw\u00e4gen nun aber, Deregulierungs-Bestimmungen f\u00fcr Community Banks an den CLARITY Act zu kn\u00fcpfen. Ein neuer Stolperstein.<\/p>\n<p>Schliessendes Zeitfenster vor den Midterms<\/p>\n<p>Was dabei untergeht: Der politische Kalender arbeitet gegen den CLARITY Act. Senator Bernie Moreno warnte, ohne Fortschritte bis Mai werde der Kongress digitale Asset-Gesetzgebung wom\u00f6glich jahrelang nicht mehr anfassen. Die Midterm-Wahlen 2026 verengen das Gesetzgebungsfenster zus\u00e4tzlich. Das f\u00fcr Ende April geplante Senate Banking Committee Markup wird damit zum entscheidenden Termin.<\/p>\n<p>Die Dynamik im Kongress bleibt dennoch komplex. Cynthia Lummis, eine der prominentesten Krypto-Bef\u00fcrworterinnen im Senat, \u00e4usserte sich nach einer geschlossenen GOP-Sitzung ern\u00fcchtert. Der Weg vorw\u00e4rts sei &#171;nicht jener, den sie erwartet hatte&#187;. Trotz breiter Unterst\u00fctzung im Repr\u00e4sentantenhaus bleibt die Senatspassage der schwierigste Schritt.<\/p>\n<p>F\u00fcr die Krypto-Industrie steht viel auf dem Spiel. Der CLARITY Act w\u00fcrde erstmals klare Zust\u00e4ndigkeiten zwischen SEC und CFTC schaffen und die \u00c4ra der &#171;Regulation by Enforcement&#187; unter dem fr\u00fcheren SEC-Chef Gary Gensler beenden. JPMorgan-Analysten bezeichnen eine Verabschiedung bis Mitte 2026 als positiven Katalysator f\u00fcr institutionelles Scaling und Tokenisierung. Dieselben Grossbanken, die Stablecoin-Zinsen aktiv bek\u00e4mpfen, stehen als potenzielle Nutzniesser der neuen Krypto-Custody-Regeln bereit.<\/p>\n","protected":false},"excerpt":{"rendered":"US-Finanzminister Scott Bessent fordert den Senat auf, den CLARITY Act noch vor dem Sommer zu verabschieden. In einem&hellip;\n","protected":false},"author":2,"featured_media":78120,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[57,21895,46,5935,52,51,53,56,45,21896,5936,44,55,54,6046],"class_list":{"0":"post-78119","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-unternehmen-maerkte","8":"tag-business","9":"tag-cftc","10":"tag-ch","11":"tag-clarity-act","12":"tag-companies","13":"tag-companies-markets","14":"tag-markets","15":"tag-maerkte","16":"tag-schweiz","17":"tag-sec","18":"tag-stablecoin","19":"tag-switzerland","20":"tag-unternehmen","21":"tag-unternehmen-maerkte","22":"tag-us-kongress"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_de\/116376765164294725","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts\/78119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/comments?post=78119"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts\/78119\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/media\/78120"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/media?parent=78119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/categories?post=78119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/tags?post=78119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}