{"id":82173,"date":"2026-04-14T07:40:11","date_gmt":"2026-04-14T07:40:11","guid":{"rendered":"https:\/\/www.europesays.com\/ch-de\/82173\/"},"modified":"2026-04-14T07:40:11","modified_gmt":"2026-04-14T07:40:11","slug":"coachella-superstars-und-superreiche-feiern-inkognito","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-de\/82173\/","title":{"rendered":"Coachella: Superstars und Superreiche feiern inkognito"},"content":{"rendered":"<p class=\"tracking-tight font-semibold text-base\" q:key=\"O8_0\">Zahlreiche Stars feiern jedes Jahr am Coachella-Musikfestival. Diesmal mit dabei? Katy Perry und Justin Trudeau. Auch Kim Kardashian zeigt sich mit ihrem Lover.<\/p>\n<p><img onload=\"this.style.backgroundColor = ''\" loading=\"eager\" fetchpriority=\"high\" decoding=\"sync\" height=\"450\" alt=\"Katy Perry\" width=\"900\"  style=\"aspect-ratio:2;object-fit:cover;background-color:#60565E\"  src=\"https:\/\/www.europesays.com\/ch-de\/wp-content\/uploads\/2026\/04\/1776152411_89_katy-perry.jpg\" class=\"rounded-xl mx-auto\" on:load=\"q-Bumj2Yqw.js#s_pVFDuJsFGxQ\"\/>Katy Perry und der fr\u00fchere kanadische Premier sind ein Paar. Am Coachella feiern sie wie zwei Normalos. &#8211; Instagram\/katyperry<\/p>\n<p>Das Wichtigste in K\u00fcrze<\/p>\n<p>Katy Perry und Justin Trudeau genossen am Coachella Zeit zu zweit.<\/p>\n<p>Auch Kim Kardashian und Lewis Hamilton mischten sich unter die Leute.<\/p>\n<p>Die Turteltauben versuchten (vergeblich) unerkannt zu bleiben.<\/p>\n<p preventdefault:click=\"\" lang=\"de\" class=\"text-base hyphens-auto\" on:click=\"q-B5MhqGdh.js#s_Dola2XqN0FU[0 1]\" q:key=\"YR_0\" q:id=\"87\">Hier werden Superstars und Superreiche zu Normalos! Das Coachella-Musikfestival in Kalifornien (USA) zieht jedes Jahr <a href=\"https:\/\/www.nau.ch\/people\/welt\/sabrina-carpenter-sorgt-bei-coachella-mit-fan-reaktion-fur-wirbel-67116884\" rel=\"nofollow noopener\" target=\"_blank\">tausende Besucherinnern<\/a> und Besucher aus aller Welt an.<\/p>\n<p preventdefault:click=\"\" lang=\"de\" class=\"text-base hyphens-auto\" on:click=\"q-B5MhqGdh.js#s_Dola2XqN0FU[0 1]\" q:key=\"YR_0\" q:id=\"89\">Und w\u00e4hrend einige von ihnen auf <a href=\"https:\/\/www.nau.ch\/people\/welt\/diese-promis-sorgen-mit-ihren-coachella-outfits-fur-aufsehen-66963967\" rel=\"nofollow noopener\" target=\"_blank\">extravagante Outfits<\/a> setzen, m\u00f6gen es andere lieber unauff\u00e4llig. So etwa <a href=\"https:\/\/www.nau.ch\/people\/katy-perry\" rel=\"nofollow noopener\" target=\"_blank\">Katy Perry<\/a> (41) und <a href=\"https:\/\/www.nau.ch\/politik\/justin-trudeau\" rel=\"nofollow noopener\" target=\"_blank\">Justin Trudeau<\/a> (54).<\/p>\n<p>Diese Stars feiern wie Normalos<\/p>\n<p preventdefault:click=\"\" lang=\"de\" class=\"text-base hyphens-auto\" on:click=\"q-B5MhqGdh.js#s_Dola2XqN0FU[0 1]\" q:key=\"YR_0\" q:id=\"8b\">Die S\u00e4ngerin und der ehemalige kanadische Premier (400 Mio. und 90 Mio. Verm\u00f6gen) machten im vergangenen Jahr ihre Beziehung \u00f6ffentlich. Nun zeigten sie sich zusammen am Festival \u2013 und zwar beinahe im Partnerlook!<\/p>\n<p><img onload=\"this.style.backgroundColor = ''\" loading=\"lazy\" decoding=\"async\" height=\"900\" alt=\"Na, h\u00e4ttest du diese Stars auf dem Gel\u00e4nde erkannt?\" width=\"900\"  style=\"aspect-ratio:1;object-fit:contain;background-color:#3D4347\"  src=\"https:\/\/www.europesays.com\/ch-de\/wp-content\/uploads\/2026\/04\/1776152411_610_katy-perry.jpg\" class=\"\u2b50\ufe0fkw1va4-1 mx-auto\" on:load=\"q-Bumj2Yqw.js#s_pVFDuJsFGxQ\"\/>Na, h\u00e4ttest du diese Stars auf dem Gel\u00e4nde erkannt? &#8211; Instagram\/katyperry<img onload=\"this.style.backgroundColor = ''\" loading=\"lazy\" decoding=\"async\" height=\"900\" alt=\"Die S\u00e4ngerin g\u00f6nnt sich etwas zu trinken.\" width=\"900\"  style=\"aspect-ratio:1;object-fit:contain;background-color:#0C6E8F\"  src=\"https:\/\/www.europesays.com\/ch-de\/wp-content\/uploads\/2026\/04\/1776152411_128_katy-perry.jpg\" class=\"\u2b50\ufe0fkw1va4-1 mx-auto\" on:load=\"q-Bumj2Yqw.js#s_pVFDuJsFGxQ\"\/>Die S\u00e4ngerin g\u00f6nnt sich etwas zu trinken. &#8211; Instagram\/katyperry<img onload=\"this.style.backgroundColor = ''\" loading=\"lazy\" decoding=\"async\" height=\"900\" alt=\"Der fr\u00fchere kanadische Premier zeigt sich ganz l\u00e4ssig.\" width=\"900\"  style=\"aspect-ratio:1;object-fit:contain;background-color:#820C0C\"  src=\"https:\/\/www.europesays.com\/ch-de\/wp-content\/uploads\/2026\/04\/justin-trudea-u.jpg\" class=\"\u2b50\ufe0fkw1va4-1 mx-auto\" on:load=\"q-Bumj2Yqw.js#s_pVFDuJsFGxQ\"\/>Der fr\u00fchere kanadische Premier zeigt sich ganz l\u00e4ssig. &#8211; Instagram\/katyperry<\/p>\n<p preventdefault:click=\"\" lang=\"de\" class=\"text-base hyphens-auto\" on:click=\"q-B5MhqGdh.js#s_Dola2XqN0FU[0 1]\" q:key=\"YR_0\" q:id=\"8i\">In weissen T-Shirts spazieren sie Hand in Hand \u00fcbers Gel\u00e4nde, wie die S\u00e4ngerin selbst auf <a href=\"https:\/\/www.nau.ch\/news\/instagram\" rel=\"nofollow noopener\" target=\"_blank\">Instagram<\/a> zeigt. Perry tr\u00e4gt Shorts und Stiefel, Trudeau setzt auf blaue Jeans und Sneaker. Seinen l\u00e4ssigen Look rundet der 54-J\u00e4hrige mit einem Baseball-K\u00e4ppi ab, das er verkehrt herum tr\u00e4gt.<\/p>\n<p preventdefault:click=\"\" lang=\"de\" class=\"text-base hyphens-auto\" on:click=\"q-B5MhqGdh.js#s_Dola2XqN0FU[0 1]\" q:key=\"YR_0\" q:id=\"8k\">Auf einem weiteren Schnappschuss sind die beiden mit roten Bechern in der Hand zu sehen. Der Inhalt? Unbekannt. Trudeau g\u00f6nnt sich zudem eine Portion Ramen-Nudeln aus dem Karton.<\/p>\n<p>Warst du schon mal am Coachella?<\/p>\n<p>1Ja.<\/p>\n<p>2Nein, aber ich m\u00f6chte unbedingt mal gehen!<\/p>\n<p>3Nein, nicht meine Musik.<\/p>\n<p preventdefault:click=\"\" lang=\"de\" class=\"text-base hyphens-auto\" on:click=\"q-B5MhqGdh.js#s_Dola2XqN0FU[0 1]\" q:key=\"YR_0\" q:id=\"8w\">Auch Topmodel Miranda Kerr (42) und ihr Ehemann Evan <a href=\"https:\/\/www.nau.ch\/news\/spiegel\" rel=\"nofollow noopener\" target=\"_blank\">Spiegel<\/a> (35, 60 Mio. und 2,5 Milliarden Verm\u00f6gen) statteten dem <a href=\"https:\/\/www.nau.ch\/people\/welt\/justin-bieber-pragt-coachella-mit-comeback-und-kontroverse-67116908\" rel=\"nofollow noopener\" target=\"_blank\">Coachella-Festival<\/a> gemeinsam einen Besuch ab. W\u00e4hrend letzterer im Inkognito-Look unterwegs war \u2013 mit K\u00e4ppi und Sonnenbrille \u2013 war Kerr sofort zu erkennen.<\/p>\n<p><img onload=\"this.style.backgroundColor = ''\" loading=\"lazy\" decoding=\"async\" height=\"1200\" alt=\"Miranda Kerr\" width=\"900\"  style=\"aspect-ratio:1.3333333333333333;object-fit:contain\"  src=\"https:\/\/www.europesays.com\/ch-de\/wp-content\/uploads\/2026\/04\/miranda-kerr.jpg\" class=\"rounded-xl mx-auto\" on:load=\"q-Bumj2Yqw.js#s_pVFDuJsFGxQ\"\/>Miranda Kerr strahlt beim Coachella-Festival. Ehemann Evan ist kaum zu erkennen. &#8211; Instagram\/mirandakerr<\/p>\n<p preventdefault:click=\"\" lang=\"de\" class=\"text-base hyphens-auto\" on:click=\"q-B5MhqGdh.js#s_Dola2XqN0FU[0 1]\" q:key=\"YR_0\" q:id=\"91\">Auf einem <a href=\"https:\/\/www.nau.ch\/news\/selfie\" rel=\"nofollow noopener\" target=\"_blank\">Selfie<\/a> strahlen sie zusammen in die Kameralinse.<\/p>\n<p preventdefault:click=\"\" lang=\"de\" class=\"text-base hyphens-auto\" on:click=\"q-B5MhqGdh.js#s_Dola2XqN0FU[0 1]\" q:key=\"YR_0\" q:id=\"93\"><a href=\"https:\/\/www.nau.ch\/people\/kim-kardashian\" rel=\"nofollow noopener\" target=\"_blank\">Kim Kardashian<\/a> (45, 1,2 Milliarden Verm\u00f6gen) liess sich das musikalische Spektakel ebenfalls nicht entgehen. Die Reality-<a href=\"https:\/\/www.nau.ch\/people\/queen\" rel=\"nofollow noopener\" target=\"_blank\">Queen<\/a> erschien zusammen mit ihm: <a href=\"https:\/\/www.nau.ch\/sport\/lewis-hamilton\" rel=\"nofollow noopener\" target=\"_blank\">Lewis Hamilton<\/a> (41, 300 Mio. Verm\u00f6gen).<\/p>\n<p preventdefault:click=\"\" lang=\"de\" class=\"text-base hyphens-auto\" on:click=\"q-B5MhqGdh.js#s_Dola2XqN0FU[0 1]\" q:key=\"YR_0\" q:id=\"95\">Die beiden wurden zuletzt immer mal wieder gemeinsam gesichtet. Berichten zufolge soll es zwischen der 45-J\u00e4hrigen und dem Formel-1-Star gefunkt haben!<\/p>\n<p>Kim Kardashian und Lewis Hamilton im Inkognito-Look<\/p>\n<p preventdefault:click=\"\" lang=\"de\" class=\"text-base hyphens-auto\" on:click=\"q-B5MhqGdh.js#s_Dola2XqN0FU[0 1]\" q:key=\"YR_0\" q:id=\"97\">Am Coachella versuchten die Turteltauben nun wohl unerkannt zu bleiben. Kim zeigte sich vermummt mit einer Kopfbedeckung. Nur ihre Augen waren zu sehen. Und auch der Rennfahrer versteckte sein Gesicht hinter Bandana, K\u00e4ppi, Kapuze und Sonnenbrille.<\/p>\n<p preventdefault:click=\"\" lang=\"de\" class=\"text-base hyphens-auto\" on:click=\"q-B5MhqGdh.js#s_Dola2XqN0FU[0 1]\" q:key=\"YR_0\" q:id=\"9e\">Trotz der Inkognito-Outfits wurden die beiden aber abgelichtet. Ob Kims sexy Look sie verraten hat?<\/p>\n<p><img onload=\"this.style.backgroundColor = ''\" loading=\"lazy\" decoding=\"async\" height=\"1125\" alt=\"Kim Kardashian Lewis Hamilton\" width=\"900\"  style=\"aspect-ratio:1.3333333333333333;object-fit:contain\"  src=\"https:\/\/www.europesays.com\/ch-de\/wp-content\/uploads\/2026\/04\/kim-kardashian-lewis-hamilton.jpg\" class=\"rounded-xl mx-auto\" on:load=\"q-Bumj2Yqw.js#s_pVFDuJsFGxQ\"\/>Lewis Hamilton und Kim Kardashian zusammen am Coachella. &#8211; Dukas<\/p>\n<p preventdefault:click=\"\" lang=\"de\" class=\"text-base hyphens-auto\" on:click=\"q-B5MhqGdh.js#s_Dola2XqN0FU[0 1]\" q:key=\"YR_0\" q:id=\"9j\">Im Gegensatz zu ihrem Gesicht war sie untenrum n\u00e4mlich deutlich freiz\u00fcgiger gekleidet. Die vierfache Mama trug ein schwarzes Top mit XL-Ausschnitt.<\/p>\n<p>Coachella: Foodst\u00e4nde leer wegen Ozempic?<\/p>\n<p preventdefault:click=\"\" lang=\"de\" class=\"text-base hyphens-auto\" on:click=\"q-B5MhqGdh.js#s_Dola2XqN0FU[0 1]\" q:key=\"YR_0\" q:id=\"9l\">Das Coachella-Festival sorgt aber nicht nur wegen des Starauflaufs immer wieder f\u00fcr Schlagzeilen. Sondern auch wegen den hohen Preisen. F\u00fcr Getr\u00e4nke und Essen muss man hier eine ganze Stange Geld hinbl\u00e4ttern.<\/p>\n<p preventdefault:click=\"\" lang=\"de\" class=\"text-base hyphens-auto\" on:click=\"q-B5MhqGdh.js#s_Dola2XqN0FU[0 1]\" q:key=\"YR_0\" q:id=\"9n\">Ob die Foodst\u00e4nde deshalb nun an einigen Tagen fast komplett leer standen? Ein Influencer auf <a href=\"https:\/\/www.nau.ch\/news\/instagram\" rel=\"nofollow noopener\" target=\"_blank\">Instagram<\/a> hat eine andere Vermutung. Er glaubt: Alle nehmen Ozempic \u2013 und haben darum keinen Hunger!<\/p>\n<p><img onload=\"this.style.backgroundColor = ''\" loading=\"lazy\" decoding=\"async\" height=\"782.608695652174\" alt=\"Vor den Foodtrucks am Coachella bilden sich keine Schlangen.\" width=\"900\"  style=\"aspect-ratio:1.15;object-fit:contain;background-color:#B3B4B7\"  src=\"https:\/\/www.europesays.com\/ch-de\/wp-content\/uploads\/2026\/04\/coachella.jpg\" class=\"\u2b50\ufe0fkw1va4-1 mx-auto\" on:load=\"q-Bumj2Yqw.js#s_pVFDuJsFGxQ\"\/>Vor den Foodtrucks am Coachella bilden sich keine Schlangen. &#8211; Instagram<img onload=\"this.style.backgroundColor = ''\" loading=\"lazy\" decoding=\"async\" height=\"782.608695652174\" alt=\"Ein Influencer vermutet: Niemand will essen, weil alle auf Ozempic sind.\" width=\"900\"  style=\"aspect-ratio:1.15;object-fit:contain;background-color:#B4BBC1\"  src=\"https:\/\/www.europesays.com\/ch-de\/wp-content\/uploads\/2026\/04\/1776152411_328_coachella.jpg\" class=\"\u2b50\ufe0fkw1va4-1 mx-auto\" on:load=\"q-Bumj2Yqw.js#s_pVFDuJsFGxQ\"\/>Ein Influencer vermutet: Niemand will essen, weil alle auf Ozempic sind. &#8211; Instagram<\/p>\n<p preventdefault:click=\"\" lang=\"de\" class=\"text-base hyphens-auto\" on:click=\"q-B5MhqGdh.js#s_Dola2XqN0FU[0 1]\" q:key=\"YR_0\" q:id=\"9u\">Bei Ozempic handelt es sich um ein Medikament, welches bei Typ-2-Diabetes angewendet wird. Es ist jedoch auch ein Appetitz\u00fcgler und wird von zum <a href=\"https:\/\/www.nau.ch\/news\/abnehmen\" rel=\"nofollow noopener\" target=\"_blank\">Abnehmen<\/a> genutzt. Insbesondere bei Stars ist die Abnehmspritze beliebt.<\/p>\n","protected":false},"excerpt":{"rendered":"Zahlreiche Stars feiern jedes Jahr am Coachella-Musikfestival. Diesmal mit dabei? Katy Perry und Justin Trudeau. Auch Kim Kardashian&hellip;\n","protected":false},"author":2,"featured_media":82174,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[101,46,22505,68,1125,1058,8145,13898,22950,11262,102,45,1265,44,69],"class_list":{"0":"post-82173","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-prominente","8":"tag-celebrities","9":"tag-ch","10":"tag-coachella","11":"tag-entertainment","12":"tag-justin-trudeau","13":"tag-katy-perry","14":"tag-kim-kardashian","15":"tag-lewis-hamilton","16":"tag-miranda-kerr","17":"tag-musikfestival","18":"tag-prominente","19":"tag-schweiz","20":"tag-stars","21":"tag-switzerland","22":"tag-unterhaltung"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_de\/116401924515205532","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts\/82173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/comments?post=82173"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts\/82173\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/media\/82174"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/media?parent=82173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/categories?post=82173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/tags?post=82173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}