{"id":85553,"date":"2026-04-16T15:05:09","date_gmt":"2026-04-16T15:05:09","guid":{"rendered":"https:\/\/www.europesays.com\/ch-de\/85553\/"},"modified":"2026-04-16T15:05:09","modified_gmt":"2026-04-16T15:05:09","slug":"ex-dsds-kandidat-cosimo-citiolo-packt-ueber-seine-finanzen-aus","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-de\/85553\/","title":{"rendered":"Ex-DSDS-Kandidat Cosimo Citiolo packt \u00fcber seine Finanzen aus"},"content":{"rendered":"<p>&#171;Das Leben ist teuer&#187; <\/p>\n<p>Cosimo Citiolo packt \u00fcber seine Finanzen aus<\/p>\n<p>16.04.2026 &#8211; 13:08 UhrLesedauer: 1 Min.<\/p>\n<p><a href=\"#focus-0\" class=\"transition-colors duration-200 block text-current relative\" data-sctrack=\"FocusGalleryImage.Reference\"><img fetchpriority=\"high\" data-testid=\"Opener.Image\" style=\"--lqipURL:url('https:\/\/images.t-online.de\/2023\/02\/ceYRGYW7pbEw\/486x96:3455x1944\/fit-in\/150x0\/filters:blur(25)\/cosimo-citiolo-der-musiker-hat-beim-diesjaehrigen-dschungelcamp-mitgemacht.jpg')\"   loading=\"eager\" src=\"https:\/\/www.europesays.com\/ch-de\/wp-content\/uploads\/2026\/04\/cosimo-citiolo-der-musiker-hat-beim-diesjaehrigen-dschungelcamp-mitgemacht.jpg\" alt=\"Cosimo Citiolo: Der Musiker hat beim diesj\u00e4hrigen Dschungelcamp mitgemacht.\" title=\"Cosimo Citiolo: Der Musiker hat beim diesj\u00e4hrigen Dschungelcamp mitgemacht.\" width=\"3455\" height=\"1944\" class=\"bg-[url:var(--lqipURL)] bg-cover bg-center flex h-full w-full max-w-full\" decoding=\"async\"\/><img style=\"--width:32;--height:32\" loading=\"lazy\" src=\"https:\/\/www.t-online.de\/s\/paper\/_next\/static\/media\/zoom-in.f7dae02f.svg\" alt=\"Vergr\u00f6\u00dfern des Bildes\" title=\"Vergr\u00f6\u00dfern des Bildes\" class=\"block h-[calc(var(--height)_\/_16_*_1rem)] w-[calc(var(--width)_\/_16_*_1rem)] max-w-none absolute bottom-8 right-8 rounded-4 bg-snow p-8\" decoding=\"async\"\/><\/a><\/p>\n<p>Cosimo Citiolo: Der ehemalige DSDS-Kandidat spricht \u00fcber Geld. (Quelle: IMAGO\/Gartner)<\/p>\n<p class=\"font-bold text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\">2025 war Cosimo Citiolo in zahlreichen TV-Formaten pr\u00e4sent. In monet\u00e4rer Hinsicht spiegelt sich das nicht zwangsl\u00e4ufig wieder, wie ein Blick auf seine Finanzen zeigt.<\/p>\n<p class=\"text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\">Sechs TV-Formate in einem Jahr, dazu ein Sieg bei &#171;Promis unter Palmen&#187; mit 44.000 Euro Gewinn: Cosimo Citiolo hat sich 2025 fest in der deutschen Reality-TV-Welt etabliert. Laut Recherchen von RTL soll der 44-J\u00e4hrige im Schnitt rund 10.000 Euro im Monat durch Gagen, Kooperationen und Auftritte verdienen.<\/p>\n<p class=\"text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\">Doch im Gespr\u00e4ch mit dem TV-Sender zeichnet Cosimo Citiolo selbst ein anderes Bild. &#171;Keine Ahnung, das Leben ist teuer. Ich zahle Miete, ich zahle alles&#187;, sagt er. &#171;Das ist schon nicht ohne.&#187;<\/p>\n<p class=\"text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\">Einen Teil der Erkl\u00e4rung liefert seine Vergangenheit: Cosimo Citiolo musste einst <a class=\"transition-colors duration-200 cursor-pointer text-inherit no-underline text-salemsfur md:hover:text-magenta md:hover:border-magenta md:focus:text-magenta border-current border-b border-solid break-words\" data-tracking=\"{&quot;action&quot;:&quot;click&quot;,&quot;category&quot;:&quot;intextLink&quot;,&quot;label&quot;:&quot;\/unterhaltung\/tv\/dschungelcamp\/id_100114914\/dschungelcamp-2023-cosimo-citiolo-sitzt-auf-einem-riesen-schuldenberg.html&quot;}\" href=\"https:\/\/www.t-online.de\/unterhaltung\/tv\/dschungelcamp\/id_100114914\/dschungelcamp-2023-cosimo-citiolo-sitzt-auf-einem-riesen-schuldenberg.html\" data-sctrack=\"BodyAnchor\" rel=\"nofollow noopener\" target=\"_blank\">Insolvenz anmelden<\/a>. Das Geld aus Formaten wie dem &#171;Dschungelcamp&#187; nutzte er nach eigenen Angaben vor allem f\u00fcr R\u00fcckzahlungen.<\/p>\n<p class=\"text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\">Realitykollege Maurice Dziwak \u00e4u\u00dferte sich im RTL-Interview mit einem Seitenhieb: &#171;Bei Cosimo ist das Problem: Dass das Geld nicht da ist, das liegt vielleicht an anderen Sachen.&#187;<\/p>\n<p class=\"text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\">Etwas mehr Einblick gab Cosimos Ehefrau Nathalie Gaus. &#171;Bei uns ist das Problem, dass wir kein regelm\u00e4\u00dfiges Einkommen haben. Geld ist da und wir geben es gerne aus&#187;, erkl\u00e4rte sie gegen\u00fcber RTL. Allein f\u00fcr gemeinsame Beauty-Eingriffe planten die beiden nach eigenen Angaben rund 2.500 Euro im Monat ein. &#171;Reich werden ist schwierig. Man muss halt schlau investieren&#187;, so Nathalie Gaus weiter.<\/p>\n<p class=\"text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\">Bei den diesj\u00e4hrigen Reality Awards ist Cosimo Citiolo als &#171;Realitystar des Jahres&#187; nominiert. Ob er den Titel gewinnt, zeigt sich am 16. April im Livestream auf RTL+.<\/p>\n","protected":false},"excerpt":{"rendered":"&#171;Das Leben ist teuer&#187; Cosimo Citiolo packt \u00fcber seine Finanzen aus 16.04.2026 &#8211; 13:08 UhrLesedauer: 1 Min. Cosimo&hellip;\n","protected":false},"author":2,"featured_media":85554,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[801,996,46,2081,68,10746,23839,398,511,45,90,89,44,69],"class_list":{"0":"post-85553","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-serien","8":"tag-801","9":"tag-996","10":"tag-ch","11":"tag-dsds","12":"tag-entertainment","13":"tag-insolvenz","14":"tag-nathalie-gaus","15":"tag-promis-unter-palmen","16":"tag-rtl","17":"tag-schweiz","18":"tag-serien","19":"tag-series","20":"tag-switzerland","21":"tag-unterhaltung"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_de\/116414998823048581","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts\/85553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/comments?post=85553"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts\/85553\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/media\/85554"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/media?parent=85553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/categories?post=85553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/tags?post=85553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}