{"id":86089,"date":"2026-04-16T23:59:10","date_gmt":"2026-04-16T23:59:10","guid":{"rendered":"https:\/\/www.europesays.com\/ch-de\/86089\/"},"modified":"2026-04-16T23:59:10","modified_gmt":"2026-04-16T23:59:10","slug":"wann-startet-prominent-getrennt-2026-der-sendetermin-steht","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-de\/86089\/","title":{"rendered":"Wann startet \u201eProminent getrennt\u201d 2026? Der Sendetermin steht!"},"content":{"rendered":"<p>Start, Kandidaten und Co.Der Starttermin steht! Hier kommen alle Infos zur f\u00fcnften \u201eProminent getrennt\u201d-Staffel  16. April 2026 um 22:28 Uhr<\/p>\n<p class=\"AnnotatedMarkup_paragraph__IUT9l\">Hier gibt\u2019s viel Kl\u00e4rungsbedarf!<br \/>Man nehme sieben \u00f6ffentliche Trennungen, unausgesprochene Konflikte und eine Prise emotionalen Ballast \u2013 fertig ist der Exen-Kessel! Auch in der  5. Staffel von \u201eProminent getrennt\u201d wird die Stimmung in S\u00fcdafrika wieder hochkochen. Und wir d\u00fcrfen ihnen auch schon ganz bald dabei zuschauen. Den Cast seht ihr oben im Video.<\/p>\n<p>Wann startet \u201eDie Bachelors\u201d auf RTL+ und bei RTL?<\/p>\n<p class=\"AnnotatedMarkup_paragraph__IUT9l\"><a href=\"https:\/\/beta.plus.rtl.de\/prominent-getrennt-die-villa-der-verflossenen-p_9219?utm_source=rtl&amp;utm_content=6864303&amp;utm_medium=owned&amp;utm_campaign=textlink&amp;utm_term=na\" target=\"_blank\" rel=\"nofollow noopener\">\u201eProminent getrennt\u201d <\/a>startet am 30. April. Ab dann werden immer donnerstags um 0 Uhr die neusten Folgen auf RTL+ zu sehen sein. Insgesamt wird es 12 Folgen geben.<\/p>\n<p>Was passiert bei \u201eProminent getrennt\u201d?<\/p>\n<p class=\"AnnotatedMarkup_paragraph__IUT9l\">In S\u00fcdafrika hei\u00dft es wieder: Trennung deluxe, denn sieben prominente Ex-Paare wagen sich in die 5. Staffel \u201eProminent getrennt\u201d \u2013 und stellen sich ihrer Vergangenheit. Alte Konflikte, neue Allianzen und jede Menge Emotionen: Wer schafft es, trotz gebrochener Herzen wieder als Team zu funktionieren? Denn nur wer zusammenarbeitet, hat am Ende die Chance auf bis zu 100.000 Euro.<\/p>\n<p class=\"AnnotatedMarkup_paragraph__IUT9l\">Lese-Tipp: <a href=\"https:\/\/www.rtl.de\/sendungen\/prominent-getrennt\/prominent-getrennt-gewinner-2025-dieses-ex-paar-schnappt-sich-den-sieg-im-finale-id6634541.html\" target=\"_self\" rel=\"nofollow noopener\">Dieses Ex-Paar holt sich 2025 den \u201eProminent getrennt\u201d-Sieg <\/a><\/p>\n<p>Anzeige:<\/p>\n<p>Empfehlungen unserer Partner<\/p>\n<p>Diese Paare stellen sich der Herausforderung bei \u201eProminent getrennt\u201d 2026. Vanessa Nwattu und Aleks Petrovic<\/p>\n<p class=\"AnnotatedMarkup_paragraph__IUT9l\"><a href=\"https:\/\/www.rtl.de\/themen\/personen\/aleksandar-aleks-petrovic-t17344.html\" target=\"_self\" rel=\"nofollow noopener\">Aleks Petrovic<\/a> und <a href=\"https:\/\/www.rtl.de\/themen\/personen\/vanessa-nwattu-t17347.html\" target=\"_self\" rel=\"nofollow noopener\">Vanessa Nwattu <\/a>lernten sich 2022 bei \u201eTemptation Island VIP\u201c (<a href=\"https:\/\/plus.rtl.de\/video-tv\/shows\/temptation-island-vip-868824?utm_source=google&amp;utm_medium=cpc&amp;utm_marketing_tactic=sea&amp;utm_campaign=sea_12619206938&amp;utm_content=128541227468&amp;utm_creative_format=c_12619206938_ag_128541227468_a_608260751913&amp;gad_source=1&amp;gad_campaignid=12619206938&amp;gbraid=0AAAAADHYWfSUtu8sV4B169ANZz_KITyfm&amp;gclid=CjwKCAiA95fLBhBPEiwATXUsxEcN313YTVv0YupIYhrLKk6hCXx0gaHPpx5NIkAHmeNie2PiePfwMhoCNtUQAvD_BwE\" target=\"_blank\" rel=\"nofollow noopener\">hier auf RTL+ streamen<\/a>) kennen \u2013 unter denkbar brisanten Umst\u00e4nden. <a href=\"https:\/\/www.rtl.de\/cms\/temptation-island-vip-aleks-sorgt-fuer-eklat-du-hast-dich-verliebt-5021604.html\" target=\"_self\" rel=\"nofollow noopener\">Aleks ging noch w\u00e4hrend der Show eine neue Beziehung mit Vanessa ein und trennte sich daf\u00fcr von seiner damaligen Partnerin Christina Dimitriou<\/a>. Von Beginn an stand ihre Liebe unter besonderer Beobachtung, der \u00f6ffentliche Gegenwind war gro\u00df. Trotzdem pr\u00e4sentierten sich die beiden \u00fcber Jahre hinweg nach au\u00dfen geschlossen: als starkes Team, als vermeintliche Bilderbuchbeziehung. Sie hielten zusammen, zogen Ende 2024 sogar gemeinsam nach Dubai und kr\u00f6nten ihre Beziehung im November desselben Jahres mit einer Verlobung. Alles lief nach Plan: verliebt, verlobt&#8230; aber leider nicht verheiratet. Denn: 2026 trennten sie sich \u2013 ausgerechnet da, wo ihre Geschichte begonnen hat. Bei \u201eTemptation Island VIP\u201c.<\/p>\n<p>Samira Cilingir und Yasin Cilingir <img alt=\"Yasin Cilingir und Samira Cilingir&#10;&#10;+++ Die Verwendung des sendungsbezogenen Materials ist nur mit dem Hinweis und Verlinkung auf RTL+ gestattet. +++\" fetchpriority=\"auto\" loading=\"lazy\" width=\"940\" height=\"529\" decoding=\"async\" data-nimg=\"1\" class=\"Image_image__SdgLQ Picture_image__vGN9W\" style=\"color:transparent\"   src=\"https:\/\/www.europesays.com\/ch-de\/wp-content\/uploads\/2026\/04\/a2a20.webp.webp\"\/><\/p>\n<p>Yasin Cilingir und Samira Cilingir.<\/p>\n<p> RTL \/ Africa Vumazonke<\/p>\n<p class=\"AnnotatedMarkup_paragraph__IUT9l\">Sie waren eines der <a href=\"https:\/\/plus.rtl.de\/video-tv\/shows\/love-island-heisse-flirts-wahre-liebe-1000003373\/staffel-3-1900337303?utm_source=rtl&amp;utm_content=6864303&amp;utm_medium=owned&amp;utm_campaign=textlink&amp;utm_term=love-island-heisse-flirts-wahre-liebe\" target=\"_blank\" rel=\"nofollow noopener\">\u201eLove Island\u201d<\/a>-Traumpaare schlechthin. <a href=\"https:\/\/www.rtl.de\/unterhaltung\/stars\/love-island-stars-samira-und-yasin-cilingir-nach-ehekrise-wieder-versoehnt-id1835223.html\" target=\"_self\" rel=\"nofollow noopener\">Yasin und Samira<\/a> haben sich 2019 verliebt, zwei Jahre sp\u00e4ter wurde geheiratet. Die beiden haben zwei Kinder, aber mittlerweile <a href=\"https:\/\/www.rtl.de\/unterhaltung\/stars\/love-island-traumpaar-samira-cilingir-von-yasins-scheidungs-statement-geschockt-id6659864.html\" target=\"_self\" rel=\"nofollow noopener\">liegt ihre Ehe in Scherben<\/a>. Ob da noch was zu kitten ist?<\/p>\n<p>Rebecca Ries und G\u00f6k G\u00f6ker<img alt=\"G\u00f6k G\u00f6ker und Rebecca Ries.&#10;&#10;+++ Die Verwendung des sendungsbezogenen Materials ist nur mit dem Hinweis und Verlinkung auf RTL+ gestattet. +++\" fetchpriority=\"auto\" loading=\"lazy\" width=\"940\" height=\"529\" decoding=\"async\" data-nimg=\"1\" class=\"Image_image__SdgLQ Picture_image__vGN9W\" style=\"color:transparent\"   src=\"https:\/\/www.europesays.com\/ch-de\/wp-content\/uploads\/2026\/04\/f2e78.webp.webp\"\/><\/p>\n<p>G\u00f6k G\u00f6ker und Rebecca Ries.<\/p>\n<p>RTL \/ Africa Vumazonke<\/p>\n<p class=\"AnnotatedMarkup_paragraph__IUT9l\">Rebecca Ries und G\u00f6ktug G\u00f6ker haben sich <a href=\"https:\/\/plus.rtl.de\/video-tv\/shows\/temptation-island-vip-868824\/staffel-5-989418?utm_source=rtl&amp;utm_content=6864303&amp;utm_medium=owned&amp;utm_campaign=textlink&amp;utm_term=temptation-island-vip\" target=\"_blank\" rel=\"nofollow noopener\">2024 bei \u201eTemptation Island VIP\u201d<\/a> kennen und lieben gelernt. Schon im April 2025 kam der gemeinsame Sohn Malik zur Welt \u2013 und im Mai gaben beide<a href=\"https:\/\/www.rtl.de\/unterhaltung\/nach-trennung-von-goektug-goeker-temptation-island-star-rebecca-ries-spricht-klartext-id4377815.html\" target=\"_self\" rel=\"nofollow noopener\"> \u00fcberraschend die Trennung<\/a> bekannt.<\/p>\n<p>Vanessa Brahimi und Richard Sternberg<img alt=\"Richard Sternberg und Vanessa Brahimi&#10;&#10;+++ Die Verwendung des sendungsbezogenen Materials ist nur mit dem Hinweis und Verlinkung auf RTL+ gestattet. +++\" fetchpriority=\"auto\" loading=\"lazy\" width=\"940\" height=\"529\" decoding=\"async\" data-nimg=\"1\" class=\"Image_image__SdgLQ Picture_image__vGN9W\" style=\"color:transparent\"   src=\"https:\/\/www.europesays.com\/ch-de\/wp-content\/uploads\/2026\/04\/0af0f.webp.webp\"\/><\/p>\n<p>Richard Sternberg und Vanessa Brahimi.<\/p>\n<p>RTL \/ Africa Vumazonke<\/p>\n<p class=\"AnnotatedMarkup_paragraph__IUT9l\">Ihre Liebe hat<a href=\"https:\/\/plus.rtl.de\/video-tv\/shows\/das-sommerhaus-der-normalos-1005437?utm_source=rtl&amp;utm_content=6864303&amp;utm_medium=owned&amp;utm_campaign=textlink&amp;utm_term=das-sommerhaus-der-normalos\" target=\"_blank\" rel=\"nofollow noopener\"> \u201eDas Sommerhaus der Normalos\u201d<\/a> nicht \u00fcberstanden. Jetzt treffen Vanessa und Richard bei \u201eProminent getrennt\u201d wieder aufeinander. Und da <a href=\"https:\/\/www.rtl.de\/sendungen\/das-sommerhaus-der-normalos\/der-sommerhaus-fluch-schlaegt-wieder-zu-auch-dieses-paar-ist-getrennt-und-das-schon-laenger-id2905292.html\" target=\"_self\" rel=\"nofollow noopener\">Vanessas zweiter Vorname Drama ist<\/a>, k\u00f6nnen wir uns wohl auf einiges gefasst machen<\/p>\n<p>Tessa Bergmeier und Jakob Morgenstern<img alt=\"Jakob Morgenstern und Tessa Bergmeier&#10;&#10;+++ Die Verwendung des sendungsbezogenen Materials ist nur mit dem Hinweis und Verlinkung auf RTL+ gestattet. +++\" fetchpriority=\"auto\" loading=\"lazy\" width=\"940\" height=\"529\" decoding=\"async\" data-nimg=\"1\" class=\"Image_image__SdgLQ Picture_image__vGN9W\" style=\"color:transparent\"   src=\"https:\/\/www.europesays.com\/ch-de\/wp-content\/uploads\/2026\/04\/fd621.webp.webp\"\/><\/p>\n<p>Jakob Morgenstern und Tessa Bergmeier.<\/p>\n<p>RTL \/ Africa Vumazonke<\/p>\n<p class=\"AnnotatedMarkup_paragraph__IUT9l\">Im <a href=\"https:\/\/plus.rtl.de\/video-tv\/shows\/das-sommerhaus-der-stars-kampf-der-promipaare-761973\/staffel-9-899767?utm_source=rtl&amp;utm_content=6864303&amp;utm_medium=owned&amp;utm_campaign=textlink&amp;utm_term=das-sommerhaus-der-stars-kampf-der-promipaare\" target=\"_blank\" rel=\"nofollow noopener\">\u201eSommerhaus der Stars\u201d 2024<\/a> haben wir sie zum ersten und zum letzten Mal als Paar gesehen.  Denn schon vor der Wiedersehensshow haben <a href=\"https:\/\/www.rtl.de\/sendungen\/das-sommerhaus-der-stars\/sommerhaus-der-stars-trennung-liebes-aus-bei-tessa-bergmeier-und-ihrem-jakob-id1901732.html\" target=\"_self\" rel=\"nofollow noopener\">Tessa und Jakob ihre Trennung bekannt gegeben<\/a>. Vielleicht erfahren wir bei \u201eProminent getrennt\u201d 2026 mehr \u00fcber die Gr\u00fcnde.<\/p>\n<p>Tanina und Fabian<img alt=\"Fabian und Tanina&#10;&#10;+++ Die Verwendung des sendungsbezogenen Materials ist nur mit dem Hinweis und Verlinkung auf RTL+ gestattet. +++\" fetchpriority=\"auto\" loading=\"lazy\" width=\"940\" height=\"529\" decoding=\"async\" data-nimg=\"1\" class=\"Image_image__SdgLQ Picture_image__vGN9W\" style=\"color:transparent\"   src=\"https:\/\/www.europesays.com\/ch-de\/wp-content\/uploads\/2026\/04\/982ab.webp.webp\"\/><\/p>\n<p>Fabian und Tanina.<\/p>\n<p>RTL \/ Africa Vumazonke<\/p>\n<p class=\"AnnotatedMarkup_paragraph__IUT9l\">Ger\u00fcchte sagen, dass sie schon vor der Show ein Paar waren. Offiziell haben sich Tanina und Fabien aber in der zweiten Staffel von \u201eToo Hot to Handle\u201d kennengelernt. Doch die Fernbeziehung hat nicht gehalten.<\/p>\n<p>Vivien und Mou<img alt=\"Mou und Vivien.&#10;+++ Die Verwendung des sendungsbezogenen Materials ist nur mit dem Hinweis und Verlinkung auf RTL+ gestattet. +++\" fetchpriority=\"auto\" loading=\"lazy\" width=\"940\" height=\"529\" decoding=\"async\" data-nimg=\"1\" class=\"Image_image__SdgLQ Picture_image__vGN9W\" style=\"color:transparent\"   src=\"https:\/\/www.europesays.com\/ch-de\/wp-content\/uploads\/2026\/04\/1dd0c.webp.webp\"\/><\/p>\n<p>Mou und Vivien.<\/p>\n<p>RTL \/ Africa Vumazonke<\/p>\n<p class=\"AnnotatedMarkup_paragraph__IUT9l\">Mou hat die Reality-Nation und vor allem seine (Ex-) Freundin Vivien mit seiner Fremdgeh-Beichte bei<a href=\"https:\/\/plus.rtl.de\/video-tv\/shows\/temptation-island-versuchung-im-paradies-121619\/staffel-6-953263?utm_source=rtl&amp;utm_content=6864303&amp;utm_medium=owned&amp;utm_campaign=textlink&amp;utm_term=temptation-island-versuchung-im-paradies\" target=\"_blank\" rel=\"nofollow noopener\"> \u201eTemptation Island\u201c in Staffel 6<\/a> nachhaltig schockiert: <a href=\"https:\/\/www.rtl.de\/cms\/temptation-island-vivien-betrogen-mou-gesteht-affaere-vor-der-sendung-5089191.html\" target=\"_self\" rel=\"nofollow noopener\">Er hatte sie schon VOR der Sendung betrogen<\/a>. Nach der Trennung versuchten die beiden 2025 bei \u201eEx on the Beach\u201d ihre Beziehung zu retten. Erfolglos. Da gibt es bei \u201eProminent getrennt\u201d 2026 sicherlich noch einiges zu kl\u00e4ren.<\/p>\n<p>Bianca Eigenfeld und Joshi Josh<img alt=\"&#10;Joshi Josh und Bianca Eigenfeld.&#10;+++ Die Verwendung des sendungsbezogenen Materials ist nur mit dem Hinweis und Verlinkung auf RTL+ gestattet. +++\" fetchpriority=\"auto\" loading=\"lazy\" width=\"940\" height=\"529\" decoding=\"async\" data-nimg=\"1\" class=\"Image_image__SdgLQ Picture_image__vGN9W\" style=\"color:transparent\"   src=\"https:\/\/www.europesays.com\/ch-de\/wp-content\/uploads\/2026\/04\/f8567.webp.webp\"\/><\/p>\n<p>Joshi Josh und Bianca Eigenfeld.<\/p>\n<p>RTL \/ Africa Vumazonke<\/p>\n<p class=\"AnnotatedMarkup_paragraph__IUT9l\">Joshi Josh und Bianca kennen wir von<a href=\"https:\/\/plus.rtl.de\/video-tv\/shows\/ex-on-the-beach-866040\/staffel-6-1013351?utm_source=rtl&amp;utm_content=6864303&amp;utm_medium=owned&amp;utm_campaign=textlink&amp;utm_term=ex-on-the-beach\" target=\"_blank\" rel=\"nofollow noopener\"> \u201eEx on the Beach\u201d 2025<\/a>. ER hat <a href=\"https:\/\/www.rtl.de\/sendungen\/ex-on-the-beach\/ex-on-the-beach-wegen-seiner-sexszene-will-joshi-josh-am-liebsten-auswandern-id4455764.html\" target=\"_self\" rel=\"nofollow noopener\">dort f\u00fcr jede Menge Action gesorgt<\/a>. Treibt Joshi es auch bei \u201eProminent getrennt\u201d wieder (zu) wild?<\/p>\n<p>\u201eProminent getrennt\u201c auf RTL+ streamen<img alt=\"Prominent getrennt - Die Villa der Verflossenen\" fetchpriority=\"auto\" loading=\"lazy\" width=\"615\" height=\"346\" decoding=\"async\" data-nimg=\"1\" class=\"Image_image__SdgLQ RtlPlusContent_image__Gbn0N\" style=\"color:transparent\"   src=\"https:\/\/www.europesays.com\/ch-de\/wp-content\/uploads\/2026\/04\/prominent-getrennt-die-villa-der-verflossenen.webp.webp\"\/><\/p>\n<p class=\"AnnotatedMarkup_paragraph__IUT9l\">Bis Staffel 5 ausgestrahlt wird, dauert es noch ein wenig. <a href=\"https:\/\/plus.rtl.de\/video-tv\/shows\/prominent-getrennt-die-villa-der-verflossenen-898918?utm_source=rtl&amp;utm_content=6864303&amp;utm_medium=owned&amp;utm_campaign=textlink&amp;utm_term=prominent-getrennt-die-villa-der-verflossenen\" target=\"_blank\" rel=\"nofollow noopener\">Die ersten vier \u201eProminent getrennt\u201c-Staffeln stehen aber nat\u00fcrlich auf RTL+ jeder Zeit zur Verf\u00fcgung.<\/a><\/p>\n<p class=\"AnnotatedMarkup_paragraph__IUT9l\">Verwendete Quellen: RTL<\/p>\n","protected":false},"excerpt":{"rendered":"Start, Kandidaten und Co.Der Starttermin steht! Hier kommen alle Infos zur f\u00fcnften \u201eProminent getrennt\u201d-Staffel 16. April 2026 um&hellip;\n","protected":false},"author":2,"featured_media":86090,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[46,68,9502,23919,511,45,90,89,44,221,69,23920],"class_list":{"0":"post-86089","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-serien","8":"tag-ch","9":"tag-entertainment","10":"tag-prominent-getrennt","11":"tag-prominent-getrennt-2026","12":"tag-rtl","13":"tag-schweiz","14":"tag-serien","15":"tag-series","16":"tag-switzerland","17":"tag-tv","18":"tag-unterhaltung","19":"tag-villa-der-verflossenen"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_de\/116417098618280094","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts\/86089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/comments?post=86089"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts\/86089\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/media\/86090"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/media?parent=86089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/categories?post=86089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/tags?post=86089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}