{"id":87225,"date":"2026-04-17T18:15:12","date_gmt":"2026-04-17T18:15:12","guid":{"rendered":"https:\/\/www.europesays.com\/ch-de\/87225\/"},"modified":"2026-04-17T18:15:12","modified_gmt":"2026-04-17T18:15:12","slug":"desiree-nick-sollte-professur-erhalten-doch-hochschule-distanziert-sich-von-entertainerin-unterhaltung","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-de\/87225\/","title":{"rendered":"D\u00e9sir\u00e9e Nick sollte Professur erhalten, doch Hochschule distanziert sich von Entertainerin | Unterhaltung"},"content":{"rendered":"<p><a class=\"skip-content skip-content--link\" href=\"#in-content-skip-link-target-v-0-0\">TTS-Player \u00fcberspringen\u21b5<\/a><a id=\"in-content-skip-link-target-v-0-0\" class=\"skip-content--target-link-hidden skip-content skip-content--target-link\" href=\"#in-content-skip-link-target-v-0-0\">Artikel weiterlesen<\/a><\/p>\n<p>M\u00fcnchen\/Berlin \u2013 Sie ist sicherlich die schillerndste Gastprofessorin, die eine deutsche Hochschule jemals von innen gesehen hat. Vor rund einer Woche sagte Entertainerin D\u00e9sir\u00e9e Nick (69) zu BILD, dass sie k\u00fcnftig viermal im Jahr an der Macromedia University in M\u00fcnchen unterrichten werde. Ihr Fach: \u201eBerufsbild <a href=\"https:\/\/www.bild.de\/article\/69afdde6234864f234f03598\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">Reality<\/a>-Star\u201c. Doch nun scheint dieser Lehrk\u00f6rper versetzungsgef\u00e4hrdet zu sein: Die Hochschule distanziert sich von D\u00e9sir\u00e9e Nick.<\/p>\n<p>Vor ihrem Besuch an der Macromedia University sagte <a href=\"https:\/\/www.bild.de\/unterhaltung\/stars-und-leute\/desiree-nick-wird-professorin-ich-bin-jetzt-trash-trainerin-69d60a079e9e187ca9edb22b\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">D\u00e9sir\u00e9e Nick<\/a> zu BILD: \u201eIch bin jetzt Trash-Trainerin! Und ab sofort Professorin h.c. an der Macromedia Akademie in M\u00fcnchen mit vier Vorlesungen zum Thema ,<a href=\"https:\/\/www.bild.de\/unterhaltung\/tv-fernsehformate\/die-realitystar-academy-alle-infos-zur-neuen-show-mit-desiree-nick-69a046d72cfe24517f7c9e1a\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">Berufsbild Reality-Star\u2018<\/a>. Ich habe aus Reality eine Industrie gemacht.\u201c <\/p>\n<p><img decoding=\"async\" width=\"992\" height=\"558\" alt=\"In der letzten Staffel von \u201ePromi Big Brother\u201c sorgten D\u00e9sir\u00e9e Nick und Harald Gl\u00f6\u00f6ckler (60) f\u00fcr maximale Aufmerksamkeit\" src=\"https:\/\/www.europesays.com\/ch-de\/wp-content\/uploads\/2026\/04\/f340e186fe8de11b28865af423e4d2c8,56b1dded.jpeg\"   class=\"landscape\" loading=\"lazy\"\/><\/p>\n<p class=\"fig__caption__text\">In der letzten Staffel von \u201ePromi Big Brother\u201c sorgten D\u00e9sir\u00e9e Nick und Harald Gl\u00f6\u00f6ckler (60) f\u00fcr maximale Aufmerksamkeit <\/p>\n<p>Foto: Joyn<\/p>\n<p>War D\u00e9sir\u00e9e Nicks Wunsch vielleicht der Vater des akademischen Gedankens? Die Macromedia University l\u00e4sst BILD \u00fcber eine Sprecherin jetzt ausrichten: \u201eAls Hochschule legen wir gro\u00dfen Wert auf die Qualit\u00e4t und Integrit\u00e4t unserer Lehre sowie auf klar definierte akademische Rollen und Verfahren. Gastbeitr\u00e4ge externer Pers\u00f6nlichkeiten sind ein etabliertes Format, um Studierenden zus\u00e4tzliche Impulse aus Praxis, Kultur und \u00d6ffentlichkeit zu vermitteln. Sie begr\u00fcnden jedoch keine akademische Position oder institutionelle Funktion.\u201c<\/p>\n<p>Macromedia University dementiert Nick-Professur<\/p>\n<p>Es stimme: D\u00e9sir\u00e9e Nick war in der letzten Woche an der Akademie in M\u00fcnchen zu Gast. Dazu sagt die Hochschule allerdings: \u201eFrau Nick hielt im Rahmen einer bestehenden Lehrveranstaltung einen einmaligen, kurzen Gastbeitrag w\u00e4hrend einer Unterrichtspause. Dieser erfolgte weder im Rahmen eines Lehrauftrags noch in einer sonstigen akademischen Funktion.\u201c<\/p>\n<p><img decoding=\"async\" width=\"992\" height=\"659\" alt=\"Seit 16. April auf Joyn: \u201eDie Realitystar Academy\u201c mit D\u00e9sir\u00e9e Nick\" src=\"https:\/\/www.europesays.com\/ch-de\/wp-content\/uploads\/2026\/04\/f8b93ab8e672df34058f18e50fd476e3,a2dbd468.jpeg\"   class=\"dynamic\" loading=\"lazy\"\/><\/p>\n<p class=\"fig__caption__text\">Seit 16. April auf Joyn: \u201eDie Realitystar Academy\u201c mit D\u00e9sir\u00e9e Nick <\/p>\n<p>Foto: Joyn\/Marc Rehbeck<\/p>\n<p>Und weiter: \u201eDie Verleihung einer Honorarprofessur folgt an der Macromedia University einem klar geregelten, mehrstufigen Verfahren und setzt nachgewiesene wissenschaftliche Qualifikation oder herausragende Leistungen in der Praxis voraus.\u201c<\/p>\n<p>D\u00e9sir\u00e9e Nick reagiert auf Macromedia Academy<\/p>\n<p>Was sagt D\u00e9sir\u00e9e Nick zu dem Durcheinander? Sie zu BILD: \u201eWir sind in einem Reality-Format wie ,Die Realitystar Academy\u2018 weder vor Gericht noch bei der Polizei. Tatsache ist, dass die Studierenden in M\u00fcnchen meine Kompetenzen zum Fach Reality mit gr\u00f6\u00dfter Begeisterung f\u00fcr ihre Bachelor-Arbeit verwerten konnten. Inzwischen liegen diverse Anfragen auch von anderen Akademien in Deutschland vor.\u201c<\/p>\n<p>Mehr zum Thema<\/p>\n<p>Der Macromedia University l\u00e4sst D\u00e9sir\u00e9e Nick ausrichten: \u201eNun lernen diese Pfeifen wenigstens, was real Marketing bedeutet.\u201c Und weiter: \u201eDa die Macromedia Academy meinen umfangreichen Einsatz vor ca. 40 Studierenden herunterspielen will, werde ich wohl eine Rechnung f\u00fcr die erfolgte PR-Arbeit ausfertigen m\u00fcssen. Es ist ja nicht real, gratis zu arbeiten, wenn man an einer Akademie 45 Minuten eine Vorlesung h\u00e4lt.\u201c<\/p>\n","protected":false},"excerpt":{"rendered":"TTS-Player \u00fcberspringen\u21b5Artikel weiterlesen M\u00fcnchen\/Berlin \u2013 Sie ist sicherlich die schillerndste Gastprofessorin, die eine deutsche Hochschule jemals von innen&hellip;\n","protected":false},"author":2,"featured_media":87226,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[12671,101,46,473,68,9015,102,1681,352,45,44,103,69],"class_list":{"0":"post-87225","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-prominente","8":"tag-big-brother-promi","9":"tag-celebrities","10":"tag-ch","11":"tag-dschungelcamp","12":"tag-entertainment","13":"tag-nick-desiree","14":"tag-prominente","15":"tag-reality-show","16":"tag-sat-1","17":"tag-schweiz","18":"tag-switzerland","19":"tag-texttospeech","20":"tag-unterhaltung"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_de\/116421408374629628","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts\/87225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/comments?post=87225"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/posts\/87225\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/media\/87226"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/media?parent=87225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/categories?post=87225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-de\/wp-json\/wp\/v2\/tags?post=87225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}