{"id":110034,"date":"2026-04-29T16:35:09","date_gmt":"2026-04-29T16:35:09","guid":{"rendered":"https:\/\/www.europesays.com\/ch-fr\/110034\/"},"modified":"2026-04-29T16:35:09","modified_gmt":"2026-04-29T16:35:09","slug":"venu-tout-droit-de-coree-du-sud-le-phenomene-photoism-ouvre-a-lille-sa-2eme-boutique-de-photobooths-k-pop","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-fr\/110034\/","title":{"rendered":"Venu tout droit de Cor\u00e9e du Sud, le ph\u00e9nom\u00e8ne Photoism ouvre \u00e0 Lille sa 2\u00e8me boutique de photobooths K-pop"},"content":{"rendered":"<p>                    Par<\/p>\n<p>            <a href=\"https:\/\/actu.fr\/auteur\/hervine-mahaud\" title=\"Consulter tous les articles de Hervine Mahaud\" rel=\"nofollow noopener\" target=\"_blank\">Hervine Mahaud<\/a><\/p>\n<p>        Publi\u00e9 le<\/p>\n<p>            29 avr. 2026 \u00e0 18h00        <\/p>\n<p>La vague cor\u00e9enne continue de d\u00e9ferler \u00e0 <a href=\"https:\/\/actu.fr\/hauts-de-france\/lille_59350\" rel=\"nofollow noopener\" target=\"_blank\">Lille<\/a>. Apr\u00e8s les <a href=\"https:\/\/actu.fr\/hauts-de-france\/lille_59350\/lille-le-restaurant-coreen-yena-ne-va-vous-faire-voyager-grace-a-ses-plats-authentiques_62882025.html\" rel=\"nofollow noopener\" target=\"_blank\">restaurants<\/a>, les <a href=\"https:\/\/actu.fr\/hauts-de-france\/lille_59350\/nouveau-a-lille-inamori-market-un-enorme-magasin-de-specialites-asiatiques-reparti-sur-deux-etages_61472709.html\" rel=\"nofollow noopener\" target=\"_blank\">\u00e9piceries asiatiques<\/a> et les <a href=\"https:\/\/actu.fr\/hauts-de-france\/villeneuve-d-ascq_59009\/pres-de-lille-un-pop-up-store-geant-dedie-a-la-k-pop-et-a-la-k-beauty-ouvre-ce-week-end_62687940.html\" rel=\"nofollow noopener\" target=\"_blank\">\u00e9v\u00e9nements K-pop<\/a>, un nouveau concept tout droit venu de Cor\u00e9e du Sud s\u2019installe dans le Vieux-Lille ce mercredi 29 avril 2026. Photoism, marque mondialement connue pour ses photobooths immersifs et ses collaborations avec les plus grandes stars de la K-pop, ouvre sa deuxi\u00e8me boutique fran\u00e7aise au 103 rue Esquermoise. Cabines photo tendance, clich\u00e9s avec des idoles, goodies exclusifs et produits import\u00e9s\u2026 le lieu promet d\u00e9j\u00e0 d\u2019attirer les fans de culture cor\u00e9enne.<\/p>\n<p>Le leader du photobooth en Cor\u00e9e d\u00e9barque \u00e0 Lille<\/p>\n<p class=\" wall-content\">Originaire de Cor\u00e9e du Sud, Photoism s\u2019est impos\u00e9 ces derni\u00e8res ann\u00e9es comme une r\u00e9f\u00e9rence mondiale du photobooth nouvelle g\u00e9n\u00e9ration. L\u2019enseigne revendique aujourd\u2019hui plus de 38 millions de visiteurs annuels dans 15 pays.<\/p>\n<p class=\" wall-content\"><a href=\"https:\/\/www.instagram.com\/p\/DXJXmn3DbIr\/embed\" title=\"Ouvrir le lien sur Instagram\" rel=\"nofollow noopener\" target=\"_blank\">Visualiser le contenu sur Instagram<\/a><\/p>\n<p class=\" wall-content\">Le concept revisite totalement la cabine photo classique. \u00c0 Lille, quatre photobooths seront accessibles au public.<\/p>\n<p class=\" wall-content\">Les visiteurs pourront choisir leurs filtres, leurs cadres (\u201cframes\u201d) et repartir quelques secondes plus tard avec deux tirages imprim\u00e9s en qualit\u00e9 studio, mais aussi leur photo et leur vid\u00e9o en format num\u00e9rique.<\/p>\n<p>    <img   decoding=\"async\" loading=\"lazy\" class=\"size-large\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/04\/c13200db02f96063200db02f92a320v-960x640.jpg\" alt=\"photoism cabines photos coree du sud k-pop photoboothes vieux lille rue esquermoise\" width=\"960\" height=\"640\"\/><br \/>\n    Quatre cabines photos sont disponibles \u00e0 Lille. \u00a9Hervine Mahaud<\/p>\n<p class=\" wall-content\">L\u2019une des cabines proposera m\u00eame des prises de vue en contre-plong\u00e9e pour un rendu plus original et ludique.<\/p>\n<p>Des photos avec BTS, Lisa de Blackpink ou Stray Kids<\/p>\n<p class=\" wall-content\">Photoism mise surtout sur l\u2019univers de la K-culture et de la K-pop. Gr\u00e2ce aux nombreux partenariats sign\u00e9s avec les grandes agences cor\u00e9ennes, les visiteurs pourront poser virtuellement aux c\u00f4t\u00e9s de stars mondialement connues comme BTS, Lisa de Blackpink, Stray Kids, aespa ou encore Enhypen.<\/p>\n<p>    <img   decoding=\"async\" loading=\"lazy\" class=\"size-large\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/04\/8a3900db02f96fe3900db02f953490v-960x640.jpg\" alt=\"photoism cabines photos coree du sud k-pop photoboothes vieux lille rue esquermoise\" width=\"960\" height=\"640\"\/><br \/>\n    G\u00e9rant de la boutique lilloise, Antoine nous explique le fonctionnement des cabines photo : un jeu d\u2019enfant. \u00a9Hervine Mahaud<\/p>\n<p class=\" wall-content\">Le concept pla\u00eet autant aux fans de K-pop qu\u2019aux groupes d\u2019amis ou aux couples venus simplement immortaliser un moment original. Des accessoires tels que des chapeaux, des lunettes, des masques et objets th\u00e9matiques, sont gratuitement mis \u00e0 disposition pour personnaliser les s\u00e9ances photo. Des collections saisonni\u00e8res seront \u00e9galement propos\u00e9es pour Halloween, No\u00ebl ou encore la Saint-Valentin.<\/p>\n<p>    <img   decoding=\"async\" loading=\"lazy\" class=\"size-large\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/04\/ddf001bc02f96500101bc02f924010v-960x640.jpg\" alt=\"photoism cabines photos coree du sud k-pop photoboothes vieux lille rue esquermoise\" width=\"960\" height=\"640\"\/><br \/>\n    Il est possible d\u2019emprunter tout un tas d\u2019accessoires pour rendre sa photo la plus fun possible. \u00a9Hervine MahaudUne boutique entre photobooth, snacks et produits cor\u00e9ens<\/p>\n<p class=\" wall-content\">Au-del\u00e0 des cabines photo, la boutique Photoism veut aussi devenir un petit lieu de d\u00e9couverte de la culture cor\u00e9enne \u00e0 Lille. Les visiteurs retrouveront une s\u00e9lection de produits de beaut\u00e9 cor\u00e9ens, du merchandising officiel K-pop ainsi que des snacks directement import\u00e9s de Cor\u00e9e du Sud.<\/p>\n<p class=\" wall-content\">Pour l\u2019enseigne, Lille repr\u00e9sentait une implantation strat\u00e9gique. Avec plus de 120 000 \u00e9tudiants et une importante communaut\u00e9 de passionn\u00e9s de culture cor\u00e9enne, la capitale des Flandres apparaissait comme une \u00e9vidence.<\/p>\n<p>Combien co\u00fbtent les photos ?\u00a0<\/p>\n<p class=\" wall-content\">Trois formules seront propos\u00e9es :<\/p>\n<p>Session classique : 8 \u20ac (2 tirages photo + fichiers num\u00e9riques + vid\u00e9o)<br \/>\nSession grand format : 12 \u20ac (2 grands tirages + fichiers num\u00e9riques + vid\u00e9o)<br \/>\nSession idol : 15 \u20ac (2 tirages avec son artiste pr\u00e9f\u00e9r\u00e9 + fichiers num\u00e9riques + vid\u00e9o)<\/p>\n<p class=\" wall-content\">Les bornes acceptent les paiements par carte bancaire et en esp\u00e8ces. Attention toutefois : les machines ne rendent pas la monnaie. Il faudra donc pr\u00e9voir l\u2019appoint pour les paiements en liquide.<\/p>\n<p class=\" wall-content\">Personnalisez votre actualit\u00e9 en ajoutant vos villes et m\u00e9dias en favori avec <a href=\"https:\/\/moncompte.actu.fr\" title=\"D\u00e9couvez Mon Actu\" rel=\"nofollow noopener\" data-trk=\"{&quot;cta&quot;:{&quot;action&quot;:&quot;https:\\\/\\\/moncompte.actu.fr&quot;,&quot;category&quot;:&quot;mon compte&quot;,&quot;from&quot;:&quot;article footer&quot;,&quot;name&quot;:&quot;Mon actu&quot;,&quot;type&quot;:&quot;cta&quot;}}\" target=\"_blank\">Mon Actu<\/a>.<\/p>\n<p>                    <script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"Par Hervine Mahaud Publi\u00e9 le 29 avr. 2026 \u00e0 18h00 La vague cor\u00e9enne continue de d\u00e9ferler \u00e0 Lille.&hellip;\n","protected":false},"author":2,"featured_media":110035,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[155,156,113,112,1289,1377,20732,755,23],"class_list":{"0":"post-110034","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-arts-et-design","8":"tag-arts-and-design","9":"tag-arts-et-design","10":"tag-divertissement","11":"tag-entertainment","12":"tag-lille","13":"tag-loisirs-culture","14":"tag-nouveaux-commerces","15":"tag-photographie","16":"tag-suisse"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_fr\/116488970328467838","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/110034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/comments?post=110034"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/110034\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media\/110035"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media?parent=110034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/categories?post=110034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/tags?post=110034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}