{"id":115438,"date":"2026-05-03T16:49:20","date_gmt":"2026-05-03T16:49:20","guid":{"rendered":"https:\/\/www.europesays.com\/ch-fr\/115438\/"},"modified":"2026-05-03T16:49:20","modified_gmt":"2026-05-03T16:49:20","slug":"le-fc-sion-corrige-saint-gall-et-se-rapproche-de-leurope-revivez-le-match-sur-le-nouvelliste","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-fr\/115438\/","title":{"rendered":"Le FC Sion corrige Saint-Gall et se rapproche de l\u2019Europe. Revivez le match sur \u00ab\u00a0Le Nouvelliste\u00a0\u00bb"},"content":{"rendered":"\n<p>Le FC Sion a confirm\u00e9 sa forme \u00e9tincelante en championnat et s\u2019est impos\u00e9 sur le score de 3-0 face au deuxi\u00e8me, le FC Saint-Gall. Une rencontre \u00e0 suivre en direct sur \u00abLe Nouvelliste\u00bb.<\/p>\n<p>      <img   alt=\"Logo_FC_Sion_1977.svg\" draggable=\"false\" loading=\"lazy\" decoding=\"async\" data-picture=\"true\" class=\"no-class nuxt-aio-img\" data-v-32c1ed04=\"\"\/>    <img   alt=\"Benjamin Kololli et le FC Sion ont \u00e9t\u00e9 particuli\u00e8rement efficace.\" draggable=\"false\" loading=\"lazy\" decoding=\"async\" data-picture=\"true\" class=\"no-class nuxt-aio-img\" data-v-32c1ed04=\"\"\/> <\/p>\n<p>\n                  Benjamin Kololli et le FC Sion ont \u00e9t\u00e9 particuli\u00e8rement efficace.\n                <\/p>\n<p>                  \u00a9 KEYSTONE \/ URS FLUEELER<br \/>\n                   <img   alt=\"Daschner au duel avec Nivokazi durant le match entre Saint-Gall et Sion.\" draggable=\"false\" loading=\"lazy\" decoding=\"async\" data-picture=\"true\" class=\"no-class nuxt-aio-img\" data-v-32c1ed04=\"\"\/> <\/p>\n<p>\n                  Daschner au duel avec Nivokazi durant le match entre Saint-Gall et Sion.\n                <\/p>\n<p>                  \u00a9 KEYSTONE \/ URS FLUEELER<br \/>\n                   <img   alt=\"Didier Tholot a d\u00e9j\u00e0 rempli ses objectifs cette saison mais peut d\u00e9sormais viser plus haut et croire \u00e0 la Coupe d'Europe.\" draggable=\"false\" loading=\"lazy\" decoding=\"async\" data-picture=\"true\" class=\"no-class nuxt-aio-img\" data-v-32c1ed04=\"\"\/> <\/p>\n<p>\n                  Didier Tholot a d\u00e9j\u00e0 rempli ses objectifs cette saison mais peut d\u00e9sormais viser plus haut et croire \u00e0 la Coupe d&rsquo;Europe.\n                <\/p>\n<p>                  \u00a9 KEYSTONE \/ CYRIL ZINGARO (archives)<br \/>\n                   <img   alt=\"C'est le logo du FC Saint-Gall.\" draggable=\"false\" loading=\"lazy\" decoding=\"async\" data-picture=\"true\" class=\"no-class nuxt-aio-img\" data-v-32c1ed04=\"\"\/> <\/p>\n<p>\n                  C&rsquo;est le logo du FC Saint-Gall.\n                <\/p>\n<p>                  keystone<br \/>\n                   <img   alt=\"Logo_FC_Sion_1977.svg\" draggable=\"false\" loading=\"lazy\" decoding=\"async\" data-picture=\"true\" class=\"no-class nuxt-aio-img\" data-v-32c1ed04=\"\"\/>    <img   alt=\"Benjamin Kololli et le FC Sion ont \u00e9t\u00e9 particuli\u00e8rement efficace.\" draggable=\"false\" loading=\"lazy\" decoding=\"async\" data-picture=\"true\" class=\"no-class nuxt-aio-img\" data-v-32c1ed04=\"\"\/> <\/p>\n<p>\n                  Benjamin Kololli et le FC Sion ont \u00e9t\u00e9 particuli\u00e8rement efficace.\n                <\/p>\n<p>                  \u00a9 KEYSTONE \/ URS FLUEELER<br \/>\n                   <img   alt=\"Daschner au duel avec Nivokazi durant le match entre Saint-Gall et Sion.\" draggable=\"false\" loading=\"lazy\" decoding=\"async\" data-picture=\"true\" class=\"no-class nuxt-aio-img\" data-v-32c1ed04=\"\"\/> <\/p>\n<p>\n                  Daschner au duel avec Nivokazi durant le match entre Saint-Gall et Sion.\n                <\/p>\n<p>                  \u00a9 KEYSTONE \/ URS FLUEELER<br \/>\n                   <img   alt=\"Didier Tholot a d\u00e9j\u00e0 rempli ses objectifs cette saison mais peut d\u00e9sormais viser plus haut et croire \u00e0 la Coupe d'Europe.\" draggable=\"false\" loading=\"lazy\" decoding=\"async\" data-picture=\"true\" class=\"no-class nuxt-aio-img\" data-v-32c1ed04=\"\"\/> <\/p>\n<p>\n                  Didier Tholot a d\u00e9j\u00e0 rempli ses objectifs cette saison mais peut d\u00e9sormais viser plus haut et croire \u00e0 la Coupe d&rsquo;Europe.\n                <\/p>\n<p>                  \u00a9 KEYSTONE \/ CYRIL ZINGARO (archives)<br \/>\n                   <img   alt=\"C'est le logo du FC Saint-Gall.\" draggable=\"false\" loading=\"lazy\" decoding=\"async\" data-picture=\"true\" class=\"no-class nuxt-aio-img\" data-v-32c1ed04=\"\"\/> <\/p>\n<p>\n                  C&rsquo;est le logo du FC Saint-Gall.\n                <\/p>\n<p>                  keystone<br \/>\n                   <img   alt=\"Logo_FC_Sion_1977.svg\" draggable=\"false\" loading=\"lazy\" decoding=\"async\" data-picture=\"true\" class=\"no-class nuxt-aio-img\" data-v-32c1ed04=\"\"\/>      <\/p>\n","protected":false},"excerpt":{"rendered":"Le FC Sion a confirm\u00e9 sa forme \u00e9tincelante en championnat et s\u2019est impos\u00e9 sur le score de 3-0&hellip;\n","protected":false},"author":2,"featured_media":115439,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[199,180,198,75,23],"class_list":{"0":"post-115438","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sports","8":"tag-ce-quil-sest-passe","9":"tag-fc-sion","10":"tag-info-brute","11":"tag-sports","12":"tag-suisse"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_fr\/116511674663469863","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/115438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/comments?post=115438"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/115438\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media\/115439"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media?parent=115438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/categories?post=115438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/tags?post=115438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}