{"id":117978,"date":"2026-05-05T11:56:09","date_gmt":"2026-05-05T11:56:09","guid":{"rendered":"https:\/\/www.europesays.com\/ch-fr\/117978\/"},"modified":"2026-05-05T11:56:09","modified_gmt":"2026-05-05T11:56:09","slug":"arnaud-toupense-revele-par-un-ptit-truc-en-plus-confie-etre-atteint-de-la-maladie-dalzheimer","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-fr\/117978\/","title":{"rendered":"Arnaud Toupense, r\u00e9v\u00e9l\u00e9 par \u00ab\u00a0Un p\u2019tit truc en plus\u00a0\u00bb, confie \u00eatre atteint de la maladie d\u2019Alzheimer"},"content":{"rendered":"<p>Son visage est d\u00e9sormais bien connu du public. R\u00e9v\u00e9l\u00e9 par le film\u00a0Un p\u2019tit truc en plus\u00a0il y a deux ans, Arnaud Toupense a \u00e9voqu\u00e9 son \u00e9tat de sant\u00e9 dans un documentaire diffus\u00e9 il y a quelques jours sur <a href=\"https:\/\/www.20minutes.fr\/dossier\/m6\" class=\"c-link c-link--is-underlined\" rel=\"nofollow noopener\" target=\"_blank\">M6<\/a>. Le <a href=\"https:\/\/www.20minutes.fr\/dossier\/acteur\" class=\"c-link c-link--is-underlined\" rel=\"nofollow noopener\" target=\"_blank\">com\u00e9dien<\/a> de 45 ans, atteint de <a href=\"https:\/\/www.20minutes.fr\/dossier\/trisomie\" class=\"c-link c-link--is-underlined\" rel=\"nofollow noopener\" target=\"_blank\">trisomie 21<\/a>, a expliqu\u00e9 souffrir \u00e9galement de la <a href=\"https:\/\/www.20minutes.fr\/dossier\/alzheimer\" class=\"c-link c-link--is-underlined\" rel=\"nofollow noopener\" target=\"_blank\">maladie d\u2019Alzheimer<\/a>. \u00ab\u00a0J\u2019ai un probl\u00e8me dans la t\u00eate. J\u2019ai peur de \u00e7a maintenant. Je perds l\u2019\u00e9quilibre en plus, a-t-il confi\u00e9.\u00a0Donc pour moi, c\u2019est encore plus dur et \u00e7a me rend nerveux.\u00a0\u00bb<\/p>\n<p>Le 23 avril, le comp\u00e8re d\u2019Artus avait d\u00e9j\u00e0 parl\u00e9 de la maladie dans les colonnes du <a href=\"https:\/\/www.leparisien.fr\/culture-loisirs\/cinema\/un-ptit-truc-en-plus-sur-m-6-mayane-sofian-stanislas-arnaud-que-deviennent-les-acteurs-de-la-comedie-dartus-23-04-2026-WIK2P2UVQNDG3AJOBZREIRPTQY.php\" rel=\"nofollow noopener\" target=\"_blank\" class=\"c-link c-link--is-underlined\">Parisien<\/a>. \u00ab\u00a0J\u2019ai tr\u00e8s peur, quand je l\u2019ai appris, j\u2019ai beaucoup pleur\u00e9\u00a0\u00bb, avait-il d\u00e9clar\u00e9.<\/p>\n<p>Un v\u00e9ritable carton<\/p>\n<p>L\u2019acteur avait attendri les spectateurs avec son r\u00f4le dans Un p\u2019tit truc en plus, \u00e0 la fois pour sa romance avec Marie et pour son amiti\u00e9 naissante avec Sylvain.\u00a0Arnaud Toupense a profit\u00e9 pleinement du carton de la com\u00e9die sign\u00e9e <a href=\"https:\/\/www.20minutes.fr\/arts-stars\/cinema\/artus\/\" class=\"c-link c-link--is-underlined\" rel=\"nofollow noopener\" target=\"_blank\">Artus<\/a>, qui a enregistr\u00e9 pr\u00e8s de 11\u00a0millions d\u2019entr\u00e9es en France.\u00a0Depuis, le com\u00e9dien a particip\u00e9 \u00e0 quelques tournages, dont\u00a0celui du t\u00e9l\u00e9film de <a href=\"https:\/\/www.20minutes.fr\/dossier\/tf1\" class=\"c-link c-link--is-underlined\" rel=\"nofollow noopener\" target=\"_blank\">TF1<\/a> Panique au grand magasin avec\u00a0Arnaud Ducret, Tom Villa, Isabelle Nanty, Mich\u00e8le Bernier, et <a href=\"https:\/\/www.20minutes.fr\/dossier\/franck_dubosc\" class=\"c-link c-link--is-underlined\" rel=\"nofollow noopener\" target=\"_blank\">Franck Dubosc<\/a>.<\/p>\n<p class=\"mb-m@xs text-l@xs\">En cliquant sur\u00ab J\u2019accepte \u00bb, vous acceptez le d\u00e9p\u00f4t de cookies par des services externes et aurez ainsi acc\u00e8s aux contenus de nos partenaires.<\/p>\n<p class=\"mb-xl@xs text-s@xs\">Plus d\u2019informations sur la page<a href=\"https:\/\/www.20minutes.fr\/gestion-cookies\" class=\"mx-xxs@xs color-ultramarine\" rel=\"nofollow noopener\" target=\"_blank\">Politique de gestion des cookies<\/a><\/p>\n<p>J\u2019accepte<\/p>\n<p>Selon la Fondation Recherche Alzheimer, les personnes atteintes de trisomie sont particuli\u00e8rement expos\u00e9es \u00e0 la maladie d\u2019Alzheimer. \u00ab\u00a0Un lien \u00e9troit unit ces deux syndromes, au point qu\u2019une personne porteuse de trisomie 21 a au moins vingt fois plus de risques qu\u2019une autre de d\u00e9velopper une maladie Alzheimer au seuil de la vieillesse\u00a0\u00bb, indique ainsi la Fondation <a href=\"https:\/\/alzheimer-recherche.org\/recherche-et-alzheimer\/alzheimer-et-trisomie-21-en-7-questions\/\" rel=\"nofollow noopener\" target=\"_blank\" class=\"c-link c-link--is-underlined\">sur son site Internet<\/a>.<\/p>\n<p>Des signes d\u00e8s 40 ans<\/p>\n<p>\u00ab\u00a0Les personnes porteuses de trisomie 21 ont des signes neuropathologiques de la maladie d\u2019Alzheimer d\u00e8s 40 ans avant m\u00eame l\u2019arriv\u00e9e du d\u00e9clin cognitif\u00a0\u00bb, pr\u00e9cise m\u00eame\u00a0Marie-Claude Potier, directeur de recherche au CNRS. Cette sp\u00e9cialiste explique que les patients trisomiques poss\u00e8dent trois chromosomes 21 au lieu de deux. Or, ces chromosomes sont eux-m\u00eames porteurs du g\u00e8ne APP (prot\u00e9ine pr\u00e9curseur de l\u2019amylo\u00efde) responsable de l\u00e9sions li\u00e9es \u00e0 Alzheimer.<\/p>\n<p>Pour lutter contre le stress de sa double pathologie, Arnaud Toupense a choisi de se r\u00e9fugier dans l\u2019art au travers la poterie et le chant. Il esp\u00e8re \u00e9galement continuer de tourner et d\u2019appara\u00eetre dans des films.<\/p>\n","protected":false},"excerpt":{"rendered":"Son visage est d\u00e9sormais bien connu du public. R\u00e9v\u00e9l\u00e9 par le film\u00a0Un p\u2019tit truc en plus\u00a0il y a&hellip;\n","protected":false},"author":2,"featured_media":117979,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[3358,4706,158,157,384,113,112,159,23,12306],"class_list":{"0":"post-117978","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-people","8":"tag-alzheimer","9":"tag-artus","10":"tag-celebrities","11":"tag-celebrity","12":"tag-cinema","13":"tag-divertissement","14":"tag-entertainment","15":"tag-people","16":"tag-suisse","17":"tag-trisomie"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_fr\/116521847090778088","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/117978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/comments?post=117978"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/117978\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media\/117979"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media?parent=117978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/categories?post=117978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/tags?post=117978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}