{"id":121990,"date":"2026-05-08T00:00:11","date_gmt":"2026-05-08T00:00:11","guid":{"rendered":"https:\/\/www.europesays.com\/ch-fr\/121990\/"},"modified":"2026-05-08T00:00:11","modified_gmt":"2026-05-08T00:00:11","slug":"je-ne-pouvais-plus-vivre-cette-folie-lex-femme-de-renaud-devoile-la-raison-qui-la-pousse-a-quitter-le-chanteur-francais","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-fr\/121990\/","title":{"rendered":"\u201dJe ne pouvais plus vivre cette folie\u201d: l\u2019ex-femme de Renaud d\u00e9voile la raison qui l\u2019a pouss\u00e9 \u00e0 quitter le chanteur fran\u00e7ais"},"content":{"rendered":"<p>Renaud traumatis\u00e9 \u00e0 Moscou<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Pendant 2h20, le documentaire reviendra sur certains moments forts de sa vie. Notamment sur les origines de sa rupture avec son ex-femme et sur son addiction \u00e0 l&rsquo;alcool. Deux p\u00e9riodes compliqu\u00e9es qui sont li\u00e9es \u00e0 un seul et m\u00eame \u00e9v\u00e8nement survenu \u00e0 1985 \u00e0 Moscou.<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Capitale de l&rsquo;URSS \u00e0 cette \u00e9poque, la ville russe avait accueilli Renaud dans le cadre du Festival mondial des jeunes et des \u00e9tudiants pour donner une s\u00e9rie de concerts. Le deuxi\u00e8me avait alors traumatis\u00e9 le chanteur lorsque un tiers des 10 000 spectateurs pr\u00e9sents se sont lev\u00e9s pour quitter les lieux au moment o\u00f9 il a interpr\u00e9t\u00e9 son titre \u00ab\u00a0D\u00e9serteur\u00a0\u00bb.<\/p>\n<p>Parano\u00efa aigu\u00eb, alcool et rupture<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">\u00c0 partir de cette date, le p\u00e8re de Lolita S\u00e9chan d\u00e9veloppera une parano\u00efa aigu\u00eb en \u00e9tant convaincu que sa vie \u00e9tait en danger. \u00ab\u00a0Il \u00e9tait persuad\u00e9 qu&rsquo;un attentat se pr\u00e9parait contre sa famille, On vivait un cauchemar\u00a0\u00bb, se souvient Dominique Quilichini. Diagnostiqu\u00e9 d&rsquo;une maladie, \u00ab\u00a0des d\u00e9lires parano\u00efaques en secteur\u00a0\u00bb, l&rsquo;auteur-compositeur-interpr\u00e8te d\u00e9cide alors de se r\u00e9fugier dans l&rsquo;alcool.<\/p>\n<p><a href=\"https:\/\/www.parismatch.be\/actualites\/people\/2025\/10\/10\/il-a-besoin-dun-comportement-extreme-renaud-est-parvenu-a-sortir-de-lalcool-mais-a-developpe-deux-autres-addictions-K564MHUMBFFBDNHYDT2CU7LENU\/\" target=\"_self\" class=\"ap-StoryInterstitialLink ap-StoryElement ap-StoryElement--mb\" rel=\"nofollow noopener\">\u00ab\u00a0Il a besoin d&rsquo;un comportement extr\u00eame\u00a0\u00bb : Renaud est parvenu \u00e0 sortir de l&rsquo;alcool, mais a d\u00e9velopp\u00e9 deux autres addictions<\/a><\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">\u00ab\u00a0Pas pour l&rsquo;amour de l&rsquo;alcool\u00a0\u00bb, insiste son ex-femme. \u00ab\u00a0C&rsquo;\u00e9tait son m\u00e9dicament. Il me disait toujours,il faut que je tue mes d\u00e9mons. Malheureusement, cette d\u00e9cision n&rsquo;a pas eu l&rsquo;effet escompt\u00e9 puisque sa compagne a d\u00e9cid\u00e9 de le quitter apr\u00e8s avoir notamment \u00e9t\u00e9 accus\u00e9e de faire partie de ses ennemis. \u00ab\u00a0Il savait qu&rsquo;il n&rsquo;y avait aucun d\u00e9samour, je l&rsquo;ai quitt\u00e9 parce que je ne pouvais plus vivre cette folie\u00a0\u00bb, regrette-t-elle.<\/p>\n","protected":false},"excerpt":{"rendered":"Renaud traumatis\u00e9 \u00e0 Moscou Pendant 2h20, le documentaire reviendra sur certains moments forts de sa vie. Notamment sur&hellip;\n","protected":false},"author":2,"featured_media":121991,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[896,158,157,113,112,30,141,159,21770,23],"class_list":{"0":"post-121990","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-people","8":"tag-celebrite","9":"tag-celebrities","10":"tag-celebrity","11":"tag-divertissement","12":"tag-entertainment","13":"tag-france","14":"tag-musique","15":"tag-people","16":"tag-renaud","17":"tag-suisse"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_fr\/116536018398347498","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/121990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/comments?post=121990"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/121990\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media\/121991"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media?parent=121990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/categories?post=121990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/tags?post=121990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}