{"id":128451,"date":"2026-05-12T17:22:13","date_gmt":"2026-05-12T17:22:13","guid":{"rendered":"https:\/\/www.europesays.com\/ch-fr\/128451\/"},"modified":"2026-05-12T17:22:13","modified_gmt":"2026-05-12T17:22:13","slug":"narvaez-simpose-ciccone-gagne-le-maillot-rose","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-fr\/128451\/","title":{"rendered":"Narvaez s\u2019impose, Ciccone gagne le maillot rose"},"content":{"rendered":"\n<p>        \u2013   <\/p>\n<p>  Narvaez console UAE, Ciccone enchante l\u2019Italie <\/p>\n<p class=\"lead regular externalicon-big astro-mrojhlls\"> L\u2019\u00c9quatorien a remport\u00e9 la quatri\u00e8me \u00e9tape de la comp\u00e9tition mardi \u00e0 Cosenza. L\u2019Italien Giulio Ciccone prend la t\u00eate du classement g\u00e9n\u00e9ral.   <\/p>\n<p>              Mis \u00e0 jour il y a 21 minutes                  <img decoding=\"async\" loading=\"eager\" fetchpriority=\"high\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/05\/D4wfOk4KqgW8cyT3F9nRbL.jpg\" data-image-url=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/05\/D4wfOk4KqgW8cyT3F9nRbL.jpg\" alt=\"Jhonatan Narvaez (UAE Team Emirates-XRG) l\u00e8ve les bras en signe de victoire lors de la 4e \u00e9tape du Giro d\u2019Italia 2026 \u00e0 Cosenza, Italie.\" title=\"Jhonatan Narvaez (UAE Team Emirates-XRG) l\u00e8ve les bras en signe de victoire lors de la 4e \u00e9tape du Giro d\u2019Italia 2026 \u00e0 Cosenza, Italie.\" class=\"ResponsiveImage responsive-image astro-lrzy7jfn\" style=\"background-color:#5D565B\" onload=\"this.style.backgroundColor = &quot;transparent&quot;\"\/>         <\/p>\n<p>Le champion d\u2019\u00c9quateur, 29\u00a0ans, est un ancien \u00e9clop\u00e9 qui a rat\u00e9 tout le d\u00e9but de saison \u00e0 cause de plusieurs fractures aux vert\u00e8bres.<\/p>\n<p>AFP\/Luca Bettini<\/p>\n<p class=\"articleParagraph externalicon-big focus _content-width article-element astro-g2qwsodm astro-hwk6bfo3\">\u00abOn peut \u00eatre heureux maintenant.\u00bb Apr\u00e8s un d\u00e9but de Giro cauchemardesque, <a class=\"noExternalIcon astro-hwk6bfo3\" target=\"_self\" href=\"https:\/\/www.24heures.ch\/cyclisme-la-1re-etape-du-giro-pour-narvaez-pogacar-se-montre-deja-868554102156\" data-article-link=\"https:\/\/www.24heures.ch\/cyclisme-la-1re-etape-du-giro-pour-narvaez-pogacar-se-montre-deja-868554102156\" rel=\"nofollow noopener\">Jhonatan Narvaez<\/a> a rendu le sourire \u00e0 l\u2019\u00e9quipe UAE en remportant la quatri\u00e8me \u00e9tape mardi \u00e0 <a class=\" astro-hwk6bfo3\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.giroditalia.it\/fr\/\" data-article-link=\"https:\/\/www.giroditalia.it\/fr\/\">Cosenza,<\/a> o\u00f9 Giulio Ciccone s\u2019est par\u00e9 de <a class=\"noExternalIcon astro-hwk6bfo3\" target=\"_self\" href=\"https:\/\/www.24heures.ch\/tour-ditalie-guillermo-thomas-silva-remporte-la-2e-etape-636707985146\" data-article-link=\"https:\/\/www.24heures.ch\/tour-ditalie-guillermo-thomas-silva-remporte-la-2e-etape-636707985146\" rel=\"nofollow noopener\">rose<\/a> \u00e0 point nomm\u00e9 pour cette premi\u00e8re journ\u00e9e en Italie.<\/p>\n<p class=\"hint astro-ep4xc566\">\u00c0 ce stade, vous trouverez des contenus externes suppl\u00e9mentaires. Si vous acceptez que des cookies soient plac\u00e9s par des fournisseurs externes et que des donn\u00e9es personnelles soient ainsi transmises \u00e0 ces derniers, vous devez autoriser tous les cookies et afficher directement le contenu externe.<\/p>\n<p>  Autoriser les cookies   Plus d&rsquo;infos    <\/p>\n<p class=\"articleParagraph externalicon-big focus _content-width article-element astro-g2qwsodm astro-hwk6bfo3\">Jusque-l\u00e0, cette 109e\u00a0\u00e9dition avait \u00e9t\u00e9 une nuit sans fin pour UAE qui a perdu trois coureurs dans une terrible chute collective samedi, Marc Soler et Jay Vine, victimes tous deux de fractures, ainsi que leur leader, Adam Yates.<\/p>\n<p class=\"articleParagraph externalicon-big focus _content-width article-element astro-g2qwsodm astro-hwk6bfo3\">Deux ans apr\u00e8s le triomphe de Tadej Pogacar, absent cette ann\u00e9e, il n\u2019y avait plus grand-chose \u00e0 esp\u00e9rer si ce n\u2019est viser des \u00e9tapes. Et la lumi\u00e8re a jailli d\u00e8s le retour du Giro sur le sol italien, apr\u00e8s trois premi\u00e8res \u00e9tapes en Bulgarie, avec la victoire de Jhonatan Narvaez.<\/p>\n<p>  \u00abCette victoire signifie \u00e9norm\u00e9ment pour moi\u00bb<\/p>\n<p class=\"articleParagraph externalicon-big focus _content-width article-element astro-g2qwsodm astro-hwk6bfo3\">Le champion d\u2019\u00c9quateur, 29\u00a0ans, est lui-m\u00eame un ancien \u00e9clop\u00e9 qui a rat\u00e9 tout le d\u00e9but de saison \u00e0 cause de plusieurs fractures aux vert\u00e8bres apr\u00e8s un vilain crash le 24\u00a0janvier au Tour Down Under.<\/p>\n<p class=\"articleParagraph externalicon-big focus _content-width article-element astro-g2qwsodm astro-hwk6bfo3\">\u00abCette victoire signifie \u00e9norm\u00e9ment pour moi, apr\u00e8s avoir mis trois mois \u00e0 revenir\u00bb, a expliqu\u00e9 celui qui n\u2019avait plus couru depuis l\u2019Australie, avant de d\u00e9dier son succ\u00e8s \u00e0 ses co\u00e9quipiers tomb\u00e9s samedi en Bulgarie.<\/p>\n<p class=\"articleParagraph externalicon-big focus _content-width article-element astro-g2qwsodm astro-hwk6bfo3\">\u00abC\u2019est difficile, car ils ont tous boss\u00e9 tellement dur pour arriver ici en bonne condition. Aujourd\u2019hui on gagne, on peut \u00eatre heureux maintenant\u00bb, a ajout\u00e9 l\u2019\u00c9quatorien, un des lanceurs habituels de Pogacar.<\/p>\n<p class=\"articleParagraph externalicon-big focus _content-width article-element astro-g2qwsodm astro-hwk6bfo3\">Mardi, il a r\u00e9gl\u00e9 un peloton duquel avaient disparu tous les principaux sprinteurs, l\u00e2ch\u00e9s dans le col de Cozzo Tunno, plac\u00e9 \u00e0 la mi-\u00e9tape, sous le tempo infernal de l\u2019\u00e9quipe Movistar qui a m\u00eame fait souffrir Egan Bernal.<\/p>\n<p>  \u00abC\u2019est un sentiment fabuleux\u00bb<\/p>\n<p class=\"articleParagraph externalicon-big focus _content-width article-element astro-g2qwsodm astro-hwk6bfo3\">Arnaud De Lie, qui allait ensuite abandonner tout comme Kaden Groves en d\u00e9but d\u2019\u00e9tape, a \u00e9t\u00e9 le premier \u00e0 l\u00e2cher avec le bodybuild\u00e9 Dylan Groenewegen. Puis ce fut au tour de Jonathan Milan, Paul Magnier et enfin Tobias Lund Andresen de c\u00e9der, mais aussi du maillot rose, l\u2019Uruguayen Thomas Silva.<\/p>\n<p class=\"articleParagraph externalicon-big focus _content-width article-element astro-g2qwsodm astro-hwk6bfo3\">La d\u00e9faillance de Silva a profit\u00e9 \u00e0 Giulio Ciccone qui a d\u2019abord grappill\u00e9 quelques secondes de bonifications au sprint Red Bull, avant de compl\u00e9ter sa conqu\u00eate du maillot rose en prenant la troisi\u00e8me place derri\u00e8re Narvaez et le V\u00e9n\u00e9zu\u00e9lien Orluis Aular, qui s\u2019\u00e9tait lanc\u00e9 de trop loin.<\/p>\n<p class=\"articleParagraph externalicon-big focus _content-width article-element astro-g2qwsodm astro-hwk6bfo3\">Pour l\u2019Italie, la prise de pouvoir du grimpeur de Lidl-Trek ne pouvait pas mieux tomber. Ciccone, qui avait d\u00e9j\u00e0 port\u00e9 le maillot jaune sur le Tour de France pendant deux jours en 2019, mais jamais le rose, \u00e9tait lui-m\u00eame tr\u00e8s \u00e9mu.<\/p>\n<p class=\"articleParagraph externalicon-big focus _content-width article-element astro-g2qwsodm astro-hwk6bfo3\">\u00abC\u2019est un sentiment fabuleux. Je r\u00eavais de ce maillot depuis tout petit. Je r\u00e9alise un r\u00eave d\u2019enfant aujourd\u2019hui, \u00e0 un moment o\u00f9 je ne m\u2019y attendais pas, apr\u00e8s des moments difficiles, comme l\u2019an dernier avec mon crash\u00bb au Giro, a soulign\u00e9 l\u2019Italien de 31\u00a0ans.<\/p>\n<p class=\"articleParagraph externalicon-big focus _content-width article-element astro-g2qwsodm astro-hwk6bfo3\">En 2025, il \u00e9tait arriv\u00e9 avec des ambitions de podium avant d\u2019abandonner en cours de route. Cette ann\u00e9e, il est venu seulement pour gagner des \u00e9tapes et laisser le leadership pour le g\u00e9n\u00e9ral dans son \u00e9quipe \u00e0 Derek Gee-West.<\/p>\n<p>  La possibilit\u00e9 de d\u00e9crocher le rose<\/p>\n<p class=\"articleParagraph externalicon-big focus _content-width article-element astro-g2qwsodm astro-hwk6bfo3\">Mais la possibilit\u00e9 de d\u00e9crocher le rose, alors que les 34\u00a0premiers se tenaient en dix secondes au classement g\u00e9n\u00e9ral mardi matin, a r\u00e9veill\u00e9 son app\u00e9tit, d\u00e9cupl\u00e9 lorsque les sprinteurs, dont son co\u00e9quipier Jonathan Milan, ont disparu dans le Cozzo Tunno.<\/p>\n<p class=\"articleParagraph externalicon-big focus _content-width article-element astro-g2qwsodm astro-hwk6bfo3\">Et voil\u00e0 le meilleur grimpeur du Tour de France 2023 v\u00eatu du maillot rose qu\u2019il d\u00e9fendra avec vigueur mercredi lors d\u2019une cinqui\u00e8me \u00e9tape accident\u00e9e entre Praia a Mare et Potenza. Avec le r\u00eave de le porter encore vendredi lors de la premi\u00e8re \u00e9tape de montagne dans les Abruzzes, sa r\u00e9gion natale.<\/p>\n<p class=\"boxtitle astro-42aj3uwb astro-hwk6bfo3\">Sur le Tour d\u2019Italie<\/p>\n","protected":false},"excerpt":{"rendered":"\u2013 Narvaez console UAE, Ciccone enchante l\u2019Italie L\u2019\u00c9quatorien a remport\u00e9 la quatri\u00e8me \u00e9tape de la comp\u00e9tition mardi \u00e0&hellip;\n","protected":false},"author":2,"featured_media":128452,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[195,11344,75,23],"class_list":{"0":"post-128451","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sports","8":"tag-content-en-continu","9":"tag-inspiration","10":"tag-sports","11":"tag-suisse"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_fr\/116562765342760901","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/128451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/comments?post=128451"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/128451\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media\/128452"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media?parent=128451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/categories?post=128451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/tags?post=128451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}