{"id":128774,"date":"2026-05-12T22:30:18","date_gmt":"2026-05-12T22:30:18","guid":{"rendered":"https:\/\/www.europesays.com\/ch-fr\/128774\/"},"modified":"2026-05-12T22:30:18","modified_gmt":"2026-05-12T22:30:18","slug":"le-dernier-teaser-de-sony-presente-les-ameliorations-apportees-a-lappareil-photo-du-xperia-1-viii-avant-son-lancement","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-fr\/128774\/","title":{"rendered":"Le dernier teaser de Sony pr\u00e9sente les am\u00e9liorations apport\u00e9es \u00e0 l&rsquo;appareil photo du Xperia 1 VIII avant son lancement"},"content":{"rendered":"<p class=\"bodytext\">Sony fera sa prochaine annonce de produit Xperia le 13 mai. Plus pr\u00e9cis\u00e9ment, l&rsquo;entreprise donnera le coup d&rsquo;envoi de son \u00e9v\u00e9nement produit \u00e0 02h00 UTC. D&rsquo;apr\u00e8s les <a href=\"http:\/\/www.notebookcheck.net\/Sony-Xperia-Announcement-event-runtime-spotted-on-eve-of-Xperia-1-VIII-launch.1293944.0.html\" target=\"_self\" class=\"internal-link\" rel=\"nofollow noopener\">l&rsquo;air du temps<\/a>cette ann\u00e9e, la pr\u00e9sentation des produits Xperia sera relativement courte.<\/p>\n<p class=\"bodytext\">Hier, Sony a inform\u00e9 les fans qu&rsquo;ils devaient se pr\u00e9parer <a href=\"http:\/\/www.notebookcheck.net\/Brace-yourself-for-a-seismic-shift-Sony-Xperia-1-VIII-promises-massive-camera-upgrades-in-new-official-teaser.1293717.0.html\" target=\"_self\" class=\"internal-link\" rel=\"nofollow noopener\">\u00e0 un changement sismique<\/a>. En fin de compte, l&rsquo;entreprise n&rsquo;a pas donn\u00e9 plus de d\u00e9tails. Cependant, le contenu de la vid\u00e9o de 21 secondes semblait se concentrer sur les cam\u00e9ras arri\u00e8re du Xperia 1 VIII, dont la rumeur circule. Aujourd&rsquo;hui, Sony a partag\u00e9 un nouveau teaser sur ses r\u00e9seaux sociaux.<\/p>\n","protected":false},"excerpt":{"rendered":"Sony fera sa prochaine annonce de produit Xperia le 13 mai. Plus pr\u00e9cis\u00e9ment, l&rsquo;entreprise donnera le coup d&rsquo;envoi&hellip;\n","protected":false},"author":2,"featured_media":128775,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[272,74,70,72,71,61,57,59,58,273,1146,33394,23,60,62,73,33654,33395],"class_list":{"0":"post-128774","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sciences-et-technologies","8":"tag-android","9":"tag-informations-sur-des-ordinateurs-portatifs","10":"tag-nouvelles","11":"tag-rapport","12":"tag-revues","13":"tag-science","14":"tag-science-and-technology","15":"tag-sciences","16":"tag-sciences-et-technologies","17":"tag-smartphone","18":"tag-sony","19":"tag-sony-xperia","20":"tag-suisse","21":"tag-technologies","22":"tag-technology","23":"tag-test","24":"tag-une-nouvelle-trinite-sest-reveillee","25":"tag-xperia-1-viii"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_fr\/116563976198637405","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/128774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/comments?post=128774"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/128774\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media\/128775"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media?parent=128774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/categories?post=128774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/tags?post=128774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}