{"id":128797,"date":"2026-05-12T23:00:26","date_gmt":"2026-05-12T23:00:26","guid":{"rendered":"https:\/\/www.europesays.com\/ch-fr\/128797\/"},"modified":"2026-05-12T23:00:26","modified_gmt":"2026-05-12T23:00:26","slug":"the-rookie-cest-officiel-un-spin-off-va-bien-voir-le-jour","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-fr\/128797\/","title":{"rendered":"The Rookie : C\u2019est officiel, un spin-off va bien voir le jour"},"content":{"rendered":"<p>Apr\u00e8s une huiti\u00e8me saison explosive et <a href=\"https:\/\/www.programme-tv.net\/news\/series-tv\/401522-the-rookie-la-saison-8-tue-un-personnage-present-depuis-quatre-ans-son-interprete-reagit\/\" data-api-deeplink=\"teleloisirs:\/\/news\/401522\" rel=\"nofollow noopener\" target=\"_blank\">la mort d\u2019un personnage pr\u00e9sent depuis quatre ans<\/a>, la s\u00e9rie <a href=\"https:\/\/www.programme-tv.net\/news\/series-tv\/400733-the-rookie-la-serie-avec-nathan-fillion-est-renouvelee-pour-une-saison-9\/\" data-api-deeplink=\"teleloisirs:\/\/news\/400733\" rel=\"nofollow noopener\" target=\"_blank\">The Rookie a \u00e9t\u00e9 renouvel\u00e9e pour une neuvi\u00e8me saison.<\/a> Son cr\u00e9ateur, Alexi Hawley, a m\u00eame r\u00e9v\u00e9l\u00e9<a href=\"https:\/\/www.programme-tv.net\/news\/series-tv\/401864-le-createur-de-the-rookie-reagit-au-final-choc-de-la-saison-8-et-devoile-ce-qui-attend-les-fans-dans-la-saison-9\/\" data-api-deeplink=\"teleloisirs:\/\/news\/401864\" rel=\"nofollow noopener\" target=\"_blank\"> ce qui allait se passer dans cette nouvelle salve d\u2019\u00e9pisodes. <\/a>Mais les bonnes nouvelles ne s\u2019arr\u00eatent pas l\u00e0, puisqu\u2019un spin-off a officiellement \u00e9t\u00e9 command\u00e9 par la cha\u00eene am\u00e9ricaine ABC ; il s\u2019agit de The Rookie : North.<\/p>\n<p>Le m\u00e9dia am\u00e9ricain <a href=\"https:\/\/www.tvline.com\/2169897\/the-rookie-spin-off-jay-ellis-series-order-abc\/\" rel=\"nofollow noopener\" target=\"_blank\">TV Line<\/a> a r\u00e9v\u00e9l\u00e9 que ce spin-off serait centr\u00e9 sur Alex Holland, jou\u00e9 par le com\u00e9dien Jay Ellis. La distribution comprend aussi Chris Sullivan (This Is Us), Karen Fukuhara (The Boys), Froy Gutierrez (Cruel Summer), Janet Montgomery (New Amsterdam), Mya Lowe (Yellowjackets) et Malik Watson.<\/p>\n<p>De quoi va parler le prochain spin-off de The Rookie ?<\/p>\n<p>Le synopsis officiel de The Rookie : North r\u00e9v\u00e8le qu\u2019Alex Holland est en pleine crise de la quarantaine. Mais pour lui, elle ne m\u00e9rite pas d\u2019\u00eatre v\u00e9cue. Sauf qu\u2019apr\u00e8s un violent cambriolage, tout se bouscule. Cet \u00e9v\u00e9nement traumatisant r\u00e9veille en lui une vocation enfouie : celle de se battre contre une vie d\u2019engagements non tenus.<\/p>\n<p>Alex Holland rejoint alors la police du comt\u00e9 de Pierce, devenant ainsi la recrue la plus \u00e2g\u00e9e. Ses patrouilles se d\u00e9roulent dans des zones urbaines c\u00f4ti\u00e8res, mais aussi dans des for\u00eats recul\u00e9es, emp\u00eachant les renforts d&rsquo;arriver rapidement sur place. Face \u00e0 son inspecteur sceptique sur ses capacit\u00e9s \u00e0 \u00eatre un bon policier, Alex doit prouver qu\u2019il m\u00e9rite sa place.<\/p>\n<p>Nathan Fillion fera-t-il partie du spin-off de The Rookie ?<\/p>\n<p>Avant que le spin-off soit officiellement command\u00e9 par la cha\u00eene ABC, Alexi Hawley a fait savoir que Nathan Fillion y fera une apparition dans le r\u00f4le de John Nolan. \u00ab\u00a0Je ne pense pas que ce soit un spoiler de dire qu\u2019il y a un petit lien avec Nathan dans l&rsquo;\u00e9pisode pilote\u00a0\u00bb, a-t-il d\u00e9clar\u00e9 au site am\u00e9ricain <a href=\"https:\/\/deadline.com\/2026\/05\/the-rookie-north-spinoff-crossovers-nathan-fillion-pilot-1236879187\/\" rel=\"nofollow noopener\" target=\"_blank\">Deadline<\/a>. \u00c0 noter que Nathan Fillion est \u00e9galement producteur ex\u00e9cutif de la s\u00e9rie d\u00e9riv\u00e9e.<\/p>\n<p>Pour le moment, aucune date de sortie n\u2019a \u00e9t\u00e9 communiqu\u00e9e concernant The Rookie : North qui succ\u00e8de donc \u00e0 The Rookie : Feds, premier spin-off arr\u00eat\u00e9 apr\u00e8s une saison en 2023. Le tournage de cette nouvelle s\u00e9rie d\u00e9riv\u00e9e n\u2019ayant pas encore commenc\u00e9, les fans vont devoir prendre leur mal en patience avant de d\u00e9couvrir les premi\u00e8res images de cette nouvelle s\u00e9rie.<\/p>\n<p>Article \u00e9crit avec la collaboration de 6m\u00e9dias.<\/p>\n","protected":false},"excerpt":{"rendered":"Apr\u00e8s une huiti\u00e8me saison explosive et la mort d\u2019un personnage pr\u00e9sent depuis quatre ans, la s\u00e9rie The Rookie&hellip;\n","protected":false},"author":2,"featured_media":128798,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[489,113,112,24505,486,485,23,487,142,33662,33661],"class_list":{"0":"post-128797","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-television","8":"tag-commentaire","9":"tag-divertissement","10":"tag-entertainment","11":"tag-nathan-fillion","12":"tag-netflix","13":"tag-pub-streaming-netflix","14":"tag-suisse","15":"tag-svod","16":"tag-television","17":"tag-the-rookie-fbi","18":"tag-the-rookie-1099542479"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_fr\/116564094000627836","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/128797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/comments?post=128797"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/128797\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media\/128798"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media?parent=128797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/categories?post=128797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/tags?post=128797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}