{"id":128953,"date":"2026-05-13T02:44:09","date_gmt":"2026-05-13T02:44:09","guid":{"rendered":"https:\/\/www.europesays.com\/ch-fr\/128953\/"},"modified":"2026-05-13T02:44:09","modified_gmt":"2026-05-13T02:44:09","slug":"la-venus-electrique-le-film-cinemas-le-telegramme-quotidien-regional-de-bretagne","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-fr\/128953\/","title":{"rendered":"La V\u00e9nus \u00e9lectrique le film &#8211; Cin\u00e9mas &#8211; Le T\u00e9l\u00e9gramme : quotidien regional de Bretagne"},"content":{"rendered":"<p>Paris, 1928. Antoine Balestro, jeune peintre en vogue, n&rsquo;arrive plus \u00e0 travailler depuis la mort de son \u00e9pouse et d\u00e9sesp\u00e8re Armand, son galeriste. Un soir d&rsquo;ivresse, Antoine tente d&rsquo;entrer en contact avec sa femme par l&rsquo;interm\u00e9diaire d&rsquo;une voyante. Sans le savoir, il parle en r\u00e9alit\u00e9 avec Suzanne, une modeste foraine qui s&rsquo;est gliss\u00e9e dans la roulotte pour y voler de la nourriture. Suzanne se r\u00e9v\u00e8le dou\u00e9e pour l&rsquo;imposture et, rapidement second\u00e9e par Armand, elle encha\u00eene les fausses s\u00e9ances. Peu \u00e0 peu, Antoine retrouve l&rsquo;inspiration, mais pour Suzanne les choses se compliquent alors qu&rsquo;elle tombe doucement amoureuse de l&rsquo;homme qu&rsquo;elle manipule&#8230; Ce film est pr\u00e9sent\u00e9 hors-comp\u00e9tition au Festival de Cannes 2026 et en fait l&rsquo;ouverture.<\/p>\n<p>Date de sortie : 12\/05\/2026De : Pierre SalvadoriActeurs : Pio Marma\u00efAna\u00efs DemoustierGilles LelloucheVimala PonsGustave KervernMadeleine BaudotCharline CerriRomain Lefebvre<\/p>\n<p>2h02 &#8211; Com\u00e9die dramatique &#8211; France, Belgique<\/p>\n","protected":false},"excerpt":{"rendered":"Paris, 1928. Antoine Balestro, jeune peintre en vogue, n&rsquo;arrive plus \u00e0 travailler depuis la mort de son \u00e9pouse&hellip;\n","protected":false},"author":2,"featured_media":47216,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[16306,113,112,139,138,16305,137,23],"class_list":{"0":"post-128953","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-films","8":"tag-cinemas","9":"tag-divertissement","10":"tag-entertainment","11":"tag-film","12":"tag-films","13":"tag-homes","14":"tag-movies","15":"tag-suisse"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_fr\/116564974898510764","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/128953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/comments?post=128953"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/128953\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media\/47216"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media?parent=128953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/categories?post=128953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/tags?post=128953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}