{"id":27870,"date":"2026-03-02T01:20:07","date_gmt":"2026-03-02T01:20:07","guid":{"rendered":"https:\/\/www.europesays.com\/ch-fr\/27870\/"},"modified":"2026-03-02T01:20:07","modified_gmt":"2026-03-02T01:20:07","slug":"au-lam-a-villeneuve-dascq-kandinsky-et-les-secrets-de-son-inspiration","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-fr\/27870\/","title":{"rendered":"Au LaM, \u00e0 Villeneuve-d\u2019Ascq, Kandinsky et les secrets de son inspiration"},"content":{"rendered":"<p>\n    EXPOSITION &#8211; Un parcours in\u00e9dit sur le pionnier russe de l\u2019abstraction met en lumi\u00e8re son rapport \u00e0 la photographie et \u00e0 l\u2019archive personnelle. Un \u00e9clairage passionnant.<\/p>\n<p class=\"fig-paragraph\">L\u2019exposition de la Philharmonie de Paris,\u00a0<a href=\"http:\/\/www.lefigaro.fr\/arts-expositions\/a-la-philharmonie-de-paris-kandinsky-s-admire-et-s-ecoute-20251017\" data-fig-type=\"Article\" data-gtm-custom-categorie=\"navigation\" data-gtm-custom-action=\"crossclick\" data-gtm-custom-label=\"Contextuel\" data-gtm-event=\"customEventSPE\" data-fig-domain=\"LEFIGARO\" rel=\"nofollow noopener\" target=\"_blank\">\u00ab\u00a0Kandinsky. La musique des couleurs\u00a0\u00bb<\/a>, belle composition d\u2019id\u00e9es, d\u2019\u0153uvres cl\u00e9s et de sc\u00e9nographie lumineuse, s\u2019est achev\u00e9e le 1er\u00a0f\u00e9vrier. Et d\u00e9j\u00e0 une autre exposition Kandinsky\u00a0? C\u2019est cette fois au LaM \u00e0 Villeneuve-d\u2019Ascq (Nord). Outre le fait que Beaubourg est ferm\u00e9 et que donc ses collections somptueuses sont disponibles, c\u2019est aussi l\u2019occasion d\u2019explorer d\u2019autres facettes du pionnier de l\u2019abstraction. \u00ab\u00a0Kandinsky face aux images\u00a0\u00bb rel\u00e8ve ce d\u00e9fi et pr\u00e9sente dans les salles modernes du LaM fra\u00eechement restaur\u00e9 tout le r\u00e9pertoire d\u2019images qui a suivi et nourri le peintre, un v\u00e9ritable tr\u00e9sor cach\u00e9 de sources et de r\u00e9f\u00e9rences jamais montr\u00e9 dans cette ampleur en France.<\/p>\n<p class=\"fig-paragraph\">S\u2019appuyant sur les apports des \u00ab\u00a0visual studies\u00a0\u00bb &#8211; discipline anglo-saxonne &#8211; qui redonnent tout leur pouvoir aux images, des plus modestes au plus \u00e9labor\u00e9es, des plus vernaculaires aux plus \u00e9rudites, les trois commissaires, Angela Lampe du Centre Pompidou\u2026<\/p>\n<p class=\"fig-premium-paywall__infos\">\n        Cet article est r\u00e9serv\u00e9 aux abonn\u00e9s.        Il vous reste 75% \u00e0 d\u00e9couvrir.\n    <\/p>\n<p>                <img  data- alt=\"Le Figaro\" class=\"fig-img--complete fig-img\"\/><\/p>\n<p class=\"fig-premium-paywall__title\">Vous avez envie de lire la suite ?<\/p>\n<p class=\"fig-premium-paywall__subtitle\">D\u00e9bloquez tous les articles imm\u00e9diatement.<\/p>\n<p class=\"fig-premium-paywall__connect\">\n                D\u00e9j\u00e0 abonn\u00e9\u00a0?                <a class=\"fig-premium-paywall__connect-link\" href=\"https:\/\/connect.lefigaro.fr\/login?client=horizon_web&amp;type=main&amp;redirect_uri=https%3A%2F%2Fwww.lefigaro.fr%2Farts-expositions%2Fau-lam-a-villeneuve-d-ascq-kandinsky-et-les-secrets-de-son-inspiration-20260301\" data-js-gtm=\"{&quot;event&quot;:&quot;customEventGA4&quot;,&quot;eventName&quot;:&quot;click_action&quot;,&quot;feature&quot;:&quot;paywall&quot;,&quot;location&quot;:&quot;paywall&quot;,&quot;button_action&quot;:&quot;connect&quot;,&quot;click_text&quot;:&quot;Connectez-vous&quot;}\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n                    Connectez-vous<br \/>\n                <\/a>\n            <\/p>\n","protected":false},"excerpt":{"rendered":"EXPOSITION &#8211; Un parcours in\u00e9dit sur le pionnier russe de l\u2019abstraction met en lumi\u00e8re son rapport \u00e0 la&hellip;\n","protected":false},"author":2,"featured_media":27871,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[1434,155,156,113,112,11182,1289,210,755,249,23],"class_list":{"0":"post-27870","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-arts-et-design","8":"tag-art-moderne","9":"tag-arts-and-design","10":"tag-arts-et-design","11":"tag-divertissement","12":"tag-entertainment","13":"tag-kandinsky","14":"tag-lille","15":"tag-peinture","16":"tag-photographie","17":"tag-russie","18":"tag-suisse"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/27870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/comments?post=27870"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/27870\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media\/27871"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media?parent=27870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/categories?post=27870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/tags?post=27870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}