{"id":32759,"date":"2026-03-05T03:28:21","date_gmt":"2026-03-05T03:28:21","guid":{"rendered":"https:\/\/www.europesays.com\/ch-fr\/32759\/"},"modified":"2026-03-05T03:28:21","modified_gmt":"2026-03-05T03:28:21","slug":"espionnage-infiltration-les-dessous-dune-operation-hors-norme","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-fr\/32759\/","title":{"rendered":"Espionnage, infiltration : les dessous d&rsquo;une op\u00e9ration hors norme"},"content":{"rendered":"<p class=\"jsx-4058425199 jsx-2164199691 ExpandableText__Text\">L&rsquo;\u00e9limination du guide supr\u00eame iranien Ali Khamenei, samedi, dans le bombardement de son quartier g\u00e9n\u00e9ral a montr\u00e9 \u00e0 quel point les services de renseignements am\u00e9ricains et isra\u00e9liens \u00e9taient bien inform\u00e9s. L&rsquo;op\u00e9ration a \u00e9t\u00e9 pr\u00e9par\u00e9e depuis des ann\u00e9es.  C&rsquo;est le fruit d&rsquo;un long travail d&rsquo;espionnage et d&rsquo;infiltration en Iran par la CIA et le Mossad via des agents dormants, des satellites, mais aussi, plus surprenant, la prise de contr\u00f4le \u00e0 distance des cam\u00e9ras de surveillance de la capitale iranienne.<\/p>\n<p>Lire plusReplier<\/p>\n","protected":false},"excerpt":{"rendered":"L&rsquo;\u00e9limination du guide supr\u00eame iranien Ali Khamenei, samedi, dans le bombardement de son quartier g\u00e9n\u00e9ral a montr\u00e9 \u00e0&hellip;\n","protected":false},"author":2,"featured_media":32760,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[4472,113,112,12524,152,12525,23,142,154,3071],"class_list":{"0":"post-32759","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-television","8":"tag-ali-khamenei","9":"tag-divertissement","10":"tag-entertainment","11":"tag-liran-attaque-par-les-etats-unis-et-israel","12":"tag-le-20h","13":"tag-le-moyen-orient-sembrase","14":"tag-suisse","15":"tag-television","16":"tag-video","17":"tag-video-international"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_fr\/116174448439059937","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/32759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/comments?post=32759"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/32759\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media\/32760"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media?parent=32759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/categories?post=32759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/tags?post=32759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}