{"id":34555,"date":"2026-03-06T05:50:08","date_gmt":"2026-03-06T05:50:08","guid":{"rendered":"https:\/\/www.europesays.com\/ch-fr\/34555\/"},"modified":"2026-03-06T05:50:08","modified_gmt":"2026-03-06T05:50:08","slug":"kiev-accuse-la-hongrie-davoir-pris-des-employes-dune-banque-ukrainienne-en-otage-a-budapest","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-fr\/34555\/","title":{"rendered":"Kiev accuse la Hongrie d&rsquo;avoir pris des employ\u00e9s d&rsquo;une banque ukrainienne \u00ab\u00a0en otage\u00a0\u00bb \u00e0 Budapest"},"content":{"rendered":"<p>Le chef de la diplomatie ukrainienne a accus\u00e9 vendredi la Hongrie d&rsquo;avoir \u00ab\u00a0pris en otage\u00a0\u00bb sept employ\u00e9s d&rsquo;une banque ukrainienne \u00e0 Budapest, selon l&rsquo;institution. Ils convoyaient plusieurs dizaines de millions d&rsquo;euros depuis l&rsquo;Autriche.<\/p>\n<p>\u00ab\u00a0A Budapest, les autorit\u00e9s hongroises ont pris en otage sept citoyens ukrainiens\u00a0\u00bb, tous des employ\u00e9s de la banque d&rsquo;Etat Oschadbank qui op\u00e9raient dans deux v\u00e9hicules bancaires\u00a0\u00bb depuis l&rsquo;Autriche, a \u00e9crit Andri\u00ef Sybiga sur le r\u00e9seau social X.<\/p>\n<p>Contenu externe<\/p>\n<p> Ce contenu externe ne peut pas \u00eatre affich\u00e9 car il est susceptible de collecter des donn\u00e9es personnelles. Pour voir ce contenu vous devez autoriser la cat\u00e9gorie R\u00e9seaux sociaux. <\/p>\n<p> Accepter Plus d&rsquo;info <\/p>\n<p>\u00ab\u00a0Il s&rsquo;agit de terrorisme et de racket d&rsquo;Etat\u00a0\u00bb commis par la Hongrie, a d\u00e9nonc\u00e9 le ministre, affirmant avoir d\u00e9j\u00e0 envoy\u00e9 une note officielle pour exiger \u00ab\u00a0la lib\u00e9ration imm\u00e9diate\u00a0\u00bb de ses compatriotes.<\/p>\n<p>Oschadbank a indiqu\u00e9 dans un communiqu\u00e9 que deux de ses v\u00e9hicules transportaient jeudi \u00ab\u00a035 millions d&rsquo;euros et 9 kg d&rsquo;or\u00a0\u00bb depuis la Raiffeisen Bank en Autriche, \u00ab\u00a0en accord avec les r\u00e8gles de transport internationales et les proc\u00e9dures douani\u00e8res europ\u00e9ennes en vigueur\u00a0\u00bb.<\/p>\n<p>Ol\u00e9oduc<\/p>\n<p>Les deux v\u00e9hicules transporteurs de fonds \u00ab\u00a0se trouvent actuellement dans le centre de Budapest\u00a0\u00bb, a d\u00e9clar\u00e9 la banque ukrainienne, mais la localisation des employ\u00e9s reste inconnue. Le gouvernement hongrois n&rsquo;a pour l&rsquo;heure pas r\u00e9pondu aux sollicitations de l&rsquo;AFP.<\/p>\n<p>La Hongrie est l&rsquo;un des rares pays de l&rsquo;Otan et de l&rsquo;Union europ\u00e9enne \u00e0 avoir renforc\u00e9 ses liens avec la Russie depuis son offensive \u00e0 grande \u00e9chelle lanc\u00e9e en 2022 en Ukraine.<\/p>\n<p>Budapest bloque notamment l&rsquo;adoption d&rsquo;un 20e paquet de sanctions de l&rsquo;UE contre Moscou et le versement d&rsquo;un pr\u00eat de 90 milliards d&rsquo;euros \u00e0 Kiev, tant qu&rsquo;elle n&rsquo;aura pas obtenu la reprise des livraisons via un ol\u00e9oduc qui traverse l&rsquo;Ukraine.<\/p>\n<p> &gt;&gt; Voir le sujet diffus\u00e9 le 23 f\u00e9vrier dans le 19h30\u00a0:   <img decoding=\"async\" class=\"embed-responsive-item\" loading=\"lazy\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/03\/vubx4j-29161825.image.jpeg\" alt=\"La Hongrie bloque l'adoption de nouvelles sanctions europ\u00e9ennes contre la Russie\"\/>    La Hongrie bloque l&rsquo;adoption de nouvelles sanctions europ\u00e9ennes contre la Russie \/ 19h30 \/ 20 sec. \/ le 23 f\u00e9vrier 2026 <\/p>\n<p class=\"sources\">ats\/jtr<\/p>\n","protected":false},"excerpt":{"rendered":"Le chef de la diplomatie ukrainienne a accus\u00e9 vendredi la Hongrie d&rsquo;avoir \u00ab\u00a0pris en otage\u00a0\u00bb sept employ\u00e9s d&rsquo;une&hellip;\n","protected":false},"author":2,"featured_media":34556,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[22,3773,13043,10324,4528,2831,421,21,1239,23,247,8252],"class_list":{"0":"post-34555","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualites","8":"tag-actualites","9":"tag-banque","10":"tag-budapest","11":"tag-euro","12":"tag-hongrie","13":"tag-kiev","14":"tag-monde","15":"tag-news","16":"tag-salarie","17":"tag-suisse","18":"tag-ukraine","19":"tag-vehicule"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_fr\/116180669099704665","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/34555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/comments?post=34555"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/34555\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media\/34556"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media?parent=34555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/categories?post=34555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/tags?post=34555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}