{"id":37951,"date":"2026-03-08T07:40:10","date_gmt":"2026-03-08T07:40:10","guid":{"rendered":"https:\/\/www.europesays.com\/ch-fr\/37951\/"},"modified":"2026-03-08T07:40:10","modified_gmt":"2026-03-08T07:40:10","slug":"les-princes-lubomirski-et-sanguszko-representent-la-noblesse-polonaise-unie-pour-la-bonne-cause-au-bal-de-berne","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-fr\/37951\/","title":{"rendered":"Les princes Lubomirski et Sanguszko repr\u00e9sentent la noblesse polonaise unie pour la bonne cause au Bal de Berne"},"content":{"rendered":"<p>Deux des plus grandes familles de la noblesse polonaises \u00e9taient r\u00e9unies au Bal de Berne pour soutenir les causes d\u00e9fendues par l\u2019ordre de Malte. Des princes de la famille Lubomirski, parents et enfants, ainsi que le dernier prince Sanguszko et ses enfants, ont particip\u00e9 \u00e0 cet \u00e9v\u00e9nement mondain et caritatif en Suisse, o\u00f9 ils ont retrouv\u00e9 de nombreux amis de l\u2019aristocratie, de la noblesse et de familles royales, venus de tout le continent.<\/p>\n<p>Lire aussi : <a href=\"https:\/\/histoiresroyales.fr\/princesses-maria-carolina-maria-chiara-bal-de-berne-ordre-malte\/\" rel=\"nofollow noopener\" target=\"_blank\">La princesse Maria Carolina et ses amis r\u00e9unissent l\u2019aristocratie au prestigieux Bal de Berne pour la bonne cause<\/a><\/p>\n<p>Les familles Lubomirski et Sanguszko r\u00e9unies \u00e0 Berne pour aider les \u0153uvres de l\u2019ordre de Malte en Suisse<\/p>\n<p>Le Bal de Berne est un \u00e9v\u00e9nement mondain et caritatif organis\u00e9 au d\u00e9but de l\u2019ann\u00e9e, auquel participent des jeunes bien n\u00e9s, venus des quatre coins du continent. La soir\u00e9e de prestige est organis\u00e9e par le Service hospitalier de l\u2019ordre de Malte suisse (SHOMS) au profit de la branche helv\u00e9tique de l\u2019ordre fond\u00e9 il y a plus de 900 ans, \u00e0 l\u2019origine pour soigner les malades \u00e0 J\u00e9rusalem, lors de la p\u00e9riode des Croisades. Il s\u2019agit de la plus ancienne association de bienfaisance au monde.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" width=\"1400\" height=\"2100\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/03\/maria-chiara-lubomirski-bal-de-berne.jpg\" alt=\"\" class=\"wp-image-240763 lazyload\" data-  \/>Le prince Jeremi Kulczyk-Lubomirski avec la princesse Maria Chiara de Bourbon des Deux-Siciles au Bal de Berne en f\u00e9vrier 2026 (Photo : David Nivi\u00e8re)<\/p>\n<p>Lire aussi : <a href=\"https:\/\/histoiresroyales.fr\/fils-grand-duc-de-toscane-engages-ordre-de-malte-bal-de-berne\/\" rel=\"nofollow noopener\" target=\"_blank\">Les fils du grand-duc de Toscane engag\u00e9s pour l\u2019ordre de Malte au Bal de Berne<\/a><\/p>\n<p>Parmi les invit\u00e9s de cette ann\u00e9e, la noblesse polonaise \u00e9tait bien repr\u00e9sent\u00e9e, notamment par les <a href=\"https:\/\/histoiresroyales.fr\/noblesse\/pologne\/lubomirski\/\" rel=\"nofollow noopener\" target=\"_blank\">princes Lubomirski<\/a>. Les membres de la famille princi\u00e8re Lubomirski sont chevaliers de Malte depuis des si\u00e8cles et soutiennent l\u2019ordre depuis des temps imm\u00e9moriaux. La princesse Weronika et son fr\u00e8re, le prince Jeremi, ont particip\u00e9 \u00e0 cette soir\u00e9e, o\u00f9 ils ont retrouv\u00e9 de nombreux amis et cousins, ainsi que des membres de la famille vivant en Suisse. <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1950\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/03\/hadrien-lubomirski-weronika-jeremi-suisse.jpg\" alt=\"\" class=\"wp-image-240788 lazyload\" data-  \/>Le prince Hadrien Lubomirski avec la princesse Weronika Kulczyk-Lubomirski et son fr\u00e8re, le prince Jeremi Kulczyk-Lubomirski (Photo : David Nivi\u00e8re)<\/p>\n<p>Lors de la soir\u00e9e, les jeunes hommes offrent des roses aux jeunes femmes. Les roses sont associ\u00e9es \u00e0 un num\u00e9ro de tombola. Le prince Jeremi Kulczyk-Lubomirski a notamment offert des roses \u00e0 la princesse Maria Chiara de Bourbon des Deux-Siciles. Les deux familles sont li\u00e9es par le mariage, en 1932, du prince Gabriel des Deux-Siciles et de la princesse C\u00e9cile Lubomirska.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1950\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/03\/sanguzsko-olympia-bal-de-berne.jpg\" alt=\"\" class=\"wp-image-240786 lazyload\" data-  \/>Le prince et la princesse Sanguszko avec leur fille, la princesse Olympia (Photo : David Nivi\u00e8re)<\/p>\n<p>Autre illustre famille de la noblesse polonaise pr\u00e9sente \u00e0 la soir\u00e9e en Suisse, les Sanguszko. Le prince Pawel Sanguszko a assist\u00e9 \u00e0 l\u2019\u00e9v\u00e9nement avec son \u00e9pouse, la princesse S\u00e9verine, et leur fille unique, la princesse Olympia. Pawel est le dernier prince de Sanguszko, en tant que dernier membre masculin de cette ancienne famille.  Le fondateur de la dynastie Sanguszko est Sanguszko Fiodorowic, prince de Ratnie, d\u00e9c\u00e9d\u00e9 au milieu du 15e si\u00e8cle. On le dit petit-fils d\u2019Olgierd, grand-duc de Lituanie. Ses fils Alexander et Michal sont \u00e0 l\u2019origine des deux branches familiales. La famille Sanguszko poss\u00e9dait des grands domaines en Ukraine, un palais \u00e0 Lviv, mais finira par s\u2019expatrier au Br\u00e9sil, au 19e si\u00e8cle.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"2100\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/03\/princesse-maria-carolina-sanguszko-lubomirski-eulalia-bal.jpg\" alt=\"\" class=\"wp-image-240829 lazyload\" data-  \/>La princesse Maria Carolina de Bourbon des Deux-Siciles et la princesse Eulalia d\u2019Orl\u00e9ans-Bourbon, membres du comit\u00e9 international des jeunes du Bal, avec la princesse Weronika Kulczyk-Lubomirski (Photo : David Nivi\u00e8re)<\/p>\n<p>Lire aussi : <a href=\"https:\/\/histoiresroyales.fr\/origines-polonaises-reine-mathilde-princes-ukraine-grand-duc-lituanie\/\" rel=\"nofollow noopener\" target=\"_blank\">Les nobles origines polonaises de la reine Mathilde : descendante du grand-duc de Lituanie et de princes ukrainiens<\/a><\/p>\n<p>La noblesse polonaise pr\u00e9sente au Bal de Berne 2026<\/p>\n<p>Les familles Lumbomirski et Sanguszko ont eu donn\u00e9 d\u2019innombrables princes ayant assur\u00e9 des hautes fonctions tout au long des si\u00e8cles. Ces deux familles ont aussi un <a href=\"https:\/\/histoiresroyales.fr\/origines-polonaises-reine-mathilde-princes-ukraine-grand-duc-lituanie\/\" rel=\"nofollow noopener\" target=\"_blank\">lien de cousinage avec la reine Mathilde de Belgique<\/a>. L\u2019actuelle reine des Belges est une descendante de la princesse Jadwiga Sanguszk\u00f3wna, dont le p\u00e8re \u00e9tait un prince Sanguszko et la m\u00e8re une princesse Lubomirska.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"2100\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/03\/famille-sanguzsko-lubomirski-bal-suisse.jpg\" alt=\"\" class=\"wp-image-240789 lazyload\" data-  \/>Le prince et la princesse Alexandre Lubomirski avec le prince et la princesse Sanguszko au Bal de Berne, en Suisse (Photo : David Nivi\u00e8re)<\/p>\n<p>La famille Lubomirski est l\u2019une des plus anciennes familles de la\u00a0<a href=\"https:\/\/histoiresroyales.fr\/noblesse\/pologne\/\" rel=\"nofollow noopener\" target=\"_blank\">noblesse polonaise<\/a>. Il existe plusieurs th\u00e9ories concernant l\u2019origine noble de la famille. La premi\u00e8re serait que le roi\u00a0Mieszko Ier\u00a0de Pologne aurait fait chevalier les membres de la famille, au 10e si\u00e8cle, pour les remercier dans leur lutte contre le paganisme. Une autre \u00e9tude des blasons indiquerait que la famille aurait eu un pouvoir \u00e9piscopal important. La premi\u00e8re mention r\u00e9elle de la famille se retrouve sur un document du 11e si\u00e8cle, qui indique son intimit\u00e9 avec la famille royale. En 1480, Piotr h\u00e9rite de Lubomierz et en adoptera le nom. La famille Lubomirski va s\u2019enrichir dans les mines de sel. Au fil des si\u00e8cles la famille devient immens\u00e9ment riche, obtient de nouveaux titres et son influence est de plus en plus importante, avec plusieurs membres qui si\u00e9geront \u00e0 la Di\u00e8te ou au S\u00e9nat.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"867\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/03\/familles-princieres-polonaises-bal-de-berne-malte.jpg\" alt=\"\" class=\"wp-image-240790 lazyload\" data-  \/>Les familles Lubomirski et Sanguszko r\u00e9unies en Suisse. Le prince Hadrien Lubomirski et la princesse Weronika Kulczyk-Lubomirski \u00e0 gauche. Derri\u00e8re eux, le prince Jeremi Kulczyk-Lubomirski, la princesse S\u00e9verine Sanguszko, la princesse Olympia Sanguszko, le prince Pawel Sanguszko, la princesse et le prince Alexandre Lubomirski (Photo : David Nivi\u00e8re)<\/p>\n<p>En 2001, le prince Jan Lubomirski avait \u00e9pous\u00e9 Dominika Kulczyk, fille du d\u00e9funt Jan Kulczyk, souvent d\u00e9crit comme l\u2019homme le plus riche de Pologne. Le couple, s\u00e9par\u00e9 en bons termes en 2013, a eu deux enfants, Jeremi Sebastian et Weronika Konstancja. Jeremi et Sebastian ont \u00e9t\u00e9 aper\u00e7us avec leur cousin, le prince Hadrien, venu avec son oncle le prince Alexandre Lubomirski. Du c\u00f4t\u00e9 des Sanguszko, il existe aussi une ascendance la reliant \u00e0 une importante famille de la noblesse fran\u00e7aise, celle des Polignac. La princesse Yolande de Polignac, fille du 4\u00e8me prince de Polignac, a \u00e9pous\u00e9 en 1930 le marquis des Roys. Leur fille, Claude des Roys d\u2019Eschandelys, a \u00e9pous\u00e9 le prince Roman Sanguszko. Claude et Roman Sanguszko sont les parentes du prince Pawel et les grands-parents de la princesse Olympia.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1950\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/03\/hadrien-prince-lubomirski-victoria-weronika.jpg\" alt=\"\" class=\"wp-image-240791 lazyload\" data-  \/>Victoria de Skowronski avec le prince Hadrien Lubomirski et la princesse Weronika Kulczyk-Lubomirski (Photo : David Nivi\u00e8re)<\/p>\n<p>Pawel Sanguszko est un homme engag\u00e9 dans la promotion de la culture polonaise et est connu comme un grand m\u00e9c\u00e8ne. En 2005, le pr\u00e9sident polonais lui a remis la croix de Chevalier\u00a0de l\u2019ordre du M\u00e9rite de la R\u00e9publique de Pologne. La soir\u00e9e permet \u00e0 l\u2019ordre de Malte de poursuivre ses actions caritatives, tant en Suisse qu\u2019\u00e0 l\u2019international, dans tous les domaines de la soci\u00e9t\u00e9, en particulier aupr\u00e8s des plus d\u00e9munis.<\/p>\n<p>\t\t\t\t<img alt=\"Avatar photo\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/02\/1771645993_763_cropped-nicolasfontaine-1-164x164.jpg\"  class=\"avatar avatar-164 photo lazyload\" height=\"164\" width=\"164\" loading=\"lazy\" decoding=\"async\"\/><br \/>\n\t\t<a href=\"https:\/\/histoiresroyales.fr\/author\/royaliste123\/\" rel=\"nofollow noopener\" target=\"_blank\">Nicolas Fontaine<\/a><br \/>\n\t\t\t\t\tR\u00e9dacteur en chef<\/p>\n<p>Nicolas Fontaine est un journaliste sp\u00e9cialis\u00e9 dans les familles royales et l&rsquo;histoire des monarchies europ\u00e9ennes et mondiales. Nicolas Fontaine a fond\u00e9 Histoires Royales, le premier m\u00e9dia en ligne d\u00e9di\u00e9 \u00e0 l&rsquo;actualit\u00e9 des t\u00eates couronn\u00e9es en 2019.&#13;<br \/>\nnicolas@histoiresroyales.fr<\/p>\n<p>\t\t\t\t\t\t\t<a href=\"https:\/\/twitter.com\/ActusRoyales\" class=\"boxed-icon fill twitter\" target=\"_blank\" rel=\"nofollow noopener\"><\/a><br \/>\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/histoiresroyales.fr\/\" class=\"boxed-icon fill instagram\" target=\"_blank\" rel=\"nofollow noopener\"><\/a><\/p>\n<p>\t\t\t\t\t\t\t\t\t\t\t\t\t<script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"Deux des plus grandes familles de la noblesse polonaises \u00e9taient r\u00e9unies au Bal de Berne pour soutenir les&hellip;\n","protected":false},"author":2,"featured_media":37952,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[13863,193,192,13906,13907,13908,13866,23],"class_list":{"0":"post-37951","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-berne","8":"tag-bal","9":"tag-bern","10":"tag-berne","11":"tag-lubomirski","12":"tag-noblesse","13":"tag-noblesse-polonaise","14":"tag-ordre-de-malte","15":"tag-suisse"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_fr\/116192426290942182","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/37951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/comments?post=37951"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/37951\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media\/37952"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media?parent=37951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/categories?post=37951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/tags?post=37951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}