{"id":39179,"date":"2026-03-09T01:10:08","date_gmt":"2026-03-09T01:10:08","guid":{"rendered":"https:\/\/www.europesays.com\/ch-fr\/39179\/"},"modified":"2026-03-09T01:10:08","modified_gmt":"2026-03-09T01:10:08","slug":"cetait-ma-maniere-de-me-faire-accepter-booder-explique-comment-lhumour-lui-a-permis-de-sintegrer-a-lecole-dans-un-dimanche-a-la-campagne","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-fr\/39179\/","title":{"rendered":"\u00ab\u00a0C&rsquo;\u00e9tait ma mani\u00e8re de me faire accepter\u00a0\u00bb : Booder explique comment l\u2019humour lui a permis de s&rsquo;int\u00e9grer \u00e0 l&rsquo;\u00e9cole dans Un dimanche \u00e0 la campagne"},"content":{"rendered":"<p class=\"mb-4 text-lg md:leading-8 break-words\">Ce dimanche 8 mars 2026, <a data-i13n=\"cpos:1;pos:1\" href=\"https:\/\/fr.style.yahoo.com\/booder-bient%C3%B4t-retour-sc%C3%A8ne-s-191719750.html\" data-ylk=\"slk:Booder \u00e9tait invit\u00e9;cpos:1;pos:1;elm:context_link;itc:0;sec:content-canvas;outcm:mb_qualified_link;_E:mb_qualified_link;ct:story;\" class=\"link  yahoo-link\" rel=\"nofollow noopener\" target=\"_blank\">Booder \u00e9tait invit\u00e9 <\/a>aux c\u00f4t\u00e9s de la chanteuse Tina Arena, qui n&rsquo;a pas h\u00e9sit\u00e9 \u00e0 se confier \u00e0 c\u0153ur ouvert sur son enfance sous les projecteurs, et du journaliste Laurent Mariotte <a data-i13n=\"cpos:2;pos:1\" href=\"https:\/\/fr.style.yahoo.com\/histoire-d-amour-m-prot%C3%A9g%C3%A9e-182516572.html\" data-ylk=\"slk:dans l&#039;\u00e9mission Un dimanche \u00e0 la campagne;cpos:2;pos:1;elm:context_link;itc:0;sec:content-canvas;outcm:mb_qualified_link;_E:mb_qualified_link;ct:story;\" class=\"link  yahoo-link\" rel=\"nofollow noopener\" target=\"_blank\">dans l&rsquo;\u00e9mission Un dimanche \u00e0 la campagne <\/a>sur France 2. Face \u00e0 <a data-i13n=\"cpos:3;pos:1\" href=\"https:\/\/www.femmeactuelle.fr\/bio\/frederic-lopez\" rel=\"nofollow noopener\" target=\"_blank\" data-ylk=\"slk:Fr\u00e9d\u00e9ric Lopez;cpos:3;pos:1;elm:context_link;itc:0;sec:content-canvas\" class=\"link \">Fr\u00e9d\u00e9ric Lopez<\/a>, l&rsquo;humoriste a fait des confidences sur la maladie dont il souffre depuis la naissance. Il a \u00e9galement expliqu\u00e9 le r\u00f4le crucial qu&rsquo;a eu son humour dans son parcours scolaire. \u00ab\u00a0Quand j&rsquo;arrive au monde, le docteur coupe <a data-i13n=\"cpos:4;pos:1\" href=\"https:\/\/www.femmeactuelle.fr\/enfant\/grossesse\/cordon-ombilical-role-soins-quand-tombe-t-il-2126827\" rel=\"nofollow noopener\" target=\"_blank\" data-ylk=\"slk:le cordon ombilical;cpos:4;pos:1;elm:context_link;itc:0;sec:content-canvas\" class=\"link \">le cordon ombilical <\/a>et il dit &lsquo;c&rsquo;est tr\u00e8s bizarre ce b\u00e9b\u00e9 ne pleure pas \u00e0 la naissance&rsquo;. Il me met un petit coup dans les fesses et je commence \u00e0 pleurer mais je ne pleure pas fort parce que j&rsquo;ai du mal \u00e0 respirer. J&rsquo;ai un asthme tr\u00e8s prononc\u00e9\u00a0\u00bb, a-t-il tout d&rsquo;abord racont\u00e9 avec beaucoup de sinc\u00e9rit\u00e9.<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">\u00ab\u00a0Le premier mois passe, un peu difficilement parce que j&rsquo;ai du mal \u00e0 me nourrir et j&rsquo;ai du mal \u00e0 respirer quand je t\u00e8te. Donc j&rsquo;ai une malnutrition due \u00e0 la respiration\u00a0\u00bb, a ensuite r\u00e9v\u00e9l\u00e9 l&rsquo;interpr\u00e8te de Juanito dans le film Marsupilami. Il a \u00e9galement expliqu\u00e9 que sa m\u00e8re avait pris la d\u00e9cision de venir en France pour qu\u2019il b\u00e9n\u00e9ficie de bons soins m\u00e9dicaux. \u00ab\u00a0Quand on arrive \u00e0 l&rsquo;h\u00f4pital Necker on lui dit &lsquo;\u00e9coutez cet enfant il faut vite s&rsquo;en occuper, on ne peut pas vous le laisser&rsquo;, et donc c&rsquo;est comme \u00e7a que je suis arriv\u00e9 en France\u00a0\u00bb, a-t-il poursuivi. Booder a par la suite \u00e9voqu\u00e9 son parcours scolaire lors duquel il a \u00e9t\u00e9 \u00ab\u00a0tr\u00e8s accept\u00e9\u00a0\u00bb.\u00a0\u00ab\u00a0Tu ne pouvais pas faire une f\u00eate d&rsquo;anniversaire sans inviter Booder\u00a0\u00bb, a-t-il d\u00e9clar\u00e9.<\/p>\n<p>\u00ab\u00a0C&rsquo;\u00e9tait ma mani\u00e8re de ne pas subir le harc\u00e8lement \u00a0\u00bb : Booder revient sur le r\u00f4le crucial de son humour dans sa scolarit\u00e9<\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">\u00ab\u00a0J&rsquo;\u00e9tais dr\u00f4le et j&rsquo;aimais faire rire. \u00c7a aga\u00e7ait certains profs et je peux le comprendre car aujourd&rsquo;hui je suis adulte mais \u00e0 l&rsquo;\u00e9poque ils ne pouvaient pas eux comprendre que c&rsquo;\u00e9tait ma mani\u00e8re de me faire accepter des gens et de ne pas subir <a data-i13n=\"cpos:5;pos:1\" href=\"https:\/\/fr.style.yahoo.com\/harc%C3%A8lement-scolaire-1-enfant-6-152826110.html\" data-ylk=\"slk:le harc\u00e8lement scolaire&quot;;cpos:5;pos:1;elm:context_link;itc:0;sec:content-canvas;outcm:mb_qualified_link;_E:mb_qualified_link;ct:story;\" class=\"link  yahoo-link\" rel=\"nofollow noopener\" target=\"_blank\">le harc\u00e8lement scolaire\u00a0\u00bb<\/a>, a r\u00e9v\u00e9l\u00e9 l&rsquo;humoriste \u00e0 Fr\u00e9d\u00e9ric Lopez. Il a ensuite ajout\u00e9 : \u00ab\u00a0je ne l&rsquo;ai pas subi car quand on se moquait de moi je vannais direct et \u00e7a allait tr\u00e8s tr\u00e8s vite\u00a0\u00bb. <\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\">Selon lui, il \u00e9tait per\u00e7u par ses camarades de classe comme \u00ab\u00a0le copain qu&rsquo;il fallait avoir dans son \u00e9quipe pour passer une bonne journ\u00e9e et pour bien rigoler\u00a0\u00bb. \u00ab\u00a0C&rsquo;\u00e9tait un don, un talent et \u00e0 la fois un mode de survie\u00a0\u00bb, a soulign\u00e9 le pr\u00e9sentateur de l&rsquo;\u00e9mission. Ce \u00e0 quoi Booder a r\u00e9pondu :\u00a0\u00ab\u00a0il fallait que je sois dr\u00f4le pour \u00eatre accept\u00e9\u00a0\u00bb. <\/p>\n<p class=\"mb-4 text-lg md:leading-8 break-words\"><a data-i13n=\"cpos:6;pos:1\" href=\"https:\/\/www.femmeactuelle.fr\/actu\/news-actu\/c-etait-ma-maniere-de-me-faire-accepter-booder-explique-comment-lhumour-lui-a-permis-de-s-integrer-a-l-ecole-dans-un-dimanche-a-la-campagne-2205196\" rel=\"nofollow noopener\" target=\"_blank\" data-ylk=\"slk:Lire l&#039;article sur le site de Femme Actuelle;cpos:6;pos:1;elm:context_link;itc:0;sec:content-canvas\" class=\"link \">Lire l&rsquo;article sur le site de Femme Actuelle<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Ce dimanche 8 mars 2026, Booder \u00e9tait invit\u00e9 aux c\u00f4t\u00e9s de la chanteuse Tina Arena, qui n&rsquo;a pas&hellip;\n","protected":false},"author":2,"featured_media":39180,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[14214,158,157,113,112,9384,14149,159,23,14097],"class_list":{"0":"post-39179","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-people","8":"tag-booder","9":"tag-celebrities","10":"tag-celebrity","11":"tag-divertissement","12":"tag-entertainment","13":"tag-etait","14":"tag-frederic-lopez","15":"tag-people","16":"tag-suisse","17":"tag-tina-arena"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_fr\/116196554978234104","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/39179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/comments?post=39179"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/39179\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media\/39180"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media?parent=39179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/categories?post=39179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/tags?post=39179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}