{"id":42647,"date":"2026-03-11T07:45:16","date_gmt":"2026-03-11T07:45:16","guid":{"rendered":"https:\/\/www.europesays.com\/ch-fr\/42647\/"},"modified":"2026-03-11T07:45:16","modified_gmt":"2026-03-11T07:45:16","slug":"croisieres-europeennes-annulees-a-cause-de-navires-bloques-dans-des-ports-du-golfe","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-fr\/42647\/","title":{"rendered":"Croisi\u00e8res europ\u00e9ennes annul\u00e9es \u00e0 cause de navires bloqu\u00e9s dans des ports du Golfe"},"content":{"rendered":"<p>\n                    Publi\u00e9 le                 10\/03\/2026 &#8211; 15:05 UTC+1\u2022Mis \u00e0 jour<br \/>\n                                     11\/03\/2026 &#8211; 7:24 UTC+1\n                                        <\/p>\n<p>Plusieurs croisi\u00e8res europ\u00e9ennes \u00e0 venir ont \u00e9t\u00e9 annul\u00e9es apr\u00e8s que des navires n\u2019ont pas pu quitter des ports du golfe arabo-persique sur fond de tensions r\u00e9gionales. <\/p>\n<p>          <img decoding=\"async\" class=\"c-ad__placeholder__logo\" src=\"https:\/\/static.euronews.com\/website\/images\/logos\/logo-euronews-stacked-outlined-72x72-grey-9.svg\" width=\"72\" height=\"72\" alt=\"\" loading=\"lazy\"\/><br \/>\n          PUBLICIT\u00c9<\/p>\n<p>          <img decoding=\"async\" class=\"c-ad__placeholder__logo\" src=\"https:\/\/static.euronews.com\/website\/images\/logos\/logo-euronews-stacked-outlined-72x72-grey-9.svg\" width=\"72\" height=\"72\" alt=\"\" loading=\"lazy\"\/><br \/>\n          PUBLICIT\u00c9<\/p>\n<p>Le conflit qui se poursuit au Moyen-Orient a contraint les compagnies \u00e0 suspendre leurs travers\u00e9es et \u00e0 rapatrier des milliers de passagers bloqu\u00e9s. <\/p>\n<p>L\u2019Organisation maritime internationale (OMI) des Nations unies a indiqu\u00e9 \u00e0 l\u2019AFP que 15 000 croisi\u00e9ristes \u00e9taient rest\u00e9s coinc\u00e9s dans la r\u00e9gion, des navires de plusieurs compagnies \u2013 dont MSC, TUI, Celestyal et AROYA \u2013 \u00e9tant \u00e0 quai dans des ports cl\u00e9s.<\/p>\n<p>Lundi, la compagnie grecque Celestyal a confirm\u00e9 que ses navires se trouvaient toujours dans le Golfe, le Celestyal Discovery \u00e9tant actuellement \u00e0 Duba\u00ef et le Celestyal Journey \u00e0 Doha. <\/p>\n<p>La compagnie a pr\u00e9cis\u00e9 que les passagers avaient d\u00e9barqu\u00e9 en toute s\u00e9curit\u00e9 \u00e0 Duba\u00ef et que les derniers clients encore \u00e0 bord du Celestyal Journey devaient quitter le navire au Qatar \u00ab dans les 24 heures \u00e0 venir \u00bb.<\/p>\n<p>\u00ab Les deux navires restent pleinement op\u00e9rationnels et pr\u00eats \u00e0 appareiller \u00bb, a indiqu\u00e9 Celestyal dans un communiqu\u00e9, ajoutant que leur d\u00e9part de la r\u00e9gion aura lieu \u00ab conform\u00e9ment aux recommandations des autorit\u00e9s comp\u00e9tentes \u00bb.<\/p>\n<p>Cette perturbation a toutefois contraint Celestyal \u00e0 annuler deux croisi\u00e8res dans les \u00eeles grecques de son programme \u00ab Iconic Aegean \u00bb, dont le d\u00e9part \u00e9tait pr\u00e9vu plus tard ce mois-ci. <\/p>\n<p>Les croisi\u00e8res de trois nuits du 20 mars et de quatre nuits du 23 mars op\u00e9r\u00e9es par le Celestyal Discovery n\u2019auront pas lieu, le temps que la compagnie finalise les modalit\u00e9s de repositionnement du navire en M\u00e9diterran\u00e9e pour la saison estivale. <\/p>\n<p>Les passagers ayant r\u00e9serv\u00e9 sur ces travers\u00e9es se verront proposer soit un remboursement int\u00e9gral, soit un avoir pour une future croisi\u00e8re.<\/p>\n<p>Saison annul\u00e9e et passagers rapatri\u00e9s<\/p>\n<p>D\u2019autres croisi\u00e9ristes ont \u00e9galement d\u00fb modifier ou suspendre leurs programmes dans la r\u00e9gion.<\/p>\n<p>La compagnie AROYA Cruises, soutenue par l\u2019Arabie saoudite, a confirm\u00e9 avoir purement et simplement annul\u00e9 le reste de sa saison hivernale dans le golfe arabo-persique. <\/p>\n<p>Elle a indiqu\u00e9 que tous les passagers pr\u00e9sents \u00e0 bord de son navire avaient d\u00e9barqu\u00e9 en toute s\u00e9curit\u00e9 \u00e0 Duba\u00ef le 7 mars, apr\u00e8s une d\u00e9cision prise \u00ab en raison de consid\u00e9rations op\u00e9rationnelles r\u00e9gionales persistantes et en coordination avec les autorit\u00e9s maritimes et nationales comp\u00e9tentes \u00bb.<\/p>\n<p>Parall\u00e8lement, MSC Croisi\u00e8res, bas\u00e9e \u00e0 Gen\u00e8ve, organise des <a href=\"https:\/\/fr.euronews.com\/2026\/03\/10\/vols-au-moyen-orient-qatar-airways-confirme-davantage-de-vols-de-rapatriement-depuis-et-ve\" rel=\"nofollow noopener\" target=\"_blank\">vols de rapatriement<\/a> pour les passagers qui voyageaient \u00e0 bord du MSC Euribia \u00e0 Duba\u00ef. La compagnie affirme avoir arrang\u00e9 des vols pour permettre \u00e0 plus de 1 500 clients de quitter la r\u00e9gion.<\/p>\n<p>Sept vols ont d\u00e9j\u00e0 d\u00e9coll\u00e9, comprenant des liaisons sp\u00e9cialement affr\u00e9t\u00e9es ainsi que des si\u00e8ges r\u00e9serv\u00e9s sur des vols commerciaux. Les voyageurs ont \u00e9t\u00e9 renvoy\u00e9s vers des destinations telles que le Royaume-Uni, l\u2019Italie, l\u2019Allemagne, l\u2019Espagne, les \u00c9tats-Unis et le Br\u00e9sil.<\/p>\n<p>\u00ab Le commandement et l\u2019\u00e9quipage de notre navire ont travaill\u00e9 sans rel\u00e2che pour que nos h\u00f4tes soient bien pris en charge et nos \u00e9quipes \u00e0 travers le monde se sont mobilis\u00e9es 24 heures sur 24 pour ramener nos clients chez eux en toute s\u00e9curit\u00e9 et dans les meilleurs d\u00e9lais \u00bb, a d\u00e9clar\u00e9 Pierfrancesco Vago, pr\u00e9sident ex\u00e9cutif de MSC Croisi\u00e8res.<\/p>\n<p>L\u2019op\u00e9rateur allemand <a href=\"https:\/\/fr.euronews.com\/2026\/03\/02\/bloques-sur-des-bateaux-de-croisiere-dans-les-ports-du-golfe-persique\" rel=\"nofollow noopener\" target=\"_blank\">TUI Cruises<\/a> a annonc\u00e9 que les prochaines croisi\u00e8res du Mein Schiff 4 \u00e9taient annul\u00e9es jusqu\u2019au d\u00e9part du voyage du 23 mars inclus, tandis que les d\u00e9parts du Mein Schiff 5 sont annul\u00e9s jusqu\u2019au d\u00e9but du voyage du 12 mars inclus.<\/p>\n<p>Le Mein Schiff 4 est actuellement \u00e0 quai \u00e0 Abou Dhabi et des trajets de retour ont \u00ab d\u00e9j\u00e0 \u00e9t\u00e9 organis\u00e9s pour tous les passagers et de nombreux membres d\u2019\u00e9quipage \u00bb ces derniers jours, a indiqu\u00e9 TUI dans un communiqu\u00e9 publi\u00e9 lundi.<\/p>\n<p>Les passagers du Mein Schiff 5 restent \u00e0 bord du navire \u00e0 Doha, o\u00f9 les op\u00e9rations \u00ab se d\u00e9roulent normalement compte tenu des circonstances \u00bb. <\/p>\n<p>Le retour des passagers et des membres d\u2019\u00e9quipage est organis\u00e9 \u00ab de mani\u00e8re continue \u00bb au moyen de vols charters affr\u00e9t\u00e9s par TUI Cruises et de places r\u00e9serv\u00e9es aupr\u00e8s de Qatar Airways.<\/p>\n","protected":false},"excerpt":{"rendered":"Publi\u00e9 le 10\/03\/2026 &#8211; 15:05 UTC+1\u2022Mis \u00e0 jour 11\/03\/2026 &#8211; 7:24 UTC+1 Plusieurs croisi\u00e8res europ\u00e9ennes \u00e0 venir ont&hellip;\n","protected":false},"author":2,"featured_media":42648,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[45,44,43,4341,13666,23],"class_list":{"0":"post-42647","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-economie","8":"tag-business","9":"tag-economie","10":"tag-economy","11":"tag-emirats-arabes-unis","12":"tag-qatar","13":"tag-suisse"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_fr\/116209433013529023","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/42647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/comments?post=42647"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/42647\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media\/42648"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media?parent=42647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/categories?post=42647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/tags?post=42647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}