{"id":62598,"date":"2026-03-24T08:39:06","date_gmt":"2026-03-24T08:39:06","guid":{"rendered":"https:\/\/www.europesays.com\/ch-fr\/62598\/"},"modified":"2026-03-24T08:39:06","modified_gmt":"2026-03-24T08:39:06","slug":"afghanistan-quand-la-malnutrition-complique-la-tuberculose-pediatrique","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-fr\/62598\/","title":{"rendered":"Afghanistan : quand la malnutrition complique la tuberculose p\u00e9diatrique"},"content":{"rendered":"<p>La <a href=\"https:\/\/www.msf-azg.be\/fr\/domaines-action\/theme\/malnutrition\" rel=\"nofollow noopener\" target=\"_blank\">malnutrition <\/a>rend les enfants beaucoup plus vuln\u00e9rables \u00e0 la tuberculose. Quand leur corps manque d\u2019\u00e9nergie et de nutriments, leur syst\u00e8me immunitaire s\u2019affaiblit : ils courent alors plus de risques d\u2019attraper la tuberculose et de d\u00e9velopper une tuberculose active, la forme o\u00f9 la maladie se d\u00e9clare r\u00e9ellement. Et l\u2019inverse est \u00e9galement\u00a0vrai : une tuberculose active provoque une perte de poids et une forte d\u00e9pense d\u2019\u00e9nergie, ce qui aggrave encore la malnutrition. Les deux probl\u00e8mes se renforcent mutuellement.\u00a0<\/p>\n<p>L\u2019Afghanistan fait face \u00e0 un taux \u00e9lev\u00e9 de tuberculose et \u00e0 une malnutrition infantile s\u00e9v\u00e8re. Mais, la tuberculose passe souvent inaper\u00e7ue chez les enfants sous-aliment\u00e9s. Les sympt\u00f4mes sont moins visibles, parfois diff\u00e9rents, et la maladie reste mal comprise ou stigmatis\u00e9e dans certaines communaut\u00e9s. Beaucoup de familles n\u2019osent demander de l\u2019aide que tardivement, ce qui retarde les soins essentiels.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"La malnutrition rend les enfants beaucoup plus vuln\u00e9rables \u00e0 la tuberculose. Quand leur corps manque d\u2019\u00e9nergie et de&hellip;\n","protected":false},"author":2,"featured_media":62599,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[5530,19644,19645,83,19646,19642,19643,19647,84,23,19641,4825],"class_list":{"0":"post-62598","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sante","8":"tag-afghanistan","9":"tag-artsen-zonder-grenzen","10":"tag-azg","11":"tag-health","12":"tag-humanitaire-hulp","13":"tag-medecins-sans-frontieres","14":"tag-msf","15":"tag-ondervoeding","16":"tag-sante","17":"tag-suisse","18":"tag-tbc","19":"tag-tuberculose"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_fr\/116283255301621176","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/62598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/comments?post=62598"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/62598\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media\/62599"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media?parent=62598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/categories?post=62598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/tags?post=62598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}