{"id":65360,"date":"2026-03-25T21:48:07","date_gmt":"2026-03-25T21:48:07","guid":{"rendered":"https:\/\/www.europesays.com\/ch-fr\/65360\/"},"modified":"2026-03-25T21:48:07","modified_gmt":"2026-03-25T21:48:07","slug":"un-homme-fracasse-des-sculptures-dune-valeur-de-240-000-dollars-dans-une-exposition-a-seattle","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-fr\/65360\/","title":{"rendered":"Un homme fracasse des sculptures d\u2019une valeur de 240 000 dollars dans une exposition \u00e0 Seattle"},"content":{"rendered":"<p>\n    L\u2019individu s\u2019est attaqu\u00e9 aux \u0153uvres de l\u2019artiste Dale Chihuly, figure centrale du mouvement Studio Glass am\u00e9ricain, et a tent\u00e9 de poignarder un vigile avec des morceaux de verre.<\/p>\n<p class=\"fig-paragraph\">Install\u00e9s au c\u0153ur de\u00a0<a href=\"http:\/\/www.lefigaro.fr\/flash-actu\/etats-unis-un-homme-abattu-par-la-police-apres-avoir-poignarde-a-mort-quatre-personnes-a-seattle-20260224\" data-fig-type=\"NewsFlash\" data-gtm-custom-categorie=\"navigation\" data-gtm-custom-action=\"crossclick\" data-gtm-custom-label=\"Contextuel\" data-gtm-event=\"customEventSPE\" data-fig-domain=\"LEFIGARO\" rel=\"nofollow noopener\" target=\"_blank\">Seattle<\/a>, aux \u00c9tats-Unis, le Seattle Center\u00a0et son exposition permanente Chihuly Garden and Glass ont \u00e9t\u00e9 la cible d\u2019un acte de vandalisme spectaculaire dans la nuit du 15 au 16 mars. Aux alentours de 23 heures, les agents de s\u00e9curit\u00e9 du parc d\u2019activit\u00e9s ont aper\u00e7u un individu dans le jardin ext\u00e9rieur, alors que les portes avaient ferm\u00e9 depuis plusieurs heures.<\/p>\n<p class=\"fig-paragraph\">L\u2019intrus, un certain Alexander Taylor Weis, \u00e2g\u00e9 de 40 ans, tr\u00f4nait au milieu de fragments de verres color\u00e9s. Il venait de d\u00e9truire douze sculptures en verre souffl\u00e9. Celle de l\u2019artiste Dale Chihuly, une figure centrale du mouvement Studio Glass am\u00e9ricain, o\u00f9 le verre devient un m\u00e9dium d\u2019expression \u00e0 part enti\u00e8re. La police de Seattle, cit\u00e9e par\u00a0<a href=\"https:\/\/www.artmajeur.com\/fr\/magazine\/2-actualites-artistiques\/seattle-un-homme-detruit-12-sculptures-de-chihuly-en-pleine-nuit\/340810\" target=\"_blank\" rel=\"nofollow noopener\" data-gtm-custom-categorie=\"navigation\" data-gtm-custom-action=\"crossclick\" data-gtm-custom-label=\"Contextuel\" data-gtm-event=\"customEventSPE\">le magazine Art Majeur<\/a>, indique que les restes des \u0153uvres \u00e9taient dispers\u00e9s un peu partout dans l\u2019all\u00e9e qui m\u00e8ne \u00e0 l\u2019entr\u00e9e de l\u2019exposition.<\/p>\n<p>                                            <a class=\"fig-a11y-skip\" href=\"#fig-a11y-skip-main-inarticle\" is=\"fig-a11y-skip\" data-trigger-mode=\"visible-once\"><br \/>\n    Passer la publicit\u00e9<br \/>\n<\/a>            <\/p>\n<p class=\"fig-paragraph\">Selon les enqu\u00eateurs, le vandale, pris de panique, aurait jet\u00e9 des \u00e9clats de verre sur un des agents de s\u00e9curit\u00e9 avant de tenter de le poignarder avec un tesson. Le garde n\u2019a pas \u00e9t\u00e9 bless\u00e9 et est parvenu \u00e0 se mettre \u00e0 l\u2019abri jusqu\u2019\u00e0 l\u2019arriv\u00e9e des autorit\u00e9s qui, malgr\u00e9 les comportements \u00ab\u00a0agressifs\u00a0\u00bb de l\u2019intrus, a r\u00e9ussi \u00e0 le ma\u00eetriser et \u00e0 l\u2019emmener au poste. Il a ensuite \u00e9t\u00e9 inculp\u00e9 pour cambriolage au premier degr\u00e9, agression au deuxi\u00e8me degr\u00e9 et dommages volontaires au premier degr\u00e9.<\/p>\n<p>                                            Un pr\u00e9judice \u00e0 hauteur de 240\u00a0000 dollars<\/p>\n<p class=\"fig-paragraph\">D\u2019apr\u00e8s<a href=\"https:\/\/news.artnet.com\/art-world\/chihuly-glass-garden-vandal-damage-2755984\" target=\"_blank\" rel=\"nofollow noopener\" data-gtm-custom-categorie=\"navigation\" data-gtm-custom-action=\"crossclick\" data-gtm-custom-label=\"Contextuel\" data-gtm-event=\"customEventSPE\">\u00a0les informations de Artnet<\/a>, le pr\u00e9judice est estim\u00e9 \u00e0 hauteur de 240\u00a0000 dollars, chacune des douze sculptures valant plus de 20\u00a0000 dollars. Deux jours apr\u00e8s les \u00e9v\u00e9nements, un juge du comt\u00e9 de King a fix\u00e9 sa caution \u00e0 quelque 100\u00a0000 dollars. Il lui a aussi interdit d\u2019entrer en contact avec les membres du Seattle Center. Alexander Taylor Weis n\u2019aurait pas pay\u00e9 la caution et serait encore en d\u00e9tention.<\/p>\n<p class=\"fig-body-link\">\n<p>        Lire le dossier<br \/>\n        <a class=\"fig-body-link__link\" href=\"http:\/\/www.lefigaro.fr\/actualite-france\/dossier\/vol-au-louvre-notre-dossier-pour-tout-comprendre\" target=\"_blank\" data-fig-type=\"Topic\" rel=\"noopener nofollow\" data-gtm-custom-categorie=\"navigation\" data-gtm-custom-action=\"crossclick\" data-gtm-custom-label=\"Contextuel\" data-gtm-event=\"customEventSPE\" data-fig-domain=\"LEFIGARO\"><\/p>\n<p>        Cambriolage au Louvre\u00a0: notre dossier pour tout comprendre<br \/>\n    <\/a>\n<\/p>\n<p class=\"fig-paragraph\">Quant \u00e0 l\u2019exposition, priv\u00e9e des douze sculptures en verre souffl\u00e9 de Dale Chihuly, elle a pu rouvrir ses portes d\u00e8s le lendemain. Le personnel a nettoy\u00e9 les d\u00e9bris dans la nuit et n\u2019a pas eu besoin de condamner l\u2019acc\u00e8s au jardin ext\u00e9rieur. Un porte-parole de l\u2019institution a d\u00e9clar\u00e9 \u00e0 la presse am\u00e9ricaine que les \u0153uvres vandalis\u00e9es seront \u00ab\u00a0remplac\u00e9es dans les semaines \u00e0 venir\u00a0\u00bb. Les responsables du mus\u00e9e n\u2019ont pas souhait\u00e9 faire de commentaires sur les potentielles failles de s\u00e9curit\u00e9 qui auraient pu conduire \u00e0 l\u2019intrusion du vandale. De la m\u00eame fa\u00e7on, ils n\u2019ont pas indiqu\u00e9 si la s\u00e9curit\u00e9 sera renforc\u00e9e.<\/p>\n","protected":false},"excerpt":{"rendered":"L\u2019individu s\u2019est attaqu\u00e9 aux \u0153uvres de l\u2019artiste Dale Chihuly, figure centrale du mouvement Studio Glass am\u00e9ricain, et a&hellip;\n","protected":false},"author":2,"featured_media":65361,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[155,156,113,112,222,9860,23],"class_list":{"0":"post-65360","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-arts-et-design","8":"tag-arts-and-design","9":"tag-arts-et-design","10":"tag-divertissement","11":"tag-entertainment","12":"tag-etats-unis","13":"tag-seattle","14":"tag-suisse"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_fr\/116292019971105514","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/65360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/comments?post=65360"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/65360\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media\/65361"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media?parent=65360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/categories?post=65360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/tags?post=65360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}