{"id":66863,"date":"2026-03-26T21:06:12","date_gmt":"2026-03-26T21:06:12","guid":{"rendered":"https:\/\/www.europesays.com\/ch-fr\/66863\/"},"modified":"2026-03-26T21:06:12","modified_gmt":"2026-03-26T21:06:12","slug":"5-livres-photo-a-ne-pas-manquer","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-fr\/66863\/","title":{"rendered":"5 livres photo \u00e0 ne pas manquer"},"content":{"rendered":"<p>Chaque mois, Phototrend vous propose de\u00a0d\u00e9couvrir les livres photo qui nous ont marqu\u00e9s. En ce mois de mars 2026, voici 5 nouveaux ouvrages que nous avons s\u00e9lectionn\u00e9s pour vous.<\/p>\n<p>Ce mois-ci, le nouvel album de RSF consacr\u00e9 \u00e0 Malick Sidib\u00e9, la guerre vue par Robert Capa et Lee Miller, l\u2019ancienne Cit\u00e9 Chambord et ses habitants vus par Arnaud Chochon et le dernier num\u00e9ro de la revue Transbordeur sont \u00e0 l\u2019honneur de notre s\u00e9lection de livres photo. Bonne lecture.<\/p>\n<p>Malick Sidib\u00e9, 100 photos pour la libert\u00e9 de la presse<\/p>\n<p><img decoding=\"async\" width=\"1400\" height=\"933\" loading=\"lazy\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/03\/rsf-cover-n-81-nuit-de-noel-chappy-club-1963-malick-sidibe_page-0001-c-1400x933.jpg\" alt=\"\" class=\"wp-image-262728\"  \/><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"933\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/03\/rsf-cover-n-81-nuit-de-noel-chappy-club-1963-malick-sidibe_page-0001-c-1400x933.jpg\" alt=\"\" class=\"wp-image-262728\"  \/><\/p>\n<p>Le 81e album de Reporters sans fronti\u00e8res rend hommage \u00e0 <a href=\"https:\/\/phototrend.fr\/tag\/malick-sidibe\/\" rel=\"nofollow noopener\" target=\"_blank\">Malick Sidib\u00e9<\/a>. Le photographe malien dresse un portrait vibrant de la jeunesse africaine des ann\u00e9es 1960 et 1970. D\u00e9passant le cadre du photojournalisme, l\u2019\u0153uvre du photographe s\u2019apparente \u00e0 un miroir tendu \u00e0 toute une g\u00e9n\u00e9ration : celle des ann\u00e9es de l\u2019Ind\u00e9pendance.<\/p>\n<p>\u00ab L\u2019\u0153il de Bamako \u00bb t\u00e9moigne de l\u2019euphorie d\u2019une \u00e9poque qui s\u2019invente \u00e0 travers le mouvement et l\u2019\u00e9l\u00e9gance. Il nous livre ainsi le r\u00e9cit visuel d\u2019une nation en pleine m\u00e9tamorphose, c\u00e9l\u00e9brant une modernit\u00e9 africaine \u00e0 la fois fi\u00e8re et optimiste.<\/p>\n<p>L\u2019avant-propos de cet album est sign\u00e9 par <a href=\"https:\/\/phototrend.fr\/tag\/francoise-huguier\/\" rel=\"nofollow noopener\" target=\"_blank\">Fran\u00e7oise Huguier<\/a>, cofondatrice des Rencontres africaines de la photographie \u00e0 Bamako en 1994, qui avait contribu\u00e9 \u00e0 faire d\u00e9couvrir son travail au public occidental. Plusieurs pages sont aussi d\u00e9di\u00e9es au bilan de la libert\u00e9 de la presse, ainsi qu\u2019au classement mondial de la libert\u00e9 de la presse \u2013 o\u00f9 la France descend \u00e0 la 25e place.<\/p>\n<p>Enfin, tous les b\u00e9n\u00e9fices de l\u2019album sont consacr\u00e9s au financement des actions de l\u2019ONG en faveur de la libert\u00e9 de la presse.<\/p>\n<p>Malick Sidib\u00e9, 100 photos pour la libert\u00e9 de la presse<br \/>\u00c9diteur : Reporters sans Fronti\u00e8res<br \/>12,50 \u20ac, 144 pages, format broch\u00e9, 21,1 x 29 cm<br \/>Acheter le livre :\u00a0<a href=\"https:\/\/boutique.rsf.org\/product\/81-malick-sidibe\" rel=\"nofollow noopener\" target=\"_blank\">Reporters sans Fronti\u00e8res<\/a>\u00a0\/\u00a0<a href=\"https:\/\/www.awin1.com\/cread.php?awinmid=12665&amp;awinaffid=282185&amp;clickref=&amp;p=https:\/\/www.fnac.com\/a22491269\/Malick-Sidibe-Malick-Sidibe-100-photos-pour-la-liberte-de-la-presse-Volume-81\" rel=\"nofollow noopener\" target=\"_blank\">Fnac<\/a><\/p>\n<p>Robert Capa<\/p>\n<p><img decoding=\"async\" width=\"1400\" height=\"933\" loading=\"lazy\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/03\/robert-capa.jpg\" alt=\"\" class=\"wp-image-264916\"  \/><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"933\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/03\/robert-capa.jpg\" alt=\"\" class=\"wp-image-264916\"  \/><\/p>\n<p>Publi\u00e9 \u00e0 l\u2019occasion de <a href=\"https:\/\/phototrend.fr\/2026\/02\/robert-capa-photographe-de-guerre-exposition\/\" rel=\"nofollow noopener\" target=\"_blank\">l\u2019exposition au Mus\u00e9e de la Lib\u00e9ration de Paris<\/a>, cet ouvrage retrace le parcours de l\u2019un des plus grands photoreporters du XXe si\u00e8cle. Seul photographe \u00e0 d\u00e9barquer aux c\u00f4t\u00e9s des troupes alli\u00e9es en Normandie, le 6 juin 1944, fondateur de l\u2019agence Magnum en 1947, Robert Capa a impos\u00e9 son style direct et engag\u00e9.<\/p>\n<p>Sobrement intitul\u00e9 Robert Capa : Photographe de guerre, le livre nous plonge dans les reportages sur la guerre civile espagnole, puis sur la Seconde Guerre mondiale. Il offre notamment un ensemble in\u00e9dit de clich\u00e9s captur\u00e9s lors de la Lib\u00e9ration de Paris, les 25 et 26 ao\u00fbt 1944. Plus de 60 tirages originaux, mais aussi des magazines et des images d\u2019\u00e9poque, ont ainsi \u00e9t\u00e9 rassembl\u00e9s par l\u2019agence Magnum et la fondation Golda Darty pour former un ensemble d\u2019une grande richesse.<\/p>\n<p>Que vous ayez d\u00e9j\u00e0 parcouru ou non les couloirs de l\u2019exposition, ce livre demeure un indispensable pour se familiariser toujours plus avec l\u2019\u0153uvre de Robert Capa.<\/p>\n<p>Robert Capa : Photographe de guerre, sous la direction de Sylvie Zaidman et Michel Lefebvre<br \/>\u00c9diteur : Paris Mus\u00e9es<br \/>30 \u20ac, 168 pages, broch\u00e9, 23,1 x 28,1 cm<br \/>Acheter le livre : <a href=\"https:\/\/www.leslibraires.fr\/livre\/25260344-robert-capa-collectif-paris-musees?affiliate=phototrend\" rel=\"nofollow noopener\" target=\"_blank\">leslibraires.fr<\/a> \/ <a href=\"https:\/\/www.awin1.com\/cread.php?awinmid=12665&amp;awinaffid=282185&amp;clickref=&amp;p=https:\/\/www.fnac.com\/a22051913\/Collectif-Robert-Capa\" rel=\"nofollow noopener\" target=\"_blank\">Fnac<\/a><\/p>\n<p>Cit\u00e9 Chambord<\/p>\n<p><img decoding=\"async\" width=\"1400\" height=\"933\" loading=\"lazy\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/03\/cite-chambord-arnaud-chauchon.jpg\" alt=\"\" class=\"wp-image-264913\"  \/><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"933\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/03\/cite-chambord-arnaud-chauchon.jpg\" alt=\"\" class=\"wp-image-264913\"  \/><\/p>\n<p>Fruit d\u2019une r\u00e9sidence de pr\u00e8s de deux ans command\u00e9e par le Grand Montauban dans le cadre du nouveau programme national de renouvellement urbain,\u00a0Cit\u00e9 Chambord\u00a0documente la mutation d\u2019un grand ensemble construit \u00e0 partir de 1952 \u00e0 l\u2019est de Montauban.<\/p>\n<p>Le photographe Arnaud Chochon (agence Hans Lucas) y d\u00e9ploie une approche \u00e0 la fois historique et participative : archives, portraits d\u2019habitants, photographies des parties communes et des logements vacants se m\u00ealent \u00e0 des images r\u00e9alis\u00e9es par les r\u00e9sidents eux-m\u00eames, \u00e0 qui des appareils jetables ont \u00e9t\u00e9 confi\u00e9s.<\/p>\n<p>Le livre int\u00e8gre aussi un volet plus inattendu, \u00ab le quartier imaginaire \u00bb, o\u00f9 les habitants ont r\u00e9invent\u00e9 les clich\u00e9s par le collage et le coloriage, peuplant la cit\u00e9 de personnages et d\u2019animaux g\u00e9ants. Des traces de vie sur les murs des appartements vides aux images de la d\u00e9molition d\u2019une barre de 60 logements en ao\u00fbt 2024, l\u2019ouvrage construit un r\u00e9cit collectif de m\u00e9moire et de transformation.<\/p>\n<p>Cit\u00e9 Chambord\u00a0accompagne l\u2019exposition multim\u00e9dia\u00a0Chambord, m\u00e9moires d\u2019une cit\u00e9 en mutation, visible au CIAP de Montauban jusqu\u2019au 31 mars 2026.<\/p>\n<p>Cit\u00e9 Chambord, Arnaud Chochon<br \/>\u00c9diteur : Arnaud Chochon<br \/>28 \u20ac, 144 pages, reli\u00e9 \u00e0 la suisse, 16,8 x 29 cm<br \/>Acheter le livre : <a href=\"https:\/\/arnaudchochon.com\/boutique\/\" rel=\"nofollow noopener\" target=\"_blank\">arnaudchochon.fr<\/a><\/p>\n<p>Lee Miller : Reportages de guerre, 1944-1945<\/p>\n<p><img decoding=\"async\" width=\"1400\" height=\"933\" loading=\"lazy\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/03\/lee-miller-reportages-de-guerre.jpg\" alt=\"\" class=\"wp-image-264914\"  \/><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"933\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/03\/lee-miller-reportages-de-guerre.jpg\" alt=\"\" class=\"wp-image-264914\"  \/><\/p>\n<p>Publi\u00e9 aux \u00e9ditions Bartillat, le livre Lee Miller : Reportages de guerre, 1944-1945 nous permet de (re)d\u00e9couvrir l\u2019engagement exceptionnel de la photographe. Ancienne \u00e9g\u00e9rie du magazine Vogue puis du photographe surr\u00e9aliste Man Ray, elle est accr\u00e9dit\u00e9e en 1942 par l\u2019US Army et capture des images du Blitz. Par la suite, elle est amen\u00e9e \u00e0 suivre le si\u00e8ge de Saint-Malo, la campagne d\u2019Alsace, la d\u00e9couverte des camps de concentration de\u00a0Buchenwald\u00a0et de\u00a0Dachau.<\/p>\n<p>Voir aussi<\/p>\n<p><a href=\"https:\/\/phototrend.fr\/2025\/09\/selection-livres-photo-septembre-2025\/\" class=\"mask-img\" title=\"Selection Livres Photo Septembre 2025\" rel=\"nofollow noopener\" target=\"_blank\"><img decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/03\/selection-livres-photo-septembre-2025-100x100.jpg\" class=\"attachment-thumbnail size-thumbnail zeen-lazy-load-base zeen-lazy-load  wp-post-image\" alt=\"\"   loading=\"lazy\"\/><img decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/03\/selection-livres-photo-septembre-2025-100x100.jpg\" class=\"attachment-thumbnail size-thumbnail zeen-lazy-load-base zeen-lazy-load  wp-post-image\" alt=\"\"   loading=\"lazy\"\/><\/a><\/p>\n<p>Point notable : c\u2019est non seulement par l\u2019image, mais aussi par le texte que Lee Miller se fait t\u00e9moin de l\u2019Histoire, puisqu\u2019elle accompagne ses photographies de ses propres \u00e9crits. \u00c0 la r\u00e9daction de Vogue, \u00e0 qui elle envoie ses clich\u00e9s des camps, elle \u00e9crit \u00ab\u00a0Je vous supplie de croire que c\u2019est vrai\u00a0\u00bb. L\u2019article du magazine porte le titre \u00ab\u00a0Believe It \u00bb, et comprend 7 pages d\u00e9di\u00e9es \u00e0 ses images.<\/p>\n<p>Enrichi d\u2019un avant-propos de David E. Scherman, l\u2019ouvrage rassemble ainsi une s\u00e9lection de textes \u00e9crits sur le vif. Cette 3e \u00e9dition, parue \u00e0 l\u2019occasion de la sortie <a href=\"https:\/\/www.google.com\/url?sa=t&amp;source=web&amp;rct=j&amp;opi=89978449&amp;url=https:\/\/phototrend.fr\/2024\/10\/critique-film-lee-miller-ellen-kuras\/&amp;ved=2ahUKEwiK39z07riTAxWkUqQEHRFGORUQFnoECB8QAQ&amp;usg=AOvVaw0HJy65CT_16g0qSNp1aCm2\" rel=\"nofollow noopener\" target=\"_blank\">du film Lee Miller d\u2019Ellen Kuras<\/a>, est enrichie par un corpus de photos prises par la photographe.<\/p>\n<p>Lee Miller : Reportages de guerre, 1944-1945, Edmonde Charles-Roux,\u00a0Lee Miller,\u00a0David E. Scherman<br \/>\u00c9diteur : Bartillat<br \/>25 \u20ac, 224 pages, broch\u00e9, 14 x 20,5 cm<br \/>Acheter le livre : <a href=\"https:\/\/www.leslibraires.fr\/livre\/20395712-reportages-de-guerre-1944-1945-lee-miller-bartillat?affiliate=phototrend\" rel=\"nofollow noopener\" target=\"_blank\">leslibraires.fr<\/a> \/ <a href=\"https:\/\/www.awin1.com\/cread.php?awinmid=12665&amp;awinaffid=282185&amp;clickref=&amp;p=https:\/\/www.fnac.com\/a16513068\/Lee-Miller-Reportages-de-guerre-1944-1945\" rel=\"nofollow noopener\" target=\"_blank\">Fnac<\/a><\/p>\n<p>Revue Transbordeur, n\u00b010<\/p>\n<p><img decoding=\"async\" width=\"1400\" height=\"933\" loading=\"lazy\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/03\/revue-transbordeur-numero-10.jpg\" alt=\"\" class=\"wp-image-264915\"  \/><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"933\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/03\/revue-transbordeur-numero-10.jpg\" alt=\"\" class=\"wp-image-264915\"  \/><\/p>\n<p>Depuis 2017, la revue Transbordeur explore chaque ann\u00e9e un aspect de l\u2019histoire photographique sous un angle social, technique ou politique. Pour sa dixi\u00e8me \u00e9dition, elle choisit un th\u00e8me aussi vaste qu\u2019ambigu : l\u2019argent \u2013 \u00e0 la fois m\u00e9tal au fondement du proc\u00e9d\u00e9 photographique \u2013 et nerf de la guerre \u00e9conomique de l\u2019image.<\/p>\n<p>La revue propose une exploration de la valeur et du travail derri\u00e8re l\u2019image, de la photographie sur carte postale \u00e0 la valorisation du fonds Gamma Rapho. Elle aborde l\u2019extraction du m\u00e9tal et les \u00e9conomies coloniales (mines d\u2019or sud-africaines, routes commerciales de l\u2019argent m\u00e9tal). Elle examine aussi la repr\u00e9sentation de l\u2019\u00e9conomie en images et les flux m\u00e9diatiques et financiers (fabrication des billets \u00e0 la Banque de France, naissance de la t\u00e9l\u00e9vision boursi\u00e8re). Enfin, elle propose une r\u00e9flexion en miroir sur l\u2019\u00e9conomie de la revue elle-m\u00eame.<\/p>\n<p>Au-del\u00e0 du dossier th\u00e9matique, Transbordeur \u00e9largit le spectre avec des articles sur la chambre noire photographique, sur Walter Benjamin comme th\u00e9oricien de la pr\u00e9sence photographique, ou encore sur la gen\u00e8se de\u00a0Bunker arch\u00e9ologie\u00a0de Paul Virilio.<\/p>\n<p>Cette revue annuelle s\u2019adresse \u00e0 un lectorat averti. La densit\u00e9 et la vari\u00e9t\u00e9 des sujets en font une r\u00e9f\u00e9rence pr\u00e9cieuse pour quiconque souhaite aller au-del\u00e0 de la surface des images.<\/p>\n<p>Revue Transbordeur, n\u00b010<br \/>\u00c9diteur : Macula<br \/>29 \u20ac, 216 pages, broch\u00e9, 21,6 x 27,9 cm<br \/>Acheter le livre : <a href=\"https:\/\/www.editionsmacula.com\/livre\/transbordeur-photographie-histoire-societe-n-10\/\" rel=\"nofollow noopener\" target=\"_blank\">\u00c9ditions Macula<\/a> \/ <a href=\"https:\/\/www.awin1.com\/cread.php?awinmid=12665&amp;awinaffid=282185&amp;clickref=&amp;p=https:\/\/www.fnac.com\/a22238521\/Christian-Joschke-Transbordeur-photographie-histoire-societe-n-10-Dossier-L-Argent-Photographie-monnaie-ressources-travail\" rel=\"nofollow noopener\" target=\"_blank\">Fnac<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Chaque mois, Phototrend vous propose de\u00a0d\u00e9couvrir les livres photo qui nous ont marqu\u00e9s. En ce mois de mars&hellip;\n","protected":false},"author":2,"featured_media":66864,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[20583,155,156,113,20584,20585,112,10194,20586,15041,20587,20588,9929,20589,23],"class_list":{"0":"post-66863","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-arts-et-design","8":"tag-arnaud-chochon","9":"tag-arts-and-design","10":"tag-arts-et-design","11":"tag-divertissement","12":"tag-editions-bartillat","13":"tag-editions-macula","14":"tag-entertainment","15":"tag-featured","16":"tag-lee-miller","17":"tag-malick-sidibe","18":"tag-reporters-sans-frontieres-rsf","19":"tag-revue-transbordeur","20":"tag-robert-capa","21":"tag-selection-livre-photo","22":"tag-suisse"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_fr\/116297517323062191","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/66863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/comments?post=66863"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/66863\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media\/66864"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media?parent=66863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/categories?post=66863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/tags?post=66863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}