{"id":66895,"date":"2026-03-26T21:31:08","date_gmt":"2026-03-26T21:31:08","guid":{"rendered":"https:\/\/www.europesays.com\/ch-fr\/66895\/"},"modified":"2026-03-26T21:31:08","modified_gmt":"2026-03-26T21:31:08","slug":"hubble-et-james-webb-revelent-des-details-saisissants","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-fr\/66895\/","title":{"rendered":"Hubble et James-Webb r\u00e9v\u00e8lent des d\u00e9tails saisissants"},"content":{"rendered":"<p>C&rsquo;est vers la fin du mois de juillet 1610 que <a href=\"https:\/\/www.futura-sciences.com\/sciences\/actualites\/astronomie-il-y-400-ans-galilee-decouvrait-saturne-24528\/\" title=\"Il y a 400 ans Galil\u00e9e d\u00e9couvrait Saturne\" rel=\"nofollow noopener\" target=\"_blank\">Galil\u00e9e<\/a> a point\u00e9 sa lunette astronomique en direction de <a href=\"https:\/\/www.futura-sciences.com\/sciences\/definitions\/saturne-saturne-3703\/\" rel=\"nofollow noopener\" target=\"_blank\">Saturne<\/a> pour y faire la d\u00e9couverte d&rsquo;un \u00e9trange aspect de la plan\u00e8te dont il ne saisit pas la signification &#8211; la puissance de son instrument n&rsquo;\u00e9tait pas suffisante pour atteindre le grossissement et la <a href=\"https:\/\/www.futura-sciences.com\/tech\/definitions\/informatique-resolution-18289\/\" rel=\"nofollow noopener\" target=\"_blank\">r\u00e9solution<\/a> n\u00e9cessaire. Mais la technologie des instruments d&rsquo;astronomie progressant,\u00a0le <a href=\"https:\/\/www.futura-sciences.com\/formation\/metiers\/metiers-mathematicien-293\/\" rel=\"nofollow noopener\" target=\"_blank\">math\u00e9maticien<\/a>, <a href=\"https:\/\/www.futura-sciences.com\/formation\/metiers\/metiers-astronome-7\/\" rel=\"nofollow noopener\" target=\"_blank\">astronome<\/a> et <a href=\"https:\/\/www.futura-sciences.com\/formation\/metiers\/metiers-physicien-42\/\" rel=\"nofollow noopener\" target=\"_blank\">physicien<\/a> hollandais <a href=\"https:\/\/www.futura-sciences.com\/sciences\/personnalites\/astronomie-christian-huygens-672\/\" rel=\"nofollow noopener\" target=\"_blank\">Christian Huygens<\/a> pourra, \u00e0 partir de 1656, affirmer que Saturne poss\u00e8de bien des anneaux.<\/p>\n<p class=\"text-center\">\n            <img decoding=\"async\" data-imgid=\"sm\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/03\/jupiter_io_europe_galileo_nasa_jpl_03.jpg\" width=\"320\" height=\"320\" alt=\"Un montage de diff\u00e9rentes images prises par la sonde Galileo. On voit \u00e0 gauche Jupiter et sa tache rouge et de haut en bas Io, Europe, Ganym\u00e8de et Callisto. \u00a9 N.A.S.A-JPL\" loading=\"lazy\"\/><\/p>\n<p>\n                Tags :<br \/>\n\tsciences\n<\/p>\n<p><a href=\"https:\/\/www.futura-sciences.com\/sciences\/actualites\/astronomie-route-vers-planetes-ardentes-andre-brahic-27456\/\" class=\"article-link\" target=\"_blank\" rel=\"nofollow noopener\"><br \/>\n        En route vers les plan\u00e8tes ardentes avec Andr\u00e9 Brahic<\/p>\n<p><\/a><\/p>\n<p>    Lire l&rsquo;article <\/p>\n<p>Ces anneaux, nous les conna\u00eetrons mieux avec les missions <a href=\"https:\/\/www.futura-sciences.com\/tech\/definitions\/logiciels-voyager-27675\/\" rel=\"nofollow noopener\" target=\"_blank\">Voyager<\/a> et surtout <a href=\"https:\/\/www.futura-sciences.com\/sciences\/actualites\/astronomie-bord-cassini-autour-saturne-andre-brahic-27544\/\" title=\"\u00c0 bord de Cassini autour de Saturne avec Andr\u00e9 Brahic\" rel=\"nofollow noopener\" target=\"_blank\">Cassini-Huygens<\/a>, mais ils n&rsquo;ont pas encore livr\u00e9 tous leurs secrets,\u00a0notamment celui de leur origine.<\/p>\n<p class=\"fs-media\">Deux images de Saturne, voir les commentaires sur les photos ci-dessous. \u00a9 Nasa, ESA, CSA, STScI, A. Simon (Nasa-GSFC), M. Wong (University of California), J. DePasquale (STScI), N. Bartmann (ESA\/Webb) Music: Stellardrone &#8211; Twilight<\/p>\n<p>Toujours est-il que dans ce but, les astronomes observent Saturne r\u00e9guli\u00e8rement avec le t\u00e9lescope spatial\u00a0Hubble dans le cadre du programme de surveillance OPAL (<a href=\"https:\/\/svs.gsfc.nasa.gov\/13783\" title=\"The Outer Planets: Hubble\u2019s Continuing Legacy\" rel=\"nofollow noopener\" target=\"_blank\">Outer Planet Atmospheres Legacy<\/a>), qui s&rsquo;\u00e9tend sur plus d&rsquo;une d\u00e9cennie, et aujourd&rsquo;hui le James-Webb, ce qui a conduit la Nasa et l&rsquo;ESA\u00a0a post\u00e9 r\u00e9cemment des communiqu\u00e9s au sujet des images prises par ces deux <a href=\"https:\/\/www.futura-sciences.com\/sante\/definitions\/corps-humain-\u0153il-14131\/\" rel=\"nofollow noopener\" target=\"_blank\">yeux<\/a> de la noosph\u00e8re du mois d&rsquo;ao\u00fbt 2024 \u00e0 2025. Images r\u00e9alis\u00e9es \u00e0 14 semaines d&rsquo;intervalle et qui montrent la plan\u00e8te passant de l&rsquo;\u00e9t\u00e9 bor\u00e9al \u00e0 l&rsquo;\u00e9quinoxe de 2025.<\/p>\n<p class=\"text-center\">\n            <img decoding=\"async\" data-imgid=\"sm\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/03\/brahic_jean_baptiste_feldmann.jpg\" width=\"320\" height=\"320\" alt=\"Le mardi 9 d\u00e9cembre 2014, Andr\u00e9 Brahic \u00e9tait l\u2019invit\u00e9 de la Soci\u00e9t\u00e9 astronomique de Bourgogne. Le sujet de sa conf\u00e9rence intitul\u00e9e\u00a0Enfants du Soleil\u00a0: \u00c0 la recherche de nos origines et de la vie dans l\u2019Univers portait aussi bien sur l\u2019origine du Syst\u00e8me solaire que sur l\u2019exobiologie. \u00a9 Jean-Baptiste Feldmann\" loading=\"lazy\"\/><\/p>\n<p>\n                Tags :<br \/>\n\tsciences\n<\/p>\n<p><a href=\"https:\/\/www.futura-sciences.com\/sciences\/actualites\/systeme-solaire-andre-brahic-seigneur-anneaux-planetaires-nous-quittait-il-y-5-ans-62810\/\" class=\"article-link\" target=\"_blank\" rel=\"nofollow noopener\"><br \/>\n        Andr\u00e9 Brahic, seigneur des anneaux plan\u00e9taires, nous quittait il y a 9 ans<\/p>\n<p><\/a><\/p>\n<p>    Lire l&rsquo;article <\/p>\n<p>Hubble observe surtout dans le visible et le t\u00e9lescope spatial James-Webb (JWST) dans l&rsquo;<a href=\"https:\/\/www.futura-sciences.com\/sciences\/definitions\/physique-infrarouge-1011\/\" rel=\"nofollow noopener\" target=\"_blank\">infrarouge<\/a>, ce qui offre aux scientifiques une compr\u00e9hension plus riche et plus nuanc\u00e9e de l&rsquo;<a href=\"https:\/\/www.futura-sciences.com\/planete\/definitions\/climatologie-atmosphere-850\/\" rel=\"nofollow noopener\" target=\"_blank\">atmosph\u00e8re<\/a> de la <a href=\"https:\/\/www.futura-sciences.com\/sciences\/questions-reponses\/astronomie-planete-tellurique-planete-gazeuse-differences-6462\/\" title=\"Plan\u00e8te tellurique, plan\u00e8te gazeuse : quelles diff\u00e9rences ?\" rel=\"nofollow noopener\" target=\"_blank\">g\u00e9ante gazeuse<\/a>.<\/p>\n<p>Le communiqu\u00e9 conjoint de la Nasa et de l&rsquo;ESA pr\u00e9cise que les deux instruments \u00ab captent la <a href=\"https:\/\/www.futura-sciences.com\/sciences\/definitions\/physique-lumiere-326\/\" rel=\"nofollow noopener\" target=\"_blank\">lumi\u00e8re<\/a> solaire r\u00e9fl\u00e9chie par les bandes nuageuses et les <a href=\"https:\/\/www.futura-sciences.com\/planete\/definitions\/meteorologie-brume-7395\/\" rel=\"nofollow noopener\" target=\"_blank\">brumes<\/a> de Saturne, mais tandis que Hubble r\u00e9v\u00e8le de subtiles variations de <a href=\"https:\/\/www.futura-sciences.com\/sciences\/definitions\/physique-couleur-4126\/\" rel=\"nofollow noopener\" target=\"_blank\">couleur<\/a> \u00e0 la surface de la plan\u00e8te, la vision infrarouge de Webb permet de d\u00e9tecter les <a href=\"https:\/\/www.futura-sciences.com\/planete\/definitions\/climatologie-nuage-14525\/\" rel=\"nofollow noopener\" target=\"_blank\">nuages<\/a> \u200b\u200bet les compos\u00e9s chimiques \u00e0 diff\u00e9rentes profondeurs atmosph\u00e9riques, des nuages \u200b\u200bprofonds \u00e0 la fine couche sup\u00e9rieure de l&rsquo;atmosph\u00e8re\u00a0\u00bb.<\/p>\n<p class=\"fs-media\">\n<p><img decoding=\"async\" data-imgid=\"full\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/03\/saturne webb hubble_NASA, ESA, CSA, STScI, Amy Simon (NASA-GSFC), Michael Wong (UC Berkeley); Image .jpeg\" width=\"1080\" height=\"2160\" alt=\"\" loading=\"lazy\"\/><br \/>\nUne comparaison c\u00f4te \u00e0 c\u00f4te d&rsquo;images de Saturne observ\u00e9es \u00e0 diff\u00e9rentes longueurs d&rsquo;onde et \u00e0 diff\u00e9rentes dates r\u00e9v\u00e8le des diff\u00e9rences d&rsquo;apparence entre l&rsquo;infrarouge (\u00e0 gauche) et la lumi\u00e8re visible (\u00e0 droite). L&rsquo;image de gauche est intitul\u00e9e \u00ab Saturne, lumi\u00e8re infrarouge du t\u00e9lescope Webb, 29 novembre 2024 \u00bb. L&rsquo;image de droite est intitul\u00e9e \u00ab Saturne, lumi\u00e8re visible du t\u00e9lescope Hubble, 22 ao\u00fbt 2024 \u00bb. En infrarouge, Saturne pr\u00e9sente des bandes horizontales. Les points blancs, repr\u00e9sentant plusieurs lunes de Saturne, sont nomm\u00e9s Janus, Dion\u00e9 et Encelade. En lumi\u00e8re visible, les bandes horizontales de Saturne apparaissent jaune p\u00e2le, certaines bandes proches des p\u00f4les Nord et Sud pr\u00e9sentant une teinte bleu clair. Les anneaux apparaissent d&rsquo;un blanc \u00e9clatant, leur luminosit\u00e9 \u00e9tant l\u00e9g\u00e8rement inf\u00e9rieure \u00e0 celle observ\u00e9e sur l&rsquo;image infrarouge du t\u00e9lescope Webb. Les points blancs, repr\u00e9sentant plusieurs lunes de Saturne, sont nomm\u00e9s Janus, Mimas et \u00c9pim\u00e9th\u00e9e. \u00a9\u00a0Nasa, ESA, CSA, STScI, Amy Simon (Nasa-GSFC), Michael Wong (UC Berkeley); Image Processing: Joseph DePasquale (STScI)<\/p>\n<p>Saturne, un laboratoire naturel pour l&rsquo;\u00e9tude de la dynamique des fluides<\/p>\n<p>Le communiqu\u00e9 ajoute : \u00ab\u00a0Sur l&rsquo;image du t\u00e9lescope Webb, un <a href=\"https:\/\/www.futura-sciences.com\/planete\/definitions\/climatologie-courant-jet-13182\/\" rel=\"nofollow noopener\" target=\"_blank\">courant-jet<\/a> persistant, surnomm\u00e9\u00a0\u00ab\u00a0onde ruban\u00a0\u00bb, serpente \u00e0 travers les <a href=\"https:\/\/www.futura-sciences.com\/planete\/definitions\/geographie-latitude-720\/\" rel=\"nofollow noopener\" target=\"_blank\">latitudes<\/a> moyennes de l&rsquo;<a href=\"https:\/\/www.futura-sciences.com\/planete\/definitions\/geographie-hemisphere-nord-12782\/\" rel=\"nofollow noopener\" target=\"_blank\">h\u00e9misph\u00e8re nord<\/a>, influenc\u00e9 par des ondes atmosph\u00e9riques autrement ind\u00e9tectables. Juste en dessous, une petite tache repr\u00e9sente un vestige de la Grande <a href=\"https:\/\/www.futura-sciences.com\/planete\/definitions\/climatologie-tempete-14551\/\" rel=\"nofollow noopener\" target=\"_blank\">Temp\u00eate<\/a> de Printemps de 2011-2012. Plusieurs autres temp\u00eates pars\u00e8ment l&rsquo;<a href=\"https:\/\/www.futura-sciences.com\/planete\/definitions\/geographie-hemisphere-sud-12813\/\" rel=\"nofollow noopener\" target=\"_blank\">h\u00e9misph\u00e8re sud<\/a> de Saturne et sont \u00e9galement visibles sur l&rsquo;image.<\/p>\n<p>Toutes ces formations sont sculpt\u00e9es par de puissants <a href=\"https:\/\/www.futura-sciences.com\/planete\/definitions\/climatologie-vent-14560\/\" rel=\"nofollow noopener\" target=\"_blank\">vents<\/a> et ondes sous la couche nuageuse visible, faisant de Saturne un laboratoire naturel pour l&rsquo;\u00e9tude de la dynamique des fluides dans des conditions extr\u00eames.<\/p>\n<p class=\"text-center\">\n            <img decoding=\"async\" data-imgid=\"sm\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/03\/Saturn-Hexagon_Cassini-Kevin-Gill.jpg\" width=\"320\" height=\"320\" alt=\"Des chercheurs de l\u2019universit\u00e9 de Harvard (\u00c9tats-Unis) proposent une explication \u00e0 la temp\u00eate en forme d\u2019hexagone du p\u00f4le nord de Saturne. \u00a9 Nasa, JPL-Caltech, SSI, Kevin M. Gill\" loading=\"lazy\"\/><\/p>\n<p>\n                Tags :<br \/>\n\tsciences\n<\/p>\n<p><a href=\"https:\/\/www.futura-sciences.com\/sciences\/actualites\/systeme-solaire-saturne-mais-formee-cette-etrange-tempete-hexagonale-50799\/\" class=\"article-link\" target=\"_blank\" rel=\"nofollow noopener\"><br \/>\n        Saturne : mais comment s&rsquo;est form\u00e9e cette \u00e9trange temp\u00eate hexagonale ?<\/p>\n<p><\/a><\/p>\n<p>    Lire l&rsquo;article <\/p>\n<p>Plusieurs des bords pointus du courant-jet hexagonal embl\u00e9matique de Saturne, d\u00e9couvert par la sonde Voyager en 1981 \u00e0 son p\u00f4le Nord, sont \u00e9galement faiblement visibles sur les deux images. Il demeure l&rsquo;un des ph\u00e9nom\u00e8nes m\u00e9t\u00e9orologiques les plus fascinants du <a href=\"https:\/\/www.futura-sciences.com\/sciences\/definitions\/univers-systeme-solaire-3728\/\" rel=\"nofollow noopener\" target=\"_blank\">Syst\u00e8me solaire<\/a>. Sa persistance pendant des d\u00e9cennies souligne la stabilit\u00e9 de certains processus atmosph\u00e9riques \u00e0 grande \u00e9chelle sur les <a href=\"https:\/\/www.futura-sciences.com\/sciences\/definitions\/univers-planete-geante-4547\/\" rel=\"nofollow noopener\" target=\"_blank\">plan\u00e8tes g\u00e9antes<\/a>. Ce sont probablement les derni\u00e8res images haute r\u00e9solution que nous verrons du c\u00e9l\u00e8bre hexagone avant les ann\u00e9es 2040, lorsque le p\u00f4le Nord entrera en <a href=\"https:\/\/www.futura-sciences.com\/planete\/definitions\/hiver-hiver-17687\/\" rel=\"nofollow noopener\" target=\"_blank\">hiver<\/a> et sombrera dans l&rsquo;obscurit\u00e9 pendant 15 ans.\u00a0\u00bb<\/p>\n<p class=\"fs-media\">\n<p><img decoding=\"async\" data-imgid=\"full\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/03\/saturne webb_NASA, ESA, CSA, STScI; Image Processing  Joseph DePasquale (STScI).jpg\" width=\"1080\" height=\"2494\" alt=\"\" loading=\"lazy\"\/><br \/>\nCette vue infrarouge \u00e9largie de Saturne a \u00e9t\u00e9 captur\u00e9e le 29 novembre 2024 par le t\u00e9lescope spatial James-Webb (Nasa, ESA, ASC). Titan est le point le plus grand et se situe \u00e0 l&rsquo;extr\u00eame gauche de l&rsquo;image, \u00e0 une certaine distance de Saturne et des autres lunes.\u00a0Hubble et Webb ont d\u00e9j\u00e0 explor\u00e9 les aurores de Saturne, apport\u00e9 des \u00e9clairages sur les spectaculaires aurores de Jupiter \u00e9galement observ\u00e9es par Hubble, confirm\u00e9 les aurores d&rsquo;Uranus aper\u00e7ues en 2011 par Hubble et d\u00e9tect\u00e9 pour la premi\u00e8re fois les aurores de Neptune gr\u00e2ce \u00e0 Webb. \u00a9\u00a0Nasa, ESA, CSA, STScI; Image Processing: Joseph DePasquale (STScI)<\/p>\n<p class=\"fs-media\">\n<p><img decoding=\"async\" data-imgid=\"full\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/03\/saturne webb_NASA, ESA, Image Processing  Joseph DePasquale (STScI).jpg\" width=\"1080\" height=\"1440\" alt=\"\" loading=\"lazy\"\/><br \/>\nSur l&rsquo;image infrarouge du t\u00e9lescope Webb, les anneaux apparaissent extr\u00eamement brillants car ils sont compos\u00e9s de glace d&rsquo;eau hautement r\u00e9fl\u00e9chissante. On distingue \u00e9galement des d\u00e9tails subtils, comme les rayons et la structure de l&rsquo;anneau B (la r\u00e9gion centrale \u00e9paisse des anneaux), qui diff\u00e8rent entre les deux observatoires. L&rsquo;anneau F, le plus externe, semble fin et net sur l&rsquo;image de Webb, tandis qu&rsquo;il brille l\u00e9g\u00e8rement sur celle de Hubble. \u00a9\u00a0Nasa, ESA, CSA, STScI; Image Processing: Joseph DePasquale (STScI)<\/p>\n<p>\n            <img decoding=\"async\" data-imgid=\"sm\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/03\/saturne coeur asterosismologie_Caltech R. Hurt  (IPAC).jpg\" width=\"320\" height=\"320\" alt=\"Une vue d'artiste de Saturne et de son int\u00e9rieur selon le mod\u00e8le propos\u00e9 dans une publication r\u00e9cente. \u00a9 Caltech\/R. Hurt (IPAC) \" loading=\"lazy\"\/><\/p>\n<p>\n                Tags :<br \/>\n\tsciences\n<\/p>\n<p><a href=\"https:\/\/www.futura-sciences.com\/sciences\/actualites\/astronomie-seismes-saturne-font-trembler-anneaux-revelent-son-interieur-93021\/\" class=\"article-link\" target=\"_blank\" rel=\"nofollow noopener\"><br \/>\n        Des s\u00e9ismes sur Saturne font trembler ses anneaux et r\u00e9v\u00e8lent son int\u00e9rieur<\/p>\n<p><\/a><\/p>\n<p>    Lire l&rsquo;article <\/p>\n","protected":false},"excerpt":{"rendered":"C&rsquo;est vers la fin du mois de juillet 1610 que Galil\u00e9e a point\u00e9 sa lunette astronomique en direction&hellip;\n","protected":false},"author":2,"featured_media":66896,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[7],"tags":[1301,6216,6586,20597,20598,61,57,59,58,23,60,62,6186],"class_list":["post-66895","post","type-post","status-publish","format-standard","has-post-thumbnail","category-sciences-et-technologies","tag-astronomie","tag-images-du-telescope-hubble","tag-james-webb-space-telescope","tag-saturne","tag-saturne-anneaux","tag-science","tag-science-and-technology","tag-sciences","tag-sciences-et-technologies","tag-suisse","tag-technologies","tag-technology","tag-telescope-spatial-james-webb"],"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_fr\/116297615534755729","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/66895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/comments?post=66895"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/66895\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media\/66896"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media?parent=66895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/categories?post=66895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/tags?post=66895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}