{"id":70139,"date":"2026-03-29T06:33:16","date_gmt":"2026-03-29T06:33:16","guid":{"rendered":"https:\/\/www.europesays.com\/ch-fr\/70139\/"},"modified":"2026-03-29T06:33:16","modified_gmt":"2026-03-29T06:33:16","slug":"les-suisses-reussissent-la-passe-de-trois","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-fr\/70139\/","title":{"rendered":"Les Suisses r\u00e9ussissent la passe de trois"},"content":{"rendered":"<p>L&rsquo;\u00e9quipe de Suisse emmen\u00e9e par le skip Marco H\u00f6sli poursuit sa s\u00e9rie de succ\u00e8s au Championnat du monde aux \u00c9tats-Unis. Le CC Glaris a remport\u00e9 sa troisi\u00e8me victoire en trois matches contre le Japon 8-3.<\/p>\n<p>Face aux Japonais, eux aussi invaincus jusqu\u2019alors, le score \u00e9tait de 3-3 apr\u00e8s cinq ends \u00e0 Ogden, dans l\u2019Utah. Le quatuor glaronnais compos\u00e9 de Justin Hausheer, Simon Gloor, du skip Marco H\u00f6sli et de Philipp H\u00f6sli a attendu le 8e end pour voler leur premi\u00e8re pierre du match et prendre l\u2019avantage 5-3. Lors de la manche suivante, le skip japonais Riku Yanagisawa a manqu\u00e9 sa derni\u00e8re pierre, ce qui a permis aux Helv\u00e8tes de r\u00e9aliser un coup de trois et de pousser leurs adversaires \u00e0 l&rsquo;abandon.<\/p>\n<p>Au classement, la Suisse partage la premi\u00e8re place avec la Su\u00e8de, qui a \u00e9galement remport\u00e9 ses trois premi\u00e8res rencontres. Toutes les autres nations ont d\u00e9j\u00e0 essuy\u00e9 au moins une d\u00e9faite. Elle disputera son prochain match dimanche soir contre la R\u00e9publique tch\u00e8que (22h00, heure suisse).<\/p>\n<p class=\"sources\">ats\/efas<\/p>\n","protected":false},"excerpt":{"rendered":"L&rsquo;\u00e9quipe de Suisse emmen\u00e9e par le skip Marco H\u00f6sli poursuit sa s\u00e9rie de succ\u00e8s au Championnat du monde&hellip;\n","protected":false},"author":2,"featured_media":70140,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[76,21479,3446,1009,456,219,1355,21480,21391,21392,186,75,916,23],"class_list":{"0":"post-70139","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sports","8":"tag-autres-sports","9":"tag-championnat-du-monde-1ere-phase-5e-journee","10":"tag-championnat-du-monde-de-hockey-sur-glace","11":"tag-competition-sportive","12":"tag-curling","13":"tag-hockey-sur-glace","14":"tag-japon","15":"tag-japon-suisse","16":"tag-marco-hosli","17":"tag-simon-gloor","18":"tag-sport","19":"tag-sports","20":"tag-succes","21":"tag-suisse"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_fr\/116311071421483666","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/70139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/comments?post=70139"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/70139\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media\/70140"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media?parent=70139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/categories?post=70139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/tags?post=70139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}