{"id":70817,"date":"2026-03-29T15:28:09","date_gmt":"2026-03-29T15:28:09","guid":{"rendered":"https:\/\/www.europesays.com\/ch-fr\/70817\/"},"modified":"2026-03-29T15:28:09","modified_gmt":"2026-03-29T15:28:09","slug":"la-marque-suisse-abri-studio-rencontre-le-succes-en-revisitant-les-classiques-vestimentaires","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-fr\/70817\/","title":{"rendered":"La marque suisse Abri Studio rencontre le succ\u00e8s en revisitant les classiques vestimentaires"},"content":{"rendered":"<p>Trois cent cinquante grammes. Voil\u00e0 ce que p\u00e8se en moyenne un livre de poche, une canette de soda pleine ou un magret de canard entier. C\u2019est aussi le poids \u2013 par m\u00e8tre carr\u00e9 \u2013 d\u2019une des toiles de coton servant \u00e0 fabriquer les jeans d\u2019Abri Studio. D\u2019un bleu nuit, tr\u00e8s profond, cette variante raw (\u00abbrute\u00bb) est un denim dit moyen, confortable mais assez robuste pour durer, qui d\u00e9veloppera une patine unique au fil du temps. Comme toutes les toiles utilis\u00e9es par la marque suisse, celle-ci a \u00e9t\u00e9 produite et trait\u00e9e dans le nord de l\u2019Italie, sur un circuit de production ultracourt. \u00abNous nous effor\u00e7ons d\u2019adopter des pratiques aussi \u00e9thiques et durables que possible, m\u00eame si tout n\u2019est pas parfait\u00bb, explique la styliste genevoise Agn\u00e8s Vadi [collaboratrice r\u00e9guli\u00e8re du magazine T, ndlr], qui a cofond\u00e9 Abri avec le cr\u00e9ateur b\u00e2lois Morris Manser.<\/p>\n<p>  <a class=\"glightbox\" href=\"https:\/\/www.letemps.ch\/placeholder.png\" data-type=\"image\" data-description=\"Toutes les toiles utilis\u00e9es par la marque suisse ont \u00e9t\u00e9 produites et trait\u00e9es dans le nord de l\u2019Italie, sur un circuit de production ultracourt. \u2014 \u00a9 Ulises Lozano\" data- rel=\"nofollow noopener\" target=\"_blank\"><\/p>\n<p>      <img decoding=\"async\" class=\"lazy\" title=\"Toutes les toiles utilis\u00e9es par la marque suisse ont \u00e9t\u00e9 produites et trait\u00e9es dans le nord de l\u2019Italie, sur un circuit de production ultracourt. \u2014 \u00a9 Ulises Lozano\" alt=\"Toutes les toiles utilis\u00e9es par la marque suisse ont \u00e9t\u00e9 produites et trait\u00e9es dans le nord de l\u2019Italie, sur un circuit de production ultracourt. \u2014 \u00a9 Ulises Lozano\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/03\/1774798089_137_large.jpeg\"\/><\/p>\n<p>  <\/a><br \/>\n  Toutes les toiles utilis\u00e9es par la marque suisse ont \u00e9t\u00e9 produites et trait\u00e9es dans le nord de l\u2019Italie, sur un circuit de production ultracourt. \u2014 \u00a9 Ulises Lozano<\/p>\n","protected":false},"excerpt":{"rendered":"Trois cent cinquante grammes. Voil\u00e0 ce que p\u00e8se en moyenne un livre de poche, une canette de soda&hellip;\n","protected":false},"author":2,"featured_media":70818,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[45,44,43,1978,822,174,238,23,1977],"class_list":{"0":"post-70817","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-economie","8":"tag-business","9":"tag-economie","10":"tag-economy","11":"tag-le-magazine-du-temps","12":"tag-mode","13":"tag-premium","14":"tag-societe","15":"tag-suisse","16":"tag-t"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_fr\/116313175186893423","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/70817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/comments?post=70817"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/70817\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media\/70818"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media?parent=70817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/categories?post=70817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/tags?post=70817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}