{"id":71234,"date":"2026-03-29T20:32:04","date_gmt":"2026-03-29T20:32:04","guid":{"rendered":"https:\/\/www.europesays.com\/ch-fr\/71234\/"},"modified":"2026-03-29T20:32:04","modified_gmt":"2026-03-29T20:32:04","slug":"sidaction-2026-36-millions-deuros-de-promesses-de-dons-29-03-2026-a-2222","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-fr\/71234\/","title":{"rendered":"Sidaction 2026: 3,6 millions d&rsquo;euros de promesses de dons &#8211; 29\/03\/2026 \u00e0 22:22"},"content":{"rendered":"<p>        <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/ch-fr\/wp-content\/uploads\/2026\/03\/fec3b63f8633f1b96f5b224f9a339f8a-760x507.jpg\" alt=\"Un 32e Sidaction pour raviver une lutte contre le VIH fragilis\u00e9e ( AFP \/ Jo\u00ebl SAGET )\" loading=\"eager\" fetchpriority=\"high\" width=\"760\" height=\"507\" style=\"max-width: 100%!important; height: auto;\"\/><\/p>\n<p class=\"c-image-news__legend\">Un 32e Sidaction pour raviver une lutte contre le VIH fragilis\u00e9e ( AFP \/ Jo\u00ebl SAGET )<\/p>\n<p>\n L&rsquo;association Sidaction a re\u00e7u 3,6 millions d&rsquo;euros de promesses de dons pour la lutte contre le sida lors de la 32e \u00e9dition de son weekend de collecte annuel, un montant en baisse par rapport \u00e0 l&rsquo;an pass\u00e9.\n<\/p>\n<p>\n \u00ab\u00a0Dans une p\u00e9riode o\u00f9 la menace d\u2019une crise \u00e9conomique internationale p\u00e8se sur chacun, nous tenons \u00e0 saluer la fid\u00e9lit\u00e9 et l\u2019engagement des donateurs. Cette mobilisation, bien qu\u2019en retrait, reste essentielle pour nous donner les moyens de poursuivre notre combat\u00a0\u00bb, a comment\u00e9 dimanche dans un communiqu\u00e9 Florence Thune, directrice g\u00e9n\u00e9rale de Sidaction, association cofond\u00e9e en 1994 par Pierre Berg\u00e9 et Line Renaud.\n<\/p>\n<p>\n L&rsquo;association, pr\u00e9sid\u00e9e par la cod\u00e9couvreuse du virus du sida au d\u00e9but des ann\u00e9es 1980 et prix Nobel de m\u00e9decine 2008 Fran\u00e7oise Barr\u00e9-Sinoussi, a exactement recueilli 3,614 millions d&rsquo;euros de promesses, contre 3,909 millions d&rsquo;euros en 2025.\n<\/p>\n<p>\n Les dons au Sidaction servent \u00e0 financer des recherches, des soins, des programmes d&rsquo;aide aux personnes vivant avec le VIH, en France et \u00e0 l&rsquo;\u00e9tranger, comme en Afrique.\n<\/p>\n<p>\n \u00ab\u00a0Nous faisons face \u00e0 une de nos plus graves crises: les financements se fragilisent alors m\u00eame que les besoins restent consid\u00e9rables. Il est imp\u00e9ratif de maintenir notre mobilisation collective pour \u00e9viter tout recul dans la lutte contre le VIH\/sida\u00a0\u00bb, a soulign\u00e9 Mme Thune.\n<\/p>\n<p>\n Depuis 2025 et l&rsquo;arr\u00eat des aides des Etats-Unis de Donald Trump, la lutte contre le VIH est \u00ab\u00a0prise en \u00e9tau\u00a0\u00bb. \u00ab\u00a0D&rsquo;un c\u00f4t\u00e9, de multiples baisses de financements, y compris par la France. De l&rsquo;autre, une mont\u00e9e de mouvements r\u00e9actionnaires qui s&rsquo;attaquent aux droits des femmes, des personnes LGBT+, des migrants\u00a0\u00bb, expliquait-elle il y a quelques jours \u00e0 l&rsquo;AFP.\n<\/p>\n<p>\n Si les traitements antir\u00e9troviraux et les outils de pr\u00e9vention innovants comme la prophylaxie pr\u00e9-exposition (PrEP) ont permis des progr\u00e8s majeurs, pr\u00e8s de 41 millions de personnes vivent encore avec le VIH dans le monde, dont un quart environ sans traitement. Et pr\u00e8s de 600.000 meurent chaque ann\u00e9e des suites du sida.\n<\/p>\n<p>\n En France, quelque 180.000 personnes vivent avec le VIH et le nombre de nouvelles d\u00e9couvertes de s\u00e9ropositivit\u00e9 stagne autour de 5.000, dont environ un tiers chez des femmes.<\/p>\n","protected":false},"excerpt":{"rendered":"Un 32e Sidaction pour raviver une lutte contre le VIH fragilis\u00e9e ( AFP \/ Jo\u00ebl SAGET ) L&rsquo;association&hellip;\n","protected":false},"author":2,"featured_media":71235,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[48,46,56,53,83,51,50,47,52,84,49,23,54,55],"class_list":{"0":"post-71234","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sante","8":"tag-action-cac-40","9":"tag-bourse-de-paris","10":"tag-boursorama","11":"tag-cotations","12":"tag-health","13":"tag-indices-devises","14":"tag-investir","15":"tag-investissement","16":"tag-marche-boursier","17":"tag-sante","18":"tag-sicav","19":"tag-suisse","20":"tag-trackers","21":"tag-warrants"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_fr\/116314370481489089","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/71234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/comments?post=71234"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/71234\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media\/71235"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media?parent=71234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/categories?post=71234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/tags?post=71234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}