{"id":80946,"date":"2026-04-06T14:48:13","date_gmt":"2026-04-06T14:48:13","guid":{"rendered":"https:\/\/www.europesays.com\/ch-fr\/80946\/"},"modified":"2026-04-06T14:48:13","modified_gmt":"2026-04-06T14:48:13","slug":"pierre-cassiere-et-le-pari-fou-dorganiser-un-festival-de-metal-a-millau","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-fr\/80946\/","title":{"rendered":"Pierre Cassi\u00e8re et le pari fou d\u2019organiser un festival de m\u00e9tal \u00e0 Millau"},"content":{"rendered":"<p>\n                                                                Fondateur et pr\u00e9sident de l\u2019association Metalheads, Pierre Cassi\u00e8re revient sur son amour pour le m\u00e9tal et son r\u00eave, en passe de se r\u00e9aliser, d\u2019organiser un festival.\n                            <\/p>\n<p>\u00c0 <a href=\"https:\/\/www.midilibre.fr\/aveyron\/millau\/\" target=\"_self\" rel=\"nofollow noopener\">Millau<\/a>, difficile de vivre pleinement sa passion pour le m\u00e9tal sans faire des kilom\u00e8tres. Alors Pierre Cassi\u00e8re a d\u00e9cid\u00e9 de ne plus attendre\u00a0: \u00e0 35 ans, il se lance dans un projet ambitieux, celui de cr\u00e9er un <a href=\"https:\/\/www.midilibre.fr\/2026\/03\/14\/un-nouveau-festival-de-metal-sinstalle-a-millau-en-2027-13270803.php\" target=\"_self\" rel=\"nofollow noopener\">festival <\/a>d\u00e9di\u00e9 \u00e0 cette musique qui le suit depuis l\u2019adolescence.<\/p>\n<p>C\u2019est \u00e0 12 ans\u00a0que le jeune Pierre bascule dans l\u2019univers fracassant, addictif et d\u00e9routant du m\u00e9tal. Dans les ann\u00e9es 90, le futur policier municipal de Millau et pr\u00e9sident de l\u2019association <a href=\"https:\/\/www.midilibre.fr\/2026\/03\/14\/un-nouveau-festival-de-metal-sinstalle-a-millau-en-2027-13270803.php\" target=\"_self\" rel=\"nofollow noopener\">Metalheads<\/a>, dont un festival \u00e9ponyme verra le jour en 2027, se prend de passion pour les CD de rock de sa s\u0153ur\u00a0: Linkin Park, Nickelback\u2026 Tr\u00e8s vite, au coll\u00e8ge, les \u00e9changes de disques avec les copains et les d\u00e9couvertes de groupes de m\u00e9tal se multiplient. Sans vraiment s\u2019en rendre compte, il scelle d\u00e9finitivement son alliance avec ce style musical qui le prend aux tripes et ne l\u2019a jamais l\u00e2ch\u00e9.<\/p>\n<p>Pierre\u00a0Cassi\u00e8re\u00a0grandit et fait ses \u00e9tudes \u00e0 Millau avant de partir en 2010 \u00e9tudier le droit \u00e0 Albi puis \u00e0 Montpellier. Deux ans plus tard, il change de cap et s\u2019oriente vers les forces de l\u2019ordre. Il devient adjoint volontaire de gendarmerie en 2014, pour cinq ans. Une mutation le ram\u00e8ne finalement \u00e0 Millau, avant d\u2019int\u00e9grer la police municipale fin 2019, o\u00f9 il est encore aujourd\u2019hui.<\/p>\n<p>Un manque \u00e0 combler dans la r\u00e9gion<\/p>\n<p>Derri\u00e8re l\u2019uniforme, une autre facette s\u2019exprime. Depuis 2011, Pierre Cassi\u00e8re\u00a0n\u2019a rat\u00e9 que deux \u00e9ditions du Hellfest. Il sillonne la France pour assister \u00e0 des concerts et voir ses groupes pr\u00e9f\u00e9r\u00e9s. \u00ab\u00a0Quand tu habites ici et que tu \u00e9coutes du m\u00e9tal, tu es oblig\u00e9 de bouger. C\u2019est un peu le vide ici\u00a0\u00bb, constate-t-il, \u00e9voquant tout de m\u00eame le Xtrem Fest, vers Albi \u00ab\u00a0plus orient\u00e9 punk\u00a0\u00bb.<\/p>\n<p>\u00c0 aujourd\u2019hui 35 ans, il estime avoir le recul et l\u2019exp\u00e9rience n\u00e9cessaire pour se lancer dans le projet fou d\u2019organiser un festival\u00a0: \u00ab\u00a0\u00c7a faisait huit ans que j\u2019avais cette id\u00e9e en t\u00eate \u00ab\u00a0, confie-t-il. Un r\u00eave nourri par ses exp\u00e9riences b\u00e9n\u00e9voles aux Natural Games, o\u00f9 il intervenait sur la partie s\u00e9curit\u00e9. \u00ab\u00a0J\u2019ai vraiment v\u00e9cu l\u2019exp\u00e9rience d\u2019un festival de l\u2019int\u00e9rieur. Voir comment tout s\u2019organise, c\u2019est super int\u00e9ressant.\u00a0\u00bb<\/p>\n<p>De l\u2019observation \u00e0 l\u2019action, il n\u2019y a qu\u2019un pas, et \u00e0 force de voir, il a eu envie de faire, m\u00eame si le chemin s\u2019annonce exigeant\u00a0: \u00ab\u00a0C\u2019est \u00e9norm\u00e9ment de travail, mais c\u2019est aussi un r\u00eave. On esp\u00e8re p\u00e9renniser le festival par la suite.\u00a0\u00bb<\/p>\n<p>Aujourd\u2019hui, l\u2019association Metalheads peut compter sur une cinquantaine de b\u00e9n\u00e9voles. Un collectif \u00e9clectique, \u00e0 l\u2019image du projet. \u00ab\u00a0On a des policiers, une directrice de Biocoop, un banquier, des fonctionnaires, des professions ind\u00e9pendantes\u2026\u00a0\u00bb, mentionne Pierre Cassi\u00e8re. Une diversit\u00e9 qui fait la force du groupe, compos\u00e9 d\u2019amis, de rencontres en festival et surtout de passionn\u00e9s de m\u00e9tal.<\/p>\n<p>\u00ab\u00a02027, c\u2019est demain\u00a0\u00bb<\/p>\n<p>Le festival, lui, se pr\u00e9pare activement depuis deux ans. Pr\u00e9vu pour l\u2019\u00e9t\u00e9 2027, il avance sans retard, m\u00eame si la programmation, en cours de construction, n\u00e9cessite un peu de patience. \u00ab\u00a0Il n\u2019y a pas assez d\u2019heures dans une journ\u00e9e. Trouver l\u2019\u00e9quilibre entre la vie personnelle, professionnelle et associative n\u2019a pas \u00e9t\u00e9 simple. Aujourd\u2019hui, j\u2019y arrive mieux\u2026 Mais c\u2019est tellement prenant que \u00e7a en devient g\u00e9nial.\u00a0\u00bb<\/p>\n<p>Au-del\u00e0 de l\u2019\u00e9v\u00e9nement, l\u2019objectif est aussi culturel\u00a0: faire tomber les id\u00e9es re\u00e7ues sur le m\u00e9tal et partager cette passion avec le plus grand nombre.\u00a0Pierre Cassi\u00e8re imagine d\u00e9j\u00e0 des initiatives pour impliquer les habitants, comme un syst\u00e8me de loterie participative permettant de faire gagner des places aux Millavois.\u00a0\u00ab\u00a02027, c\u2019est demain\u00a0\u00bb, glisse-t-il avec enthousiasme. Un projet r\u00eav\u00e9, en passe de se r\u00e9aliser.<\/p>\n","protected":false},"excerpt":{"rendered":"Fondateur et pr\u00e9sident de l\u2019association Metalheads, Pierre Cassi\u00e8re revient sur son amour pour le m\u00e9tal et son r\u00eave,&hellip;\n","protected":false},"author":2,"featured_media":80947,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[694,5977,1353,113,112,5576,140,141,238,23],"class_list":{"0":"post-80946","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-musique","8":"tag-actu","9":"tag-associations","10":"tag-aveyron","11":"tag-divertissement","12":"tag-entertainment","13":"tag-millau","14":"tag-music","15":"tag-musique","16":"tag-societe","17":"tag-suisse"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_fr\/116358316386951154","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/80946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/comments?post=80946"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/80946\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media\/80947"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media?parent=80946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/categories?post=80946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/tags?post=80946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}