{"id":86359,"date":"2026-04-11T09:55:28","date_gmt":"2026-04-11T09:55:28","guid":{"rendered":"https:\/\/www.europesays.com\/ch-fr\/86359\/"},"modified":"2026-04-11T09:55:28","modified_gmt":"2026-04-11T09:55:28","slug":"un-premier-cas-europeen-de-grippe-aviaire-chez-lhomme-detecte-en-europe","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-fr\/86359\/","title":{"rendered":"Un premier cas europ\u00e9en de grippe aviaire chez l&rsquo;homme d\u00e9tect\u00e9 en Europe"},"content":{"rendered":"<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Un homme adulte de retour du S\u00e9n\u00e9gal a contract\u00e9 le virus. Il n&rsquo;y a eu aucune exposition \u00e0 des volailles ni \u00e0 des personnes pr\u00e9sentant des sympt\u00f4mes similaires. L&rsquo;homme est d\u00e9sormais en voie de gu\u00e9rison.<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">Il s&rsquo;agit de la souche A(H9N2), qui pr\u00e9sente de fortes similitudes avec des souches pr\u00e9c\u00e9dentes d\u00e9tect\u00e9es chez des volailles au S\u00e9n\u00e9gal.<\/p>\n<p class=\"ap-StoryElement ap-StoryElement--mb ap-StoryText\">La grippe aviaire est fr\u00e9quente chez les oiseaux, mais peut \u00e9galement infecter les humains. Il s&rsquo;agit g\u00e9n\u00e9ralement d&rsquo;un contact direct avec un animal infect\u00e9 ou d&rsquo;un contact indirect avec un environnement contamin\u00e9. Aucune transmission interhumaine n&rsquo;a encore \u00e9t\u00e9 constat\u00e9e. Chez l&rsquo;homme, la grippe aviaire provoque g\u00e9n\u00e9ralement des sympt\u00f4mes b\u00e9nins, mais dans des cas exceptionnels, la maladie peut \u00e9galement \u00eatre mortelle.<\/p>\n","protected":false},"excerpt":{"rendered":"Un homme adulte de retour du S\u00e9n\u00e9gal a contract\u00e9 le virus. Il n&rsquo;y a eu aucune exposition \u00e0&hellip;\n","protected":false},"author":2,"featured_media":86360,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[1063,83,1214,1777,84,3465,23],"class_list":{"0":"post-86359","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sante","8":"tag-animaux","9":"tag-health","10":"tag-italie","11":"tag-onu","12":"tag-sante","13":"tag-senegal","14":"tag-suisse"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_fr\/116385475581474798","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/86359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/comments?post=86359"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/86359\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media\/86360"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media?parent=86359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/categories?post=86359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/tags?post=86359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}