{"id":86958,"date":"2026-04-12T05:36:05","date_gmt":"2026-04-12T05:36:05","guid":{"rendered":"https:\/\/www.europesays.com\/ch-fr\/86958\/"},"modified":"2026-04-12T05:36:05","modified_gmt":"2026-04-12T05:36:05","slug":"au-dela-des-mots-avez-vous-vu-ce-remake-de-netflix-dun-film-francais-aux-74-millions-dentrees","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/ch-fr\/86958\/","title":{"rendered":"Au-del\u00e0 des mots : Avez-vous vu ce remake de Netflix d\u2019un film fran\u00e7ais aux 7,4 millions d\u2019entr\u00e9es ?"},"content":{"rendered":"<p>Au-del\u00e0 des mots, sorti le 3 avril, est le num\u00e9ro 8 du<a href=\"https:\/\/www.programme-tv.net\/news\/cinema\/208247-notre-top-10-des-meilleurs-films-netflix\/\" data-api-deeplink=\"teleloisirs:\/\/news\/208247\" rel=\"nofollow noopener\" target=\"_blank\"> Top 10 des films <\/a>les plus vus du moment sur Netflix ! Dans ce film, on suit Eletta, une adolescente r\u00e9serv\u00e9e qui grandit aupr\u00e8s de parents et d&rsquo;un fr\u00e8re sourds. Elle se d\u00e9couvre une passion pour le chant mais, pour poursuivre sa vocation, elle va devoir s&rsquo;\u00e9loigner de sa famille&#8230; Si le sc\u00e9nario vous dit quelque chose, c&rsquo;est normal ! Au-del\u00e0 des mots est le remake italien de La Famille B\u00e9lier.<\/p>\n<p>Sorti en 2014, le film fran\u00e7ais d&rsquo;Eric Lartigau avait attir\u00e9 plus de 7,4 millions de personnes en salles. Un engouement qui fait de La Famille B\u00e9lier l&rsquo;un des grands succ\u00e8s populaires du cin\u00e9ma fran\u00e7ais qui avait valu le C\u00e9sar du meilleur espoir f\u00e9minin \u00e0 Louane. \u00c0 ses c\u00f4t\u00e9s, on retrouvait <a href=\"https:\/\/www.programme-tv.net\/news\/cinema\/321977-la-famille-belier-m6-pourquoi-francois-damiens-et-karin-viard-ont-ils-mal-vecu-le-tournage\/\" data-api-deeplink=\"teleloisirs:\/\/news\/321977\" rel=\"nofollow noopener\" target=\"_blank\">Karin Viard et Fran\u00e7ois Damiens<\/a> pour incarner les parents et <a href=\"https:\/\/www.programme-tv.net\/news\/cinema\/400051-la-famille-belier-que-devient-luca-gelberg-le-frere-de-louane-dans-le-film\/\" data-api-deeplink=\"teleloisirs:\/\/news\/400051\" rel=\"nofollow noopener\" target=\"_blank\">Lucas Gelberg<\/a> dans le r\u00f4le du fr\u00e8re.<\/p>\n<p>                        Au-del\u00e0 des mots sur Netflix : une version italienne plus inclusive<\/p>\n<p>Dans cette nouvelle version, le personnage d&rsquo;Eletta est interpr\u00e9t\u00e9 par la chanteuse Sarah Toscano, qui, comme Louane \u00e0 l&rsquo;\u00e9poque, fait ici ses premiers pas d&rsquo;actrice. Pour l&rsquo;occasion, elle a d&rsquo;ailleurs enregistr\u00e9 un titre qui fait partie de la bande originale du film.<\/p>\n<p>Contrairement \u00e0 la version fran\u00e7aise, ici ce sont des acteurs sourds qui incarnent les personnages, une premi\u00e8re en Italie. \u00ab\u00a0Il \u00e9tait important de repr\u00e9senter ce que nous sommes dans la r\u00e9alit\u00e9\u00a0\u00bb, soulignent Emilio et Carola Insolera, les acteurs qui interpr\u00e8tent les parents d&rsquo;Eletta, dans le magazine Amica. L&rsquo;absence d&rsquo;acteurs sourds avait d&rsquo;ailleurs \u00e9t\u00e9 l&rsquo;objet de pol\u00e9mique lors de la sortie de La Famille B\u00e9lier.<\/p>\n<p>            Le film La Famille B\u00e9lier avait d\u00e9j\u00e0 \u00e9t\u00e9 adapt\u00e9 aux Etats-Unis<\/p>\n<p>En 2022, l&rsquo;adaptation am\u00e9ricaine, intitul\u00e9e Coda (acronyme pour Child of deaf adults, un enfant \u00e9lev\u00e9 par des parents sourds), avait elle aussi fait appel \u00e0 des acteurs sourds. Le film a remport\u00e9 l&rsquo;Oscar du meilleur long m\u00e9trage. La r\u00e9alisatrice Sian Heder a, elle, re\u00e7u l&rsquo;Oscar du meilleur sc\u00e9nario adapt\u00e9 et Troy Kotsur, l&rsquo;acteur sourd, a aussi re\u00e7u la pr\u00e9cieuse statuette dans la cat\u00e9gorie du meilleur second r\u00f4le.<\/p>\n<p>Le succ\u00e8s de La Famille B\u00e9lier d\u00e9passe donc largement les fronti\u00e8res fran\u00e7aises, ce qui explique sans doute le projet r\u00e9cemment annonc\u00e9 de <a href=\"https:\/\/www.programme-tv.net\/news\/cinema\/400167-la-famille-belier-ou-en-est-le-projet-de-suite\/\" data-api-deeplink=\"teleloisirs:\/\/news\/400167\" rel=\"nofollow noopener\" target=\"_blank\">donner une suite au film.<\/a><\/p>\n<p>Article \u00e9crit en collaboration avec 6Medias<\/p>\n","protected":false},"excerpt":{"rendered":"Au-del\u00e0 des mots, sorti le 3 avril, est le num\u00e9ro 8 du Top 10 des films les plus&hellip;\n","protected":false},"author":2,"featured_media":86959,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[24713,24712,489,113,112,24711,139,138,1229,24710,137,486,485,23,487],"class_list":{"0":"post-86958","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-films","8":"tag-au-delu00e0-des-mots","9":"tag-au-delu00e0-des-mots-2026","10":"tag-commentaire","11":"tag-divertissement","12":"tag-entertainment","13":"tag-eric-lartigau","14":"tag-film","15":"tag-films","16":"tag-louane","17":"tag-louane-emera","18":"tag-movies","19":"tag-netflix","20":"tag-pub-streaming-netflix","21":"tag-suisse","22":"tag-svod"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@ch_fr\/116390119534777575","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/86958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/comments?post=86958"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/posts\/86958\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media\/86959"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/media?parent=86958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/categories?post=86958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/ch-fr\/wp-json\/wp\/v2\/tags?post=86958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}