{"id":1000136,"date":"2026-05-07T02:52:20","date_gmt":"2026-05-07T02:52:20","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1000136\/"},"modified":"2026-05-07T02:52:20","modified_gmt":"2026-05-07T02:52:20","slug":"deutschland-sollte-mehr-nationalhymne-wagen","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1000136\/","title":{"rendered":"Deutschland sollte mehr Nationalhymne wagen"},"content":{"rendered":"<p class=\"text-center\">Jetzt neu bei t-online:<\/p>\n<p class=\"text-center\">Schriftgr\u00f6\u00dfe anpassen!<\/p>\n<p><img loading=\"lazy\" src=\"https:\/\/www.t-online.de\/s\/paper\/_next\/static\/media\/font-sizes.32942e33.svg\" alt=\"\" title=\"\" class=\"block h-[calc(var(--height)_\/_16_*_1rem)] w-[calc(var(--width)_\/_16_*_1rem)] max-w-none group-hover:hidden group-aria-expanded:hidden\" style=\"--width:16;--height:16\" decoding=\"async\"\/><img loading=\"lazy\" src=\"https:\/\/www.t-online.de\/s\/paper\/_next\/static\/media\/font-sizes-dark-mode.e382645c.svg\" alt=\"\" title=\"\" class=\"block h-[calc(var(--height)_\/_16_*_1rem)] w-[calc(var(--width)_\/_16_*_1rem)] max-w-none hidden group-hover:block group-aria-expanded:block\" style=\"--width:16;--height:16\" decoding=\"async\"\/><img loading=\"lazy\" src=\"https:\/\/www.t-online.de\/s\/paper\/_next\/static\/media\/sharing-menu-icon.1eb71368.svg\" alt=\"\" title=\"\" class=\"block h-[calc(var(--height)_\/_16_*_1rem)] w-[calc(var(--width)_\/_16_*_1rem)] max-w-none group-hover:brightness-0 group-hover:invert\" style=\"--width:16;--height:16\" decoding=\"async\"\/>Artikel teilen<\/p>\n<p class=\"font-bold text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\"><strong class=\"font-bold\">Guten Morgen, liebe Leserin, lieber Leser,<\/strong><\/p>\n<p class=\"text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\"><strong class=\"font-bold\">Markus S\u00f6der hat es wieder mal geschafft.<\/strong> Seine Kultusministerin schickte einen Brief mit einem Hymnen-Erlass an bayerische Schulen. In Zukunft sollen im Freistaat bei Abschlussfeiern die Bayernhymne sowie die National- oder die Europahymne gespielt werden. Eine Pflicht, mitzusingen, gibt es nicht.<\/p>\n<p class=\"text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\"><strong class=\"font-bold\">Die Reaktionen erfolgten zuverl\u00e4ssig und reichten von &#8222;Ablenkung von den wahren Problemen im Bildungsbereich&#8220; (SPD) hin zu &#8222;Schnapsidee&#8220; (Lehrergewerkschaft GEW).<\/strong> Dabei kann man S\u00f6der hier einmal in Schutz nehmen: Er hatte schon wesentlich schlechtere Ideen als diese. Ein Hymnen-Erlass w\u00e4re auch f\u00fcr andere Bundesl\u00e4nder eine gute Idee.<\/p>\n<p class=\"text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\"><strong class=\"font-bold\">Optimalerweise n\u00e4mlich wird der Erlass p\u00e4dagogisch unterf\u00fcttert.<\/strong> Will hei\u00dfen: Es wird den Sch\u00fclern nicht einfach einmal im Jahr Bl\u00e4ser-Sound in die Geh\u00f6rg\u00e4nge gezwungen, sondern sie erfahren im Unterricht mehr als bisher an vielen Schulen \u00fcblich \u00fcber den Sinn, die Inhalte und die Geschichte der Hymnen. Zugleich k\u00f6nnen sie durch die M\u00f6glichkeit, die Hymne auch zu singen, positiven Patriotismus statt verderblichen Nationalismus erleben.<\/p>\n<p class=\"text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\"><strong class=\"font-bold\">F\u00fcr die Bayernhymne vermag ich aufgrund meiner etwas n\u00f6rdlicheren Herkunft nicht zu sprechen.<\/strong> F\u00fcr die deutsche Nationalhymne aber kann ich sagen: Es w\u00e4re bitter notwendig. Speziell in dieser Zeit, in der Kr\u00e4fte in der Bundesrepublik den Blick auf die Vergangenheit verstellen und die kollektive Erinnerung verzerren wollen, ist es angezeigt, sich dem Thema zu widmen, Wissen und positive Pr\u00e4senz zu f\u00f6rdern. Leere K\u00f6pfe und Herzen sind zu leicht zu kapern.<\/p>\n<p class=\"text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\"><strong class=\"font-bold\">Wie leer die K\u00f6pfe und Herzen der Deutschen mit Blick auf die Insignien der Bundesrepublik sind, wird jeder wissen, der schon einmal eine Zeit lang in den USA verbracht hat.<\/strong> Ich arbeitete nach dem Schulabschluss als Au-pair an der Ostk\u00fcste und war vom Patriotismus dort erst einmal erschlagen: Der Achtj\u00e4hrige, auf den ich aufpasste, sang mit seiner gesamten Klasse die Nationalhymne und leistete den Treueeid auf die Nation. Jeden Morgen, kleine H\u00e4nde auf den Herzen, der US-Flagge im Klassenzimmer zugewandt. Von den Feierlichkeiten zum Nationalfeiertag am 4. Juli, an dem ausnahmslos jedes Haus unabh\u00e4ngig vom Wahlverhalten seiner Bewohner in Rot, Wei\u00df und Blau geschm\u00fcckt wurde, nicht zu sprechen. Und das war lange vor Trump.<\/p>\n<p><a href=\"#focus-1\" class=\"transition-colors duration-200 block text-current relative\" data-sctrack=\"FocusGalleryImage.Reference\"><img   loading=\"lazy\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/05\/das-ganze-land-feiert-rot-blau-weisses-feuerwerk-zum-unabhaengigkeitstag-in-den-usa.jpg\" alt=\"Das ganze Land feiert: rot-blau-wei\u00dfes Feuerwerk zum Unabh\u00e4ngigkeitstag in den USA.\" title=\"Das ganze Land feiert: rot-blau-wei\u00dfes Feuerwerk zum Unabh\u00e4ngigkeitstag in den USA.\" width=\"4000\" height=\"2662\" class=\"h-full w-full max-w-full rounded-8\" decoding=\"async\"\/><img loading=\"lazy\" src=\"https:\/\/www.t-online.de\/s\/paper\/_next\/static\/media\/zoom-in.f7dae02f.svg\" alt=\"Vergr\u00f6\u00dfern des Bildes\" title=\"Vergr\u00f6\u00dfern des Bildes\" class=\"block h-[calc(var(--height)_\/_16_*_1rem)] w-[calc(var(--width)_\/_16_*_1rem)] max-w-none absolute bottom-8 right-8 rounded-4 bg-snow p-8\" style=\"--width:32;--height:32\" decoding=\"async\"\/>Das ganze Land feiert: Rot-blau-wei\u00dfes Feuerwerk zum Unabh\u00e4ngigkeitstag in den USA. (Quelle: IMAGO\/Dylan Townsend)<\/a><\/p>\n<p class=\"text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\"><strong class=\"font-bold\">F\u00fcr mich als Deutsche waren das erst einmal befremdliche Anblicke.<\/strong> Um dann zu sp\u00fcren: Dieser Patriotismus hat nichts B\u00f6ses, hat nichts Aggressives. Er ist Freude an der eigenen Herkunft, Ausdruck von Verbundenheit mit Land, Geschichte, einander.<\/p>\n<p class=\"text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\"><strong class=\"font-bold\">Das war vor gut 20 Jahren. Inzwischen hat sich auch in Deutschland ein bisschen etwas ge\u00e4ndert.<\/strong> Vor allem internationale Fu\u00dfballturniere haben die Deutschlandflagge zumindest zwischenzeitlich en vogue gemacht. Aus unpolitischem Stolz auf die Mannschaft erwuchs Stolz auf das Land, beginnend mit dem Sommerm\u00e4rchen 2006. Ein buntes, fr\u00f6hliches, entspanntes Fahnenmeer.<\/p>\n<p class=\"text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\"><strong class=\"font-bold\">Seit 2013 hat sich auch die AfD dem Thema Patriotismus verschrieben.<\/strong> Speziell die Ost-AfD aber tut das immer wieder mit dem Ziel, die Nazi-Zeit als dunkelstes Kapitel der Deutschen kleinzureden. Th\u00fcringens AfD-Chef Bj\u00f6rn H\u00f6cke beispielsweise forderte eine &#8222;erinnerungspolitische Wende um 180 Grad&#8220; schon 2017 in seiner Rede vom &#8222;Denkmal der Schande&#8220;. 2018 dann wollte Alexander Gauland die Verbrechen der Nazis auf einen &#8222;Vogelschiss&#8220; verschrumpfen. Jetzt, 2026, pl\u00e4diert die AfD in Sachsen-Anhalt in ihrem Wahlprogramm f\u00fcr ein Ende von &#8222;Identit\u00e4tsst\u00f6rung&#8220; und &#8222;Schuldkomplex&#8220;. Verbunden mit ganz konkreten Ma\u00dfnahmen: Schulklassen sollen nicht mehr KZ- und NS-Gedenkst\u00e4tten besuchen. Die gefallenen Soldaten beider Weltkriege sollen unter einer AfD-Regierung gleicherma\u00dfen geehrt werden \u2013 also auch jene, die f\u00fcr das nationalsozialistische Regime k\u00e4mpften.<\/p>\n<p><a href=\"#focus-2\" class=\"transition-colors duration-200 block text-current relative\" data-sctrack=\"FocusGalleryImage.Reference\"><img   loading=\"lazy\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/05\/16-bundesparteitag-der-alternative-fuer-deutschland-am-12-012025-in-der-wt-energiesysteme-arena-in-r.jpeg\" alt=\"imago images 0795974722\" title=\"imago images 0795974722\" width=\"3861\" height=\"2172\" class=\"h-full w-full max-w-full rounded-8\" decoding=\"async\"\/><img loading=\"lazy\" src=\"https:\/\/www.t-online.de\/s\/paper\/_next\/static\/media\/zoom-in.f7dae02f.svg\" alt=\"Vergr\u00f6\u00dfern des Bildes\" title=\"Vergr\u00f6\u00dfern des Bildes\" class=\"block h-[calc(var(--height)_\/_16_*_1rem)] w-[calc(var(--width)_\/_16_*_1rem)] max-w-none absolute bottom-8 right-8 rounded-4 bg-snow p-8\" style=\"--width:32;--height:32\" decoding=\"async\"\/>Bj\u00f6rn H\u00f6cke beim Bundesparteitag der AfD 2025: Deutschlandfahnen sind bei AfD-Veranstaltungen fast immer pr\u00e4sent, am Ende von Parteitagen wird die Nationalhymne gesungen. (Quelle: IMAGO\/Revierfoto\/imago)<\/a><\/p>\n<p class=\"text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\"><strong class=\"font-bold\">Auch die Forderung nach dem Singen der Nationalhymne bei \u00f6ffentlichen Anl\u00e4ssen in den deutschen Schulen findet sich im Programm der AfD in Sachsen-Anhalt,<\/strong> ebenso wie das t\u00e4gliche Hissen der Deutschlandfahne vor den Schulgeb\u00e4uden. Aus der Partei aber gibt es noch weitergehende Vorst\u00f6\u00dfe mit Blick auf die Hymne: <a class=\"transition-colors duration-200 cursor-pointer text-inherit no-underline text-salemsfur md:hover:text-magenta md:hover:border-magenta md:focus:text-magenta border-current border-b border-solid break-words\" data-tracking=\"{&quot;action&quot;:&quot;click&quot;,&quot;category&quot;:&quot;intextLink&quot;,&quot;label&quot;:&quot;\/nachrichten\/deutschland\/innenpolitik\/id_100940998\/afd-politiker-singen-auf-us-reise-verpoente-strophe-des-deutschlandlieds.html&quot;}\" href=\"https:\/\/www.t-online.de\/nachrichten\/deutschland\/innenpolitik\/id_100940998\/afd-politiker-singen-auf-us-reise-verpoente-strophe-des-deutschlandlieds.html\" data-sctrack=\"BodyAnchor\" rel=\"nofollow noopener\" target=\"_blank\">So forderte der stellvertretende Bundesvorsitzende der AfD, Kay Gottschalk,<\/a> im Jahr 2025 bei t-online, die erste Strophe des &#8222;Liedes der Deutschen&#8220; (&#8222;Deutschland, Deutschland \u00fcber alles&#8220;; &#8222;Von der Maas bis an die Memel&#8220;) zu rehabilitieren und wieder vermehrt zu singen. Und er war damit mitnichten der Erste aus der Partei.<\/p>\n<p class=\"text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\"><strong class=\"font-bold\">Wer als Journalist Texte zu diesem Thema schreibt, erlebt in den sozialen Medien in erstaunlicher Geschwindigkeit eine heftige Gegenreaktion.<\/strong> Befeuert von Rechten und Internet-Trollen, getragen aber auch von Unwissenden. Es zeigt sich dann: Vielen ist es nicht nur egal, sondern sie wissen schlicht wenig \u00fcber die Geschichte unserer Hymne. Ein unbestellter Acker, den die AfD mit geschichtsklitterndem Pflug bearbeiten will.<\/p>\n<p class=\"text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\"><strong class=\"font-bold\">Hilfreich w\u00e4re, w\u00fcrde man in den Schulen die Geschichte unserer Hymne intensiver lernen.<\/strong> Wie August Heinrich Hoffmann von Fallersleben den Text schon 1841 schrieb \u2013 als Ausdruck eines tiefen Wunschs nach nationaler Einheit. Wie sein &#8222;Lied der Deutschen&#8220; mit allen Strophen 1922 von Friedrich Ebert zur Hymne erkl\u00e4rt wurde. Wie die Nazis alsbald allein die erste Strophe in Verbund mit dem Horst-Wessel-Lied, zuerst Kampflied der SA, dann Parteihymne der NSDAP, als Nationalhymne missbrauchten. Wie sie so ein Symbol schufen: Deutschland als Staat und die NS-Bewegung als untrennbare Einheit. Gesungen bei staatlichen Feiern, Milit\u00e4rparaden, NSDAP-Parteitagen, Appellen und Schulveranstaltungen. H\u00e4ufig besiegelt mit dem Hitlergru\u00df. Wie sie die Zeile der ersten Strophe &#8222;Deutschland, Deutschland \u00fcber alles, \u00fcber alles in der Welt&#8220; \u2013 vom Sch\u00f6pfer g\u00e4nzlich anders gedacht \u2013 in ein Symbol f\u00fcr kriegerischen Nationalismus und Gro\u00dfmannssucht verwandelten.<\/p>\n<p class=\"text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\"><strong class=\"font-bold\">Und schlie\u00dflich:<\/strong> Wie 1952 erst Kanzler Konrad Adenauer und Bundespr\u00e4sident Theodor Heuss festlegten, bei \u00f6ffentlichen Anl\u00e4ssen nur die dritte Strophe (&#8222;Einigkeit und Recht und Freiheit&#8220;) singen zu lassen. Und 1991 Kanzler Helmut Kohl und Bundespr\u00e4sident Richard von Weizs\u00e4cker nur ebendiese dritte Strophe zur Nationalhymne erkl\u00e4rten. Drei CDU-, ein FDP-Politiker, allesamt dem allzu antifaschistischen Aktivismus recht unverd\u00e4chtig.<\/p>\n<p class=\"text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\"><strong class=\"font-bold\">Wissen ist Macht.<\/strong> In diesem Fall: die Macht, die Vergangenheit zu verstehen, einzuordnen, Populisten und Extremisten zu widerstehen und eine eigene Geschichte zu schreiben. Ein Hymnen-Erlass \u2013 kombiniert mit dem richtigen Lehrplan \u2013 k\u00f6nnte dabei helfen.<\/p>\n<p>Loading&#8230;<img decoding=\"async\" src=\"https:\/\/www.t-online.de\/s\/paper\/_next\/static\/media\/image.e47c3ca7.svg\" alt=\"Symbolbild f\u00fcr eingebettete Inhalte\"\/><\/p>\n<p class=\"text-10 uppercase leading-12 text-manatee\">Embed<\/p>\n","protected":false},"excerpt":{"rendered":"Jetzt neu bei t-online: Schriftgr\u00f6\u00dfe anpassen! Artikel teilen Guten Morgen, liebe Leserin, lieber Leser, Markus S\u00f6der hat es&hellip;\n","protected":false},"author":2,"featured_media":1000137,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[3028,186,331,3924,332,3922,5159,31,3364,29,26980,152992,30,6203,13,771,14,3923,40997,15,3921,860,9117,12,966,184,64],"class_list":{"0":"post-1000136","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deutschland","8":"tag-3028","9":"tag-afd","10":"tag-aktuelle-nachrichten","11":"tag-aktuelle-nachrichten-aus-deutschland","12":"tag-aktuelle-news","13":"tag-aktuelle-news-aus-deutschland","14":"tag-bjoern-hoecke","15":"tag-cdu","16":"tag-de","17":"tag-deutschland","18":"tag-deutschlandfahne","19":"tag-fussballstadion","20":"tag-germany","21":"tag-gew","22":"tag-headlines","23":"tag-markus-soeder","24":"tag-nachrichten","25":"tag-nachrichten-aus-deutschland","26":"tag-nationalhymne","27":"tag-news","28":"tag-news-aus-deutschland","29":"tag-sachsen-anhalt","30":"tag-sarah-connor","31":"tag-schlagzeilen","32":"tag-schule","33":"tag-spd","34":"tag-usa"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116531033404741709","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1000136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1000136"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1000136\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1000137"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1000136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1000136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1000136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}