{"id":1003542,"date":"2026-05-08T11:31:30","date_gmt":"2026-05-08T11:31:30","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1003542\/"},"modified":"2026-05-08T11:31:30","modified_gmt":"2026-05-08T11:31:30","slug":"counterpoint-zahlen-apple-waechst-bei-smartphones-am-schnellsten-iphone-17-vorn","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1003542\/","title":{"rendered":"Counterpoint-Zahlen: Apple w\u00e4chst bei Smartphones am schnellsten, iPhone 17 vorn"},"content":{"rendered":"<p>    close notice<\/p>\n<p class=\"notice-banner__text a-u-mb-0\">\n      This article is also available in<br \/>\n        <a href=\"https:\/\/www.heise.de\/en\/news\/Counterpoint-figures-Apple-fastest-growing-smartphone-maker-iPhone-17-leads-11287131.html\" class=\"notice-banner__link a-u-inline-link\" rel=\"nofollow noopener\" target=\"_blank\">English<\/a>.<\/p>\n<p>      It was translated with technical assistance and editorially reviewed before publication.\n    <\/p>\n<p class=\"notice-banner__link a-u-mb-0\">\n    Don\u2019t show this again.\n<\/p>\n<p>Das Research-Unternehmen Counterpoint hat seine Smartphone-Zahlen f\u00fcr das erste Quartal 2026 vorgelegt. Sie zeigen, dass es Apple gelungen ist, seine Marktposition weiter zu st\u00e4rken \u2013 bei einem insgesamt beim Absatz schw\u00e4chelnden Markt. Der US-Hersteller ist demnach in zwei Kategorien vorne: sowohl beim Wachstum als auch bei den Einzelverk\u00e4ufen.<\/p>\n<p>        Weiterlesen nach der Anzeige<\/p>\n<p>Apple h\u00e4lt Preise relativ stabil, w\u00e4chst trotzdem<\/p>\n<p>Laut den Counterpoint-Analysten, die sich auf Markterhebungen st\u00fctzen, gingen die St\u00fcckzahlen, die von Januar bis M\u00e4rz weltweit verkauft wurden, zur\u00fcck. Dass es <a href=\"https:\/\/counterpointresearch.com\/en\/insights\/Global-Smartphone-Revenues-Up-8-percent-YoY-in-Q1-2026\" rel=\"external noopener nofollow\" target=\"_blank\">dennoch zu einem Umsatzplus von acht Prozent im Jahresvergleich<\/a> kam, lag <a href=\"https:\/\/www.heise.de\/news\/RAM-Inflation-Schraubt-Apple-deshalb-am-iPhone-Line-up-11162243.html\" rel=\"nofollow noopener\" target=\"_blank\">an der aktuellen Komponenteninflation<\/a> insbesondere bei DRAM und NAND.<\/p>\n<p>So stieg der durchschnittliche Verkaufspreis auf einen Rekordwert von 399 US-Dollar, ein Plus von 12 Prozent. Apple wuchs mit Abstand am st\u00e4rksten, mit dem laut Counterpoint bislang h\u00f6chsten Umsatz. Das Plus lag im Jahresvergleich bei 22 Prozent, obwohl der iPhone-Konzern seine <a href=\"https:\/\/www.heise.de\/news\/Apple-will-angeblich-mit-Preisstabilitaet-beim-iPhone-den-Markt-aufmischen-11207791.html\" rel=\"nofollow noopener\" target=\"_blank\">Preise relativ stabil<\/a> gehalten hatte. Bei der Umsatzverteilung kam Apple nun auf 48 Prozent, gefolgt von Samsung mit 18 Prozent. Oppo, Xiaomi und Vivo landeten bei 6, 5 und 4 Prozent. Apples durchschnittlicher Verkaufspreis pro iPhone liegt nun bei 908 Dollar. Im Vorjahresvergleichsquartal lag dieser noch bei 816 Dollar.<\/p>\n<p>iPhone 17 ist beliebtestes Smartphone der Welt<\/p>\n<p>In einer weiteren <a href=\"https:\/\/counterpointresearch.com\/en\/insights\/iphone-17-global-best-selling-smartphone-in-q1-2026-top-10-take-25-percent-share\" rel=\"external noopener nofollow\" target=\"_blank\">Counterpoint-Untersuchung<\/a>, die nach Modellen aufschl\u00fcsselt, zeigt sich, dass das iPhone 17 weltweit das beliebteste Smartphone ist. Die gesamte Top Ten der beliebtesten Modelle kommt auf 25 Prozent Gesamtanteil, das iPhone 17 allein auf sechs Prozent. Danach folgen iPhone 17 Pro Max und iPhone 17 Pro sowie auf Platz 6 noch das iPhone 16. Rang 4 und 5 belegten Samsung Galaxy A07 in der 4G-Version sowie A17 in der 5G-Variante. In der Top Ten sind ansonsten noch drei weitere Galaxys vertreten (A56, A36, A17 4G, Rang 7 bis 9) und mit dem Redmi A5 ein einziges Xiaomi-Ger\u00e4t.<\/p>\n<p>Laut Counterpoint war das iPhone 17 aufgrund seiner technischen Verbesserungen beliebt, darunter der h\u00f6heren Speicherausstattung in der Einsteigervariante, der h\u00f6heren Kameraaufl\u00f6sung und aufgrund des verbesserten Displays. Zu bedenken bleibt, dass beliebte China-Handys von Anbietern wie Huawei in westlichen L\u00e4ndern nicht oder nur eingeschr\u00e4nkt offeriert werden.<\/p>\n<p>        Weiterlesen nach der Anzeige<\/p>\n<p>(<a class=\"redakteurskuerzel__link\" href=\"https:\/\/www.heise.de\/news\/mailto:bsc@heise.de\" title=\"Ben Schwan\" rel=\"nofollow noopener\" target=\"_blank\">bsc<\/a>)<\/p>\n<p>\n      Dieser Link ist leider nicht mehr g\u00fcltig.\n    <\/p>\n<p>Links zu verschenkten Artikeln werden ung\u00fcltig,<br \/>\n      wenn diese \u00e4lter als 7\u00a0Tage sind oder zu oft aufgerufen wurden.\n    <\/p>\n<p><strong>Sie ben\u00f6tigen ein heise+ Paket, um diesen Artikel zu lesen. Jetzt eine Woche unverbindlich testen \u2013 ohne Verpflichtung!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"close notice This article is also available in English. It was translated with technical assistance and editorially reviewed&hellip;\n","protected":false},"author":2,"featured_media":1003543,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[135],"tags":[231,29,30,1274,5553,1273,190,189,769,194,191,843,20161,55,193,192],"class_list":{"0":"post-1003542","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-wissenschaft-technik","8":"tag-apple","9":"tag-deutschland","10":"tag-germany","11":"tag-ios","12":"tag-iphone","13":"tag-mobiles","14":"tag-science","15":"tag-science-technology","16":"tag-smartphone","17":"tag-technik","18":"tag-technology","19":"tag-verkauf","20":"tag-wachstum","21":"tag-wirtschaft","22":"tag-wissenschaft","23":"tag-wissenschaft-technik"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116538736096286612","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1003542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1003542"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1003542\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1003543"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1003542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1003542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1003542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}