{"id":1003883,"date":"2026-05-08T14:52:16","date_gmt":"2026-05-08T14:52:16","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1003883\/"},"modified":"2026-05-08T14:52:16","modified_gmt":"2026-05-08T14:52:16","slug":"kartoffeln-unveraenderte-notierungen-minimale-nachfrage-nach-innovator-in-frankreich","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1003883\/","title":{"rendered":"Kartoffeln: Unver\u00e4nderte Notierungen \/ Minimale Nachfrage nach Innovator in Frankreich"},"content":{"rendered":"<p>Die Kassamarktnotierungen unterschiedlicher Verb\u00e4nde und Organisationen sind entscheidend f\u00fcr die Preisbildung sowohl am Terminmarkt als auch bei physischen Kartoffeln. F\u00fcr die ma\u00dfgeblichen Anbaul\u00e4nder der EU mit Deutschland, Niederlande, Belgien und Frankreich gibt es jeweilige Notierungen, die w\u00e4hrend der Saison w\u00f6chentlich aktualisiert werden. Anhand der Grafik sind die preislichen Differenzen zwischen den verschiedenen Preisen sowie m\u00f6gliche Tendenzen zu erkennen. Umfangreiche historische Werte stehen, geordnet nach Saison, zur Verf\u00fcgung.<\/p>\n<p class=\"text-right\">Quelle: belgapom.be, potatonl.com, rnm.franceagrimer.fr, reka-rheinland.de<\/p>\n","protected":false},"excerpt":{"rendered":"Die Kassamarktnotierungen unterschiedlicher Verb\u00e4nde und Organisationen sind entscheidend f\u00fcr die Preisbildung sowohl am Terminmarkt als auch bei physischen&hellip;\n","protected":false},"author":2,"featured_media":1003884,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3974],"tags":[331,332,548,663,3934,3980,156,13,14,15,12],"class_list":{"0":"post-1003883","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-frankreich","8":"tag-aktuelle-nachrichten","9":"tag-aktuelle-news","10":"tag-eu","11":"tag-europa","12":"tag-europe","13":"tag-france","14":"tag-frankreich","15":"tag-headlines","16":"tag-nachrichten","17":"tag-news","18":"tag-schlagzeilen"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116539526246432804","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1003883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1003883"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1003883\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1003884"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1003883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1003883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1003883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}