{"id":1005679,"date":"2026-05-09T08:09:24","date_gmt":"2026-05-09T08:09:24","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1005679\/"},"modified":"2026-05-09T08:09:24","modified_gmt":"2026-05-09T08:09:24","slug":"berlin-erinnert-an-das-kriegsende-doch-der-ukraine-krieg-spaltet-das-gedenken","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1005679\/","title":{"rendered":"Berlin erinnert an das Kriegsende \u2013 doch der Ukraine-Krieg spaltet das Gedenken"},"content":{"rendered":"<p class=\"text-black text-[17px] leading-7 font-normal font-merriweather\">\n              Liudmyla Selke steht an diesem Freitagvormittag links <a href=\"https:\/\/www.berliner-zeitung.de\/article\/tag-des-sieges-in-berlin-zwischen-tumult-und-wuerdevpgedenken-2323511\" rel=\"nofollow noopener\" target=\"_blank\">vor dem sowjetischen Ehrenmal in Tiergarten<\/a>. Sie h\u00e4lt eine ukrainische Flagge in der Hand. Das Zeigen dieser Fahnen ist, anders als bei russischen Flaggen, an diesem 8. Mai nicht verboten.\n            <\/p>\n<p class=\"text-black text-[17px] leading-7 font-normal font-merriweather\">\n              Die 54-j\u00e4hrige Ukrainerin, die seit 20 Jahren in Berlin lebt, ist gekommen, um den <a href=\"https:\/\/www.berliner-zeitung.de\/category\/tag-der-befreiung\" rel=\"nofollow noopener\" target=\"_blank\">Tag der Befreiung<\/a> zu begehen und gegen den Krieg Putins gegen ihr Heimatland zu protestieren. Am 8. Mai 1945 trat die bedingungslose Kapitulation der Wehrmacht in Kraft und beendete das Hitlerregime <a href=\"https:\/\/www.berliner-zeitung.de\/category\/zweiter-weltkrieg\" rel=\"nofollow noopener\" target=\"_blank\">und den Zweiten Weltkrieg,<\/a> der Millionen Tote gefordert hatte.\n            <\/p>\n<p class=\"text-black text-[17px] leading-7 font-normal font-merriweather\">\n              Ihre beiden Gro\u00dfv\u00e4ter h\u00e4tten im Zweiten Weltkrieg in der Roten Armee gek\u00e4mpft, erz\u00e4hlt sie. Ihr Opa v\u00e4terlicherseits sei 1945 sogar bei der Befreiung Berlins dabei gewesen. \u201eEs war ein Sieg \u00fcber den deutschen Faschismus\u201c, sagt Liudmyla Selke. Und f\u00fcgt hinzu: \u201eNun befindet sich <a href=\"https:\/\/www.berliner-zeitung.de\/article\/trotz-ukrainischer-erfolge-putin-wird-von-seinen-zielen-nicht-lassen-10034976\" rel=\"nofollow noopener\" target=\"_blank\">die Ukraine im Krieg<\/a> gegen den russischen Faschismus.\u201c Ihre Eltern, 77 und 78 Jahre alt, lebten noch immer in der Ukraine. Sie k\u00f6nnten nachts wegen der russischen Angriffe nicht ruhig schlafen.\n            <\/p>\n<p class=\"text-black text-[17px] leading-7 font-normal font-merriweather\">\n              An diesem Tag wirkt das Ehrenmal ein wenig wie ein Krieg im Kleinen, hier wird nicht mit Waffen gek\u00e4mpft, sondern mit Worten oder mit Schildern und Flaggen. Rechts neben dem Ehrenmal sind keine Fahnen zu sehen. Dort stehen Menschen mit roten Nelken oder Rosen in den H\u00e4nden. Es seien alles Putinversteher, sagt ein Mann, der nahe einer Ukrainefahne steht.\n            <\/p>\n<p class=\"text-black text-[17px] leading-7 font-normal font-merriweather\">\n              Doch nicht jeder, der sich auf der anderen Seite befindet, ist auch auf <a href=\"https:\/\/www.berliner-zeitung.de\/category\/wladimir-putin\" rel=\"nofollow noopener\" target=\"_blank\">Putins<\/a> Seite. \u201eMan muss differenzieren. Damals haben die Sowjetsoldaten unter gr\u00f6\u00dften Verlusten Deutschland befreit. Dass wir daran erinnern, ist wichtig und richtig. Andererseits ist heute Putin an der Macht und f\u00fchrt Krieg gegen die Ukraine\u201c, sagt Johannes Weiz. Er ist 58 Jahre alt und hat eine Rose dabei.\n            <\/p>\n<p>                    <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/05\/3af4f8f7-34b0-4173-81b4-821227c62daf.jpg\"   alt=\"Liudmilla Selke mit ihrem Ehemann Bernd Selke (2.v.r.) am sowjetischen Ehrenmal im Tiergarten.\" class=\"w-full h-full object-cover cursor-pointer\" loading=\"lazy\" data-original-url=\"\" data-caption=\"Liudmilla Selke mit ihrem Ehemann Bernd Selke (2.v.r.) am sowjetischen Ehrenmal im Tiergarten.\" data-source=\"Katrin Bischoff\/Berliner Zeitung\"\/><\/p>\n<p class=\"font-roboto text-sm leading-[22px] font-normal not-italic text-gray-800 text-left flex-[3]\">Liudmilla Selke mit ihrem Ehemann Bernd Selke (2.v.r.) am sowjetischen Ehrenmal im Tiergarten.<\/p>\n<p class=\"text-left md:text-right font-roboto text-xs leading-[18px] font-normal not-italic text-gray-700 flex-1 mt-1 md:mt-0\">\u00a9 Katrin Bischoff\/Berliner Zeitung<\/p>\n<p class=\"text-black text-[17px] leading-7 font-normal font-merriweather\">\n              Z\u00f6gerlich geht Maria Fr\u00f6bel die Stufen hinauf, dorthin, wo schon ein paar Kr\u00e4nze und Blumen liegen. Sie hat drei Nelken in der Hand, die sie auf den Rand des Denkmals legt.\n            <\/p>\n<p class=\"text-black text-[17px] leading-7 font-normal font-merriweather\">\n              Die 77-J\u00e4hrige lebt <a href=\"https:\/\/www.berliner-zeitung.de\/category\/grossbritannien\" rel=\"nofollow noopener\" target=\"_blank\">in England<\/a>, ist jedes Jahr zum Tag der Befreiung in Berlin. \u201eUm die gefallenen Sowjetsoldaten zu ehren\u201c, erkl\u00e4rt sie. Dann sagt sie, sie st\u00f6re, dass Ukrainer mit ihren Fahnen das Gedenken monopolisieren wollen. \u201eDamals haben Soldaten aus allen Sowjetrepubliken gegen Nazideutschland gek\u00e4mpft, aber hier sind nur ukrainische Flaggen zu sehen\u201c, erkl\u00e4rt sie ihr Unbehagen.\n            <\/p>\n<p class=\"text-black text-[17px] leading-7 font-normal font-merriweather\">\n              Fr\u00f6bel ist \u00fcberzeugt: Der Krieg in der Ukraine sei ein Krieg, den Russland nicht gewollt habe. \u201eIch bin in Ostdeutschland sozialisiert und habe keine Ber\u00fchrungs\u00e4ngste mit Russland.\u201c Evelyn Z. steht ein paar Meter weiter, sie ist derselben Meinung. Man habe Russland dazu getrieben, den Krieg zu beginnen, sagt die 48-J\u00e4hrige aus Mitte. Die Nato sei an der jetzigen Situation nicht ganz unschuldig.\n            <\/p>\n<p>            Streit um eine Nato-Flagge vor dem Ehrenmal<\/p>\n<p class=\"text-black text-[17px] leading-7 font-normal font-merriweather\">\n              Werner D. legt eine rote Rose nieder. Er ist ganz anderer Meinung, trotz seiner Ostherkunft. Vor 61 Jahren wurde er in Lichtenberg geboren. \u201eRussland ist der Aggressor, Russland muss den Krieg beenden\u201c, sagt er. Doch die heutigen Angriffe auf die Ukraine linderten nicht die Verdienste sowjetischer Soldaten zur Befreiung Deutschlands vor 81 Jahren.\n            <\/p>\n<p>                    <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/05\/7c21734f-fae2-4dd2-9f31-331200e936a9.jpg\"   alt=\"Maria Fr\u00f6bel legt Nelken am sowjetischen Ehrenmal im Tiergarten ab. Sie sieht die ukrainischen Flaggen kritisch.\" class=\"w-full h-full object-cover cursor-pointer\" loading=\"lazy\" data-original-url=\"\" data-caption=\"Maria Fr\u00f6bel legt Nelken am sowjetischen Ehrenmal im Tiergarten ab. Sie sieht die ukrainischen Flaggen kritisch.\" data-source=\"Katrin Bischoff\/Berliner Zeitung\"\/><\/p>\n<p class=\"font-roboto text-sm leading-[22px] font-normal not-italic text-gray-800 text-left flex-[3]\">Maria Fr\u00f6bel legt Nelken am sowjetischen Ehrenmal im Tiergarten ab. Sie sieht die ukrainischen Flaggen kritisch.<\/p>\n<p class=\"text-left md:text-right font-roboto text-xs leading-[18px] font-normal not-italic text-gray-700 flex-1 mt-1 md:mt-0\">\u00a9 Katrin Bischoff\/Berliner Zeitung<\/p>\n<p class=\"text-black text-[17px] leading-7 font-normal font-merriweather\">\n              Dann wird es laut vor dem Denkmal. Ein Mann mit Ukraine-Fahne entrollt auf der Treppe eine Nato-Flagge. Eine Polizistin bittet ihn, zur Seite zu treten, weil auch andere Menschen Blumen niederlegen wollten. Was die Polizei st\u00f6re, die ukrainische oder die Nato-Fahne, will der Angesprochene wissen. Die Beamtin bleibt ruhig, wiederholt ihre Bitte. Der Disput wird von zahlreichen Kameras und Handys aufgenommen. Eine junge Frau zeigt auf die Nato-Flagge und ruft laut: \u201eDie Fahne muss weg.\u201c Die Polizei kann die tumultartige Situation schlie\u00dflich beruhigen.\n            <\/p>\n<p class=\"text-black text-[17px] leading-7 font-normal font-merriweather\">\n              Kurz nach elf Uhr erscheinen die Mitglieder des Berliner <a href=\"https:\/\/www.berliner-zeitung.de\/category\/buendnis-sahra-wagenknecht\" rel=\"nofollow noopener\" target=\"_blank\">BSW-Landesvorstands<\/a> und legen zusammen mit der Parteivorsitzenden Amira Mohamed Ali eine Kranz am Ehrenmal nieder. \u201eNie wieder Krieg, nie wieder Faschismus\u201c, ist auf der Schleife zu lesen.\n            <\/p>\n<p class=\"text-black text-[17px] leading-7 font-normal font-merriweather\">\n              Wenig sp\u00e4ter sagt <a href=\"https:\/\/www.berliner-zeitung.de\/category\/amira-mohamed-ali\" rel=\"nofollow noopener\" target=\"_blank\">Amira Mohamed Ali<\/a>, es sei wichtig, sich an damals zu erinnern, an die Leistungen der Sowjetsoldaten. Weil Krieg immer unendliches Elend \u00fcber alle Menschen, die daran beteiligt sind, bringe. \u201eAuch wenn man jetzt zu Recht das Verhalten der russischen Regierung kritisieren kann, darf das nichts \u00e4ndern an dem Gedenken daran, was damals geschehen ist.\u201c\n            <\/p>\n<p class=\"text-black text-[17px] leading-7 font-normal font-merriweather\">\n              Dann erkl\u00e4rt die Parteivorsitzende, dass der Krieg in der Ukraine unbedingt gestoppt werden m\u00fcsse. Das k\u00f6nne und m\u00fcsse auf diplomatischen Wege geschehen. Es sei die einzige M\u00f6glichkeit, dieses Sterben schnell zu beenden.\n            <\/p>\n<p>                    <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/05\/b6c16565-5a30-4a35-a8f3-a49b78d2c932.jpg\"   alt=\"Auch am Zugang zum sowjetischen Ehrenmal im Treptower Park liegen Blumen.\" class=\"w-full h-full object-cover cursor-pointer\" loading=\"lazy\" data-original-url=\"\" data-caption=\"Auch am Zugang zum sowjetischen Ehrenmal im Treptower Park liegen Blumen.\" data-source=\"Katrin Bischoff\/Berliner Zeitung\"\/><\/p>\n<p class=\"font-roboto text-sm leading-[22px] font-normal not-italic text-gray-800 text-left flex-[3]\">Auch am Zugang zum sowjetischen Ehrenmal im Treptower Park liegen Blumen.<\/p>\n<p class=\"text-left md:text-right font-roboto text-xs leading-[18px] font-normal not-italic text-gray-700 flex-1 mt-1 md:mt-0\">\u00a9 Katrin Bischoff\/Berliner Zeitung<\/p>\n<p class=\"text-black text-[17px] leading-7 font-normal font-merriweather\">\n              Ein ganz anderes, zum Gedenken passenderes Bild bietet sich an diesem Tag der Befreiung am sowjetischen Ehrenmal in Treptow, dem gr\u00f6\u00dften Denkmal f\u00fcr die gefallenen Soldaten der Roten Armee in Deutschland. Dort sind wesentlich mehr Menschen unterwegs, die sich aber auf dem riesigen Areal verteilen. Es strahlt eine gro\u00dfe Ruhe aus.\n            <\/p>\n<p>            \u201eIch bin tief betr\u00fcbt, dass wieder Krieg herrscht\u201c<\/p>\n<p class=\"text-black text-[17px] leading-7 font-normal font-merriweather\">\n              Auf den Stufen zu der riesigen Statue eines sowjetischen Soldaten, der ein Kind auf seinem linken Arm h\u00e4lt und in der anderen Hand ein Schwert tr\u00e4gt, liegen Rosen, Nelken, Tulpen, Maigl\u00f6ckchen und kleine Kr\u00e4nze. Maria K. ist 32 Jahre alt und mit ihrem kleinen Sohn die Stufen nach oben gelaufen. Der Junge h\u00e4lt eine Rose in der Hand.\n            <\/p>\n<p class=\"text-black text-[17px] leading-7 font-normal font-merriweather\">\n              \u201eIch habe noch nie einen Krieg erlebt und will auch, dass mein Sohn niemals in den Krieg ziehen muss\u201c, sagt die Physiotherapeutin. \u201eAber wir Menschen vergessen leider zu schnell, was Kriege immer wieder angerichtet haben. Deswegen sind wir Beide heute hier.\u201c\n            <\/p>\n<p>                    <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/05\/f5cb910c-b0ea-47ca-918c-672772a61058.jpg\"   alt=\"Monika Niendorf und ihr Lebensgef\u00e4hrte Wolfgang Rademacher kommen jedes Jahr zum sowjetischen Ehrenmal in den Treptower Park.\" class=\"w-full h-full object-cover cursor-pointer\" loading=\"lazy\" data-original-url=\"\" data-caption=\"Monika Niendorf und ihr Lebensgef\u00e4hrte Wolfgang Rademacher kommen jedes Jahr zum sowjetischen Ehrenmal in den Treptower Park.\" data-source=\"Katrin Bischoff\/Berliner Zeitung\"\/><\/p>\n<p class=\"font-roboto text-sm leading-[22px] font-normal not-italic text-gray-800 text-left flex-[3]\">Monika Niendorf und ihr Lebensgef\u00e4hrte Wolfgang Rademacher kommen jedes Jahr zum sowjetischen Ehrenmal in den Treptower Park.<\/p>\n<p class=\"text-left md:text-right font-roboto text-xs leading-[18px] font-normal not-italic text-gray-700 flex-1 mt-1 md:mt-0\">\u00a9 Katrin Bischoff\/Berliner Zeitung<\/p>\n<p class=\"text-black text-[17px] leading-7 font-normal font-merriweather\">\n              Auch vor der Skulptur \u201eMutter Heimat\u201c liegen Kr\u00e4nze und Blumen. Der Ernst-Busch-Chor bereitet sich auf seinen Auftritt vor. Klappst\u00fchle werden herbeigetragen. Monika Niendorf und ihr Lebensgef\u00e4hrte Wolfgang Rademacher haben fr\u00fcher beim Rundfunk gearbeitet. Jedes Jahr kommen sie zum Tag der Befreiung <a href=\"https:\/\/www.berliner-zeitung.de\/category\/treptower-park\" rel=\"nofollow noopener\" target=\"_blank\">in den Treptower Park<\/a> \u2013 mit Nelken.\n            <\/p>\n<p class=\"text-black text-[17px] leading-7 font-normal font-merriweather\">\n              \u201eIch bin tief betr\u00fcbt, dass wieder Krieg herrscht, dass ein einziger Mann einen Krieg beschlie\u00dfen kann\u201c, sagt die 87-j\u00e4hrige Monika Niendorf. \u201eWir haben beide in Berlin erlebt, was Krieg bedeutet\u201c, erg\u00e4nzt der 91-J\u00e4hrige Wolfgang Rademacher. So etwas sollte nie wieder geschehen, nirgends auf der Welt.\n            <\/p>\n<p class=\"text-black text-[17px] leading-7 font-normal font-merriweather\">\n              Bis zum Nachmittag verlaufen die Feierlichkeiten friedlich und ohne St\u00f6raktionen, so die <a href=\"https:\/\/www.berliner-zeitung.de\/category\/polizei\" rel=\"nofollow noopener\" target=\"_blank\">Berliner Polizei,<\/a> die mit 380 Einsatzkr\u00e4ften die Veranstaltungen absicherten.<\/p>\n<p>                    <img decoding=\"async\" src=\"https:\/\/www.berliner-zeitung.de\/images\/blz\/send-mail.svg\" alt=\"Send feedback\"\/><\/p>\n<p>Lesen Sie mehr zum Thema<\/p>\n","protected":false},"excerpt":{"rendered":"Liudmyla Selke steht an diesem Freitagvormittag links vor dem sowjetischen Ehrenmal in Tiergarten. Sie h\u00e4lt eine ukrainische Flagge&hellip;\n","protected":false},"author":2,"featured_media":1005680,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1825],"tags":[296,29,30],"class_list":{"0":"post-1005679","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-berlin","8":"tag-berlin","9":"tag-deutschland","10":"tag-germany"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116543604202437770","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1005679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1005679"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1005679\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1005680"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1005679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1005679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1005679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}