{"id":1009186,"date":"2026-05-10T19:11:15","date_gmt":"2026-05-10T19:11:15","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1009186\/"},"modified":"2026-05-10T19:11:15","modified_gmt":"2026-05-10T19:11:15","slug":"naechtliches-autorennen-in-wuppertal","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1009186\/","title":{"rendered":"N\u00e4chtliches Autorennen in Wuppertal"},"content":{"rendered":"<p class=\"text_ohne_einzug richtext text-em-55 !leading-serif mx-6 desktop:mx-0\">Mutma\u00dflich bei einem illegalen Autorennen wurden in der Nacht zu Sonntag gleich mehrere Personen leicht verletzt. Kurz nach 0 Uhr waren ein 19-J\u00e4hriger und ein 21-J\u00e4hriger auf der Ronsdorfer Stra\u00dfe unterwegs. Beide hatten zwei sowie drei Beifahrer dabei. Kurz hinter der Kreuzung Barmenia Allee konnte das auf der rechten Spur fahrende Fahrzeug in der scharfen Linkskurve wahrscheinlich aufgrund zu hoher Geschwindigkeit die Spur nicht halten. Dabei kollidierte es mit dem auf der linken Spur fahrenden Fahrzeug, beide verloren die Kontrolle und gerieten \u00fcber den Gr\u00fcnstreifen in den Gegenverkehr \u00fcber die Gegenfahrbahn hinaus. Unter Vorbehalt der weiteren Ermittlungen geht die Polizei von einem illegalen Autorennen aus. Zur Spurensicherung wurde dazu ein spezielles Unfallaufnahmeteam der Polizei Bochum hinzugezogen. F\u00fcr die Unfallaufnahme musste die Stra\u00dfe in beide Richtungen gesperrt werden. Mehrere Personen wurden leicht verletzt, keine wollte \u00e4rztliche Hilfe.  nip<\/p>\n","protected":false},"excerpt":{"rendered":"Mutma\u00dflich bei einem illegalen Autorennen wurden in der Nacht zu Sonntag gleich mehrere Personen leicht verletzt. Kurz nach&hellip;\n","protected":false},"author":2,"featured_media":1009187,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1840],"tags":[4188,3364,29,514,30,65425,18273,9991,1209,23148,35954,13468,5185,4418],"class_list":{"0":"post-1009186","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-wuppertal","8":"tag-autorennen","9":"tag-de","10":"tag-deutschland","11":"tag-fahrzeug","12":"tag-germany","13":"tag-illegalen","14":"tag-jaehriger","15":"tag-kurz","16":"tag-nordrhein-westfalen","17":"tag-personen","18":"tag-spur","19":"tag-spurensicherung","20":"tag-verletzt","21":"tag-wuppertal"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1009186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1009186"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1009186\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1009187"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1009186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1009186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1009186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}