{"id":1010093,"date":"2026-05-11T04:54:17","date_gmt":"2026-05-11T04:54:17","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1010093\/"},"modified":"2026-05-11T04:54:17","modified_gmt":"2026-05-11T04:54:17","slug":"berlin-brandenburg-nollendorfplatz-wird-wieder-von-vier-u-bahnen-angefahren","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1010093\/","title":{"rendered":"Berlin &#038; Brandenburg: Nollendorfplatz wird wieder von vier U-Bahnen angefahren"},"content":{"rendered":"<p>Berlin &amp; BrandenburgNollendorfplatz wird wieder von vier U-Bahnen angefahren<img decoding=\"async\" class=\"Image_img__fQCi0 Image_Img_16_9__4BLfH\" loading=\"eager\" fetchpriority=\"high\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/05\/1778475257_985_Die-Bauarbeiten-am-Nollendorfplatz-enden-puenktlich.webp\" alt=\"Die-Bauarbeiten-am-Nollendorfplatz-enden-puenktlich\"\/>TeilenFolgen auf:<a href=\"https:\/\/www.whatsapp.com\/channel\/0029Va5cdVJD8SDp5YZgYF01\" title=\"Auf WhatsApp folgen\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/www.n-tv.de\/socialIcons\/whatsapp.svg\" alt=\"whatsapp\" class=\"ArticleShare_icon__FsrC2\"\/><\/a><a href=\"https:\/\/news.google.com\/publications\/CAAiEPMdif5mpRNxiLOeUpHCwwsqFAgKIhDzHYn-ZqUTcYiznlKRwsML?hl=de&amp;gl=DE&amp;ceid=DE%3Ade\" title=\"Auf Google News folgen\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/www.n-tv.de\/socialIcons\/google.svg\" alt=\"whatsapp\" class=\"ArticleShare_icon__FsrC2\"\/><\/a><\/p>\n<p class=\"Typography_text-m__XI0da Typography_weight-bold__uT6mq storyline_lead_text_leadtext__q_wg8\">Die Bauarbeiten am einzigen Berliner Bahnhof mit vier U-Bahn-Linien sind beendet, der Verkehr rollt wieder planm\u00e4\u00dfig. Die BVG blieb mit der Deckensanierung damit genau in der Zeit.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Berlin (dpa\/bb) &#8211; Gute Nachrichten f\u00fcr Pendler auf den U-Bahn-Linien U1, U3 und U4: Die Bauarbeiten am Bahnhof Nollendorfplatz sind beendet. Seit den fr\u00fchen Morgenstunden fahren die Linien U1 und U3 wieder ohne Unterbrechung durch, der Betrieb der U4 wurde wieder aufgenommen, wie aus den Fahrgastinformationen der Berliner Verkehrsbetriebe hervorgeht.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Seit Anfang Januar konnte nur die U2 den Bahnhof Nollendorfplatz anfahren. Grund war die Sanierung der Decke zwischen den beiden unteren Ebenen. Die kurze U4 wurde f\u00fcr die Zeit der Bauarbeiten komplett eingestellt. Weil bei der Sanierung die Decke von oben ge\u00f6ffnet wurde, mussten auch Gleise entfernt werden. An der Zwischendecke waren in der Vergangenheit Sch\u00e4den durch Durchfeuchtung entstanden.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Die Bauarbeiten waren f\u00fcr vier Monate angesetzt, also bis gestern. Diesen Zeitplan konnte die BVG mit dem Neustart heute einhalten.<\/p>\n<p>Einziger Bahnhof mit vier U-Bahn-Linien<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Fahrg\u00e4ste der U1 und der U3 mussten in den vergangenen Monaten unter anderem auf die U2 umsteigen, um den Nollendorfplatz zu erreichen oder zu passieren. Zudem setzte die BVG Ersatzbusse ein.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Der Nollendorfplatz ist der einzige U-Bahnhof in Berlin, an dem vier Linien zusammentreffen. Wie viele Menschen genau von den Bauma\u00dfnahmen betroffen waren, l\u00e4sst sich nicht ganz genau sagen. Laut BVG nutzen t\u00e4glich rund 560.000 Fahrg\u00e4ste die vier Linien U1 bis U4.<\/p>\n<p class=\"Typography_text-s__wu_cm Typography_weight-normal__pqUbH Typography_color-darkgrey__sZEnP article-detail-footer_source__KslPc\">Quelle: dpa<\/p>\n","protected":false},"excerpt":{"rendered":"Berlin &amp; BrandenburgNollendorfplatz wird wieder von vier U-Bahnen angefahrenTeilenFolgen auf: Die Bauarbeiten am einzigen Berliner Bahnhof mit vier&hellip;\n","protected":false},"author":2,"featured_media":1007544,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1825],"tags":[296,29,30],"class_list":{"0":"post-1010093","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-berlin","8":"tag-berlin","9":"tag-deutschland","10":"tag-germany"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116554161935568449","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1010093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1010093"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1010093\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1007544"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1010093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1010093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1010093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}