{"id":1010238,"date":"2026-05-11T06:22:15","date_gmt":"2026-05-11T06:22:15","guid":{"rendered":"https:\/\/www.europesays.com\/de\/1010238\/"},"modified":"2026-05-11T06:22:15","modified_gmt":"2026-05-11T06:22:15","slug":"marode-gebaeude-czyborra-instandhaltung-an-tu-gebaeuden-wurde-vernachlaessigt","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/1010238\/","title":{"rendered":"Marode Geb\u00e4ude: Czyborra: Instandhaltung an TU-Geb\u00e4uden wurde vernachl\u00e4ssigt"},"content":{"rendered":"<p class=\"tspAAdt tspAAdu\">Die Instandhaltung vieler Bestandsgeb\u00e4ude der Technischen Universit\u00e4t Berlin wurde laut Wissenschaftssenatorin Ina Czyborra vernachl\u00e4ssigt. In den vergangenen Jahren sei sehr viel neu gebaut worden, sagte die SPD-Politikerin im RBB-\u201eInforadio\u201c. \u201eAber der Bestand wurde etwas vernachl\u00e4ssigt, das kann man schon sagen.\u201c Im Laufe der Jahre seien eine ganze Reihe von M\u00e4ngeln aufgetreten.\u00a0<\/p>\n<p class=\"tspAAdt\">Das Hauptgeb\u00e4ude der Uni ist seit Samstag aus Sicherheitsgr\u00fcnden geschlossen und kann bis auf Weiteres nicht genutzt werden. Als Grund nannte die TU \u201ebauliche Auff\u00e4lligkeiten\u201c. Der Sanierungsstau an der TU bel\u00e4uft sich nach Angaben der Hochschule auf 2,4 Milliarden Euro.<\/p>\n<p> M\u00e4ngel betreffen den Brandschutz <\/p>\n<p class=\"tspAAdt\">Die Baum\u00e4ngel am Hauptgeb\u00e4ude waren bei einer Begehung durch Beh\u00f6rden und die Berliner Feuerwehr festgestellt worden. Die Aufsicht liege in der Verantwortung des Bezirks Charlottenburg-Wilmersdorf und des zust\u00e4ndigen Baustadtrats, sie selbst habe die Untersuchung nicht in die Wege geleitet, sagte Czyborra.\u00a0<\/p>\n<p class=\"tspAAdt\">\u201eDas ist deren Aufgabe, genau zu gucken. Es darf ja auch niemand zu Schaden kommen. Und da sind nun einige M\u00e4ngel so gravierend, dass sie gesagt haben, das Geb\u00e4ude muss geschlossen werden, weil es den Brandschutz betrifft.\u201c TU-Pr\u00e4sidentin Fatma Deniz hatte dem RBB gesagt, es gebe etwa nasse W\u00e4nde und Wassersch\u00e4den, die auch die Stromversorgung und den Brandschutz beeintr\u00e4chtigen k\u00f6nnten.<\/p>\n<p> Zeitpunkt der Wieder\u00f6ffnung noch unklar <\/p>\n<p class=\"tspAAdt\">Am Montagmorgen konnte Czyborra noch nicht sagen, wie lange das Geb\u00e4ude gesperrt bleibt. Sie sei im permanenten Kontakt mit der TU-Pr\u00e4sidentin. \u201eWir m\u00fcssen halt gucken, ob die M\u00e4ngel, die jetzt zur Schlie\u00dfung f\u00fchren, schnellstm\u00f6glich behoben werden k\u00f6nnen. Das war aber am Wochenende noch nicht ganz klar\u201c, so die Wissenschaftssenatorin.<\/p>\n<p class=\"tspAAdt\">Gro\u00dfe Sanierungen an den Hochschulen w\u00fcrden auch aus dem Haushalt des Landes finanziert. Die Haushaltssituation des Landes Berlin sei gerade sehr schwierig. Viele Ma\u00dfnahmen seien in letzter Zeit gestrichen worden. Das Hauptgeb\u00e4ude stand nach Angaben der Senatorin allerdings nie oben auf der Liste. Zus\u00e4tzlich bek\u00e4men die Hochschulen Geld f\u00fcr die Instandhaltung, so stehe es im Hochschulvertrag. \u201eDas ist nicht immer in den letzten Jahren so ausgegeben worden, wie es ausgegeben h\u00e4tte werden sollen, muss man auch sagen. Da ist viel Geld liegen geblieben.\u201c<\/p>\n<p class=\"tspAAdt\">\u00a9 dpa-infocom, dpa:260511-930-63304\/1<\/p>\n<p class=\"tspAAdt\">Das ist eine Nachricht direkt aus dem dpa-Newskanal.<\/p>\n","protected":false},"excerpt":{"rendered":"Die Instandhaltung vieler Bestandsgeb\u00e4ude der Technischen Universit\u00e4t Berlin wurde laut Wissenschaftssenatorin Ina Czyborra vernachl\u00e4ssigt. In den vergangenen Jahren&hellip;\n","protected":false},"author":2,"featured_media":1010239,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1825],"tags":[296,29,30],"class_list":{"0":"post-1010238","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-berlin","8":"tag-berlin","9":"tag-deutschland","10":"tag-germany"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116554507864244692","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1010238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=1010238"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/1010238\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/1010239"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=1010238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=1010238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=1010238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}